{"id":1011,"date":"2011-08-12T07:44:49","date_gmt":"2011-08-12T05:44:49","guid":{"rendered":"http:\/\/firmas.lasprovincias.es\/carlospajuelodearcos\/?p=1011"},"modified":"2011-08-12T07:44:49","modified_gmt":"2011-08-12T05:44:49","slug":"incentivos-por-multar-no-no-es-esono-es-eso","status":"publish","type":"post","link":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/2011\/08\/12\/incentivos-por-multar-no-no-es-esono-es-eso\/","title":{"rendered":"\u00bfIncentivos por multar? NO. No es eso,no es eso"},"content":{"rendered":"<p>l dilema es el que sigue: o multan a 35 conductores al mes o pueden sufrir un recorte de 220 euros en su sueldo. Los agentes del Subsector de Tr\u00e1fico de Valencia se enfrentan a diario con esta disyuntiva cuando se disponen a denunciar a un infractor.<\/p>\n<p>Cada d\u00eda nos lanzan una noticia que tiene acento econ\u00f3mico y esta que antecede me da pena. \u00bfNo ser\u00eda mejor incentivar por las ayudas que dan los de la Guardia Civil en general al respetable? Salir cada ma\u00f1ana mirando el n\u00famero 35 de m\u00ednima para evitar que te bajen el suledo es demasiado fuerte para ser cre\u00eddo.<\/p>\n<p>\u00bf\u00a0Pagar\u00edamos\u00a0a\u00a0m\u00e9dicos\u00a0en funci\u00f3n de un m\u00ednimo de extirpaci\u00f3n de apendicitis y si no peligra el salario? \u00bfY los periodistas\u00a0deber\u00edamos\u00a0estar\u00a0obligados a\u00a0conseguir 35 noticias deslumbrantes cada d\u00eda para mejorar la tirada?. !Bah!. Es indignante. !Que arreglen los WC de los\u00a0cuarteles, que dignifiquen las viviendas!<\/p>\n<p>En ocasiones dilapidar fondos de una parte y de otra apretar por abajo como soluci\u00f3n . La conocida Ley del Embudo. Da asco. Buenos d\u00edas y eso que estamos en Agosto o mejor porque estamos en Agosto.Qu\u00e9 hagan un informe semanal-refrito de los ya hechos- en TV como nos colocan ahora al final de cada telediario. Bon jour.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>l dilema es el que sigue: o multan a 35 conductores al mes o pueden sufrir un recorte de 220 euros en su sueldo. Los agentes del Subsector de Tr\u00e1fico de Valencia se enfrentan a diario con esta disyuntiva cuando se disponen a denunciar a un infractor. Cada d\u00eda nos lanzan una noticia que tiene [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-1011","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts\/1011","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/comments?post=1011"}],"version-history":[{"count":0,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts\/1011\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/media?parent=1011"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/categories?post=1011"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/tags?post=1011"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}