{"id":1023,"date":"2011-08-18T10:03:42","date_gmt":"2011-08-18T08:03:42","guid":{"rendered":"http:\/\/firmas.lasprovincias.es\/carlospajuelodearcos\/?p=1023"},"modified":"2011-08-18T10:03:42","modified_gmt":"2011-08-18T08:03:42","slug":"excomulgar","status":"publish","type":"post","link":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/2011\/08\/18\/excomulgar\/","title":{"rendered":"\u00bfExcomulgar?"},"content":{"rendered":"<p>\ufeffViene a ser esto de excolmulgar y luego perdonar, a aquellas abortistas que se han salto el divino mandato de no atentar contra la vida, un viaje de ida y vuelta. La vuelta al seno de la recepci\u00f3n de los sacramentos que puede hacer posible el ordinario del lugar sea Obispo o Cardenal, una posibilidad contemplada por el C\u00f3digo Can\u00f3nico.<\/p>\n<p>Supongo que es la\u00a0visita\u00a0del Papa lo que ha permitido desarrollar la piedad del cardenal. Ser\u00eda como cuando el emperador cumple a\u00f1os o el Rey decreta ua amnist\u00eda.<\/p>\n<p>Volver al seno de la Iglesia, dejar de estar excluido de la recepci\u00f3n o administraci\u00f3n de sacramentos incluido la confesi\u00f3n debe ser muy bueno para el excomulgado y una medalla para el que perdona. \u00bfSe hace con espiritu verdadero o omo demostraci\u00f3n de poder?. Yo excomulgo, yo perdono.<\/p>\n<p>Siempre perdonar. \u00bfPorqu\u00e9 hablar siempre de un Dios vengativo? Hablen de perdonar.\u00a0H\u00e1ganos\u00a0una prima de riesgo para\u00a0nuestros\u00a0posibles pecados.Buenos d\u00edas<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\ufeffViene a ser esto de excolmulgar y luego perdonar, a aquellas abortistas que se han salto el divino mandato de no atentar contra la vida, un viaje de ida y vuelta. La vuelta al seno de la recepci\u00f3n de los sacramentos que puede hacer posible el ordinario del lugar sea Obispo o Cardenal, una posibilidad [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-1023","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts\/1023","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/comments?post=1023"}],"version-history":[{"count":0,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts\/1023\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/media?parent=1023"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/categories?post=1023"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/tags?post=1023"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}