{"id":1031,"date":"2011-08-23T05:42:50","date_gmt":"2011-08-23T03:42:50","guid":{"rendered":"http:\/\/firmas.lasprovincias.es\/carlospajuelodearcos\/%c2%bfsomos-o-no-aconfesionales"},"modified":"2011-08-23T05:42:50","modified_gmt":"2011-08-23T03:42:50","slug":"somos-o-no-aconfesionales","status":"publish","type":"post","link":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/2011\/08\/23\/somos-o-no-aconfesionales\/","title":{"rendered":"\u00bfSomos o no aconfesionales?"},"content":{"rendered":"<p><strong>LA CHISPA CARLOSPAJUELODEARCOS. LASPROVINCIAS.ES<\/strong><\/p>\n<p><strong><a href=\"http:\/\/www.lasprovincias.es\/v\/20110823\/valencia\/tierra-media-20110823.html\" target=\"_self\" rel=\"external nofollow\">TIERRA MEDIA<\/a><\/strong><\/p>\n<p><strong>23.08.11 &#8211;<\/strong><strong> 00:12\u00a0&#8211; <\/strong><\/p>\n<p><strong>CARLOS PAJUELO |<\/strong><\/p>\n<p><strong>N o soy un hobbit pero a veces creo que estoy viviendo en una tierra media. Medio pagana, medio creyente y a todos al mismo tiempo los oigo decir \u00abes m\u00edo, es m\u00edo\u00bb y se refieren al anillo maldito que persiguen en pos del poder y la verdad. M\u00e1s del poder, creo yo.<\/strong><\/p>\n<p><strong>De repente estos d\u00edas pasados desde La Legi\u00f3n hasta el alcalde Gallard\u00f3n cierran filas y carreteras para esperar al enviado y hace cuatro d\u00edas nos meabamos en la cabeza de los curas.<\/strong><\/p>\n<p><strong>Nosotros somos el exceso en forma de p\u00e9ndulo y los da\u00f1os colaterales los sufrimos los habitantes de la tierra media d\u00f3nde habita la raz\u00f3n, d\u00f3nde surge el debate sereno de si o no.<\/strong><\/p>\n<p><strong>Nos estr\u00fajanos el consenso de una Constituci\u00f3n pactada d\u00f3nde mojan todos; los unos y los otros y llegan a la conclusi\u00f3n- a mi no me preguntaron- que somos un estado aconfesional y luego, un poco m\u00e1s tarde va el Presidente del Parlamento y le besa la mano al Papa que es como poner la Constituci\u00f3n al Sol de la incertidumbre y del prisma del debate.<\/strong><\/p>\n<p><strong>\u00bfSomos o no somos? Quiz\u00e1s ahora convenga que nos sangre el coraz\u00f3n con este asunto multitudinario y as\u00ed bajar la prima de riesgo celestial. \u00bfA qui\u00e9n creer? \u00bfToda la jerarqu\u00eda y quienes est\u00e1n por debajo en la llamada Iglesia de base comparte este espect\u00e1culo?<\/strong><\/p>\n<p><strong>Tambi\u00e9n puede ocurrir que aquellos que se han genuflexado crean que con este acto se han ganado una indulgencia casi plenaria en el reto final y habr\u00e1 quienes en el otro extremo del p\u00e9ndulo, es decir cuando toque ser m\u00e1s rojos que azules, si llega de nuevo el caso, encuentren excusas argumentales para defenderse de la acusaci\u00f3n de meapilas.<\/strong><\/p>\n<p><strong>Es la habilidad del pol\u00edtico que cual Jano tiene dos caras; es importante que tu mano derecha no sepa lo que hace la izquierda, lo que me preocupa, quir\u00fargicamente. Siempre nos quedar\u00e1 Cavadas.<\/strong><\/p>\n<p><strong>\u00bfY ma\u00f1ana? \u00bfQuedar\u00e1 tierra media d\u00f3nde habitar? Suarez quiso reencontrar el centro democr\u00e1tico y al final como dir\u00eda el castizo \u00abmenuda leche se peg\u00f3\u00bb. A lo mejor es que el centro, ni la tierra media existen. Son una entelequia para idiotas como yo. Buenos d\u00edas.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>LA CHISPA CARLOSPAJUELODEARCOS. LASPROVINCIAS.ES TIERRA MEDIA 23.08.11 &#8211; 00:12\u00a0&#8211; CARLOS PAJUELO | N o soy un hobbit pero a veces creo que estoy viviendo en una tierra media. Medio pagana, medio creyente y a todos al mismo tiempo los oigo decir \u00abes m\u00edo, es m\u00edo\u00bb y se refieren al anillo maldito que persiguen en pos [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-1031","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts\/1031","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/comments?post=1031"}],"version-history":[{"count":0,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts\/1031\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/media?parent=1031"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/categories?post=1031"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/tags?post=1031"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}