{"id":1087,"date":"2011-09-09T08:55:55","date_gmt":"2011-09-09T06:55:55","guid":{"rendered":"http:\/\/firmas.lasprovincias.es\/carlospajuelodearcos\/?p=1087"},"modified":"2011-09-09T08:55:55","modified_gmt":"2011-09-09T06:55:55","slug":"usted-se-nota-ninguneado-por-cospedal","status":"publish","type":"post","link":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/2011\/09\/09\/usted-se-nota-ninguneado-por-cospedal\/","title":{"rendered":"\u00bfUsted se nota ninguneado por Cospedal?"},"content":{"rendered":"<p>El PP valenciano viene percibiendo durante las \u00faltimas fechas cierta p\u00e9rdida de influencia en la calle G\u00e9nova. Al margen del papel de Esteban Gonz\u00e1lez Pons como vicesecretario nacional, que no se pone en cuesti\u00f3n, los populares de la Comunitat, y en especial la propia alcaldesa de Valencia, consideran que la direcci\u00f3n nacional de los populares ha dejado de mostrar la complicidad que en otros tiempos nadie pon\u00eda en cuesti\u00f3n.<\/p>\n<p>El amor es un\u00a0vaiv\u00e9n\u00a0y si es en pol\u00edtica el vaiv\u00e9n se transforma en\u00a0hurac\u00e1n\u00a0arrasador. Los celos por la\u00a0distribuci\u00f3n\u00a0del amor\u00a0se multiplican por cien cuando el\u00a0l\u00edder\u00a0se aproxima \u00a0a la cima.Se chupa\u00a0m\u00e1s\u00a0rueda de todo ese proceso y en el\u00a0camino\u00a0se va quedando el equipaje de la historia.<\/p>\n<p>En el caso del amor Camps-Rajoy\u00a0este\u00a0sufre un\u00a0bache\u00a0normal. Te lo dije, pensar\u00e1, no te\u00a0al\u00edes\u00a0con esos de Valencia y piensa en los tuyos<\/p>\n<p>. Nada es seguro en los lances amorosos. No me ha besado, no me ha dado un golpecito en la espalda al pasar, no me ha gui\u00f1ado el ojo. Aqu\u00ed pasa algo y luego me devuelven a Esteban- que yo ya\u00a0hab\u00eda\u00a0mandado all\u00ed y lo refuerzan con Trillo. \u00bfWhere is Cospe? \u00bfQuo vadis Mariano? \u00bfPor que te vas, por que me dejas? Yo sin ti&#8230; Total que hago un amago y me presento. Os vais a enterar. Mucho gustaros la paella y cuando se habla de\u00a0corredor\u00a0amagais. Castilla olvidadizos. Nos teneis envidia\u00a0por\u00a0el mar,seguro.Lo estoy viendo<\/p>\n<p>Somos muelles al decir del de Olivares,\u00a0pero\u00a0no tontos. !Ojo al dato!. Rita machaca. Cospe tiembla. Toma chocolate y paga lo que debes. Mi amiga la farma de Cuenca no puede m\u00e1s . Al \u00a0ERE le digo yo.Vete al ERE. Buenos d\u00edas<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El PP valenciano viene percibiendo durante las \u00faltimas fechas cierta p\u00e9rdida de influencia en la calle G\u00e9nova. Al margen del papel de Esteban Gonz\u00e1lez Pons como vicesecretario nacional, que no se pone en cuesti\u00f3n, los populares de la Comunitat, y en especial la propia alcaldesa de Valencia, consideran que la direcci\u00f3n nacional de los populares [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-1087","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts\/1087","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/comments?post=1087"}],"version-history":[{"count":0,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts\/1087\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/media?parent=1087"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/categories?post=1087"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/tags?post=1087"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}