{"id":1100,"date":"2011-09-14T10:34:22","date_gmt":"2011-09-14T08:34:22","guid":{"rendered":"http:\/\/firmas.lasprovincias.es\/carlospajuelodearcos\/?p=1100"},"modified":"2011-09-14T10:34:22","modified_gmt":"2011-09-14T08:34:22","slug":"da-usted-recibos-cuando-compra-en-nombre-de-otro-hay-que-hacerlo","status":"publish","type":"post","link":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/2011\/09\/14\/da-usted-recibos-cuando-compra-en-nombre-de-otro-hay-que-hacerlo\/","title":{"rendered":"\u00bfDa usted recibos cuando compra en nombre de otro? Hay que hacerlo"},"content":{"rendered":"<p>Un miembro de una asociaci\u00f3n festera de Banyeres de Mariola reclama al encargado de comprar loter\u00edas de la comparsa, que adem\u00e1s es un pariente lejano, m\u00e1s de 720.000 euros al creer que se apropi\u00f3 de 29 d\u00e9cimos de loter\u00eda que ten\u00eda apalabrados.<\/p>\n<p>El caso es interesante.No es el \u00fanico que leo sobre el particular. Nunca pasa nada hasta que pasa. En este caso &#8220;El Paella,&#8221; alias del acusado, dice que no canje\u00f3, que se le olvid\u00f3. Resulta sospechoso y por eso el fiscal,de momento, le pide 3 a\u00f1itos de c\u00e1rcel. Este parece que se ha comido el arroz completo y el pollo. Son parientes lejanos acusador y acusado, adem\u00e1s de amigos. Mal asunto.<\/p>\n<p>Con los dineros no se juega. La loter\u00eda, los juegos de azar y yo dir\u00eda que los encargos con el &#8220;parn\u00e9&#8221; por delante . Buenos d\u00edas<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un miembro de una asociaci\u00f3n festera de Banyeres de Mariola reclama al encargado de comprar loter\u00edas de la comparsa, que adem\u00e1s es un pariente lejano, m\u00e1s de 720.000 euros al creer que se apropi\u00f3 de 29 d\u00e9cimos de loter\u00eda que ten\u00eda apalabrados. El caso es interesante.No es el \u00fanico que leo sobre el particular. Nunca [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-1100","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts\/1100","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/comments?post=1100"}],"version-history":[{"count":0,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts\/1100\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/media?parent=1100"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/categories?post=1100"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/tags?post=1100"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}