{"id":1107,"date":"2011-09-17T07:34:05","date_gmt":"2011-09-17T05:34:05","guid":{"rendered":"http:\/\/firmas.lasprovincias.es\/carlospajuelodearcos\/?p=1107"},"modified":"2011-09-17T07:34:05","modified_gmt":"2011-09-17T05:34:05","slug":"soporta-usted-los-chantajes-emocionales-o-de-los-otros","status":"publish","type":"post","link":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/2011\/09\/17\/soporta-usted-los-chantajes-emocionales-o-de-los-otros\/","title":{"rendered":"\u00bfSoporta usted los chantajes emocionales o de los otros?"},"content":{"rendered":"<p>Un plazo de tres meses. Es el tiempo que ha otorgado la asociaci\u00f3n de vecinos de C\u00e1novas al Ayuntamiento para que resuelva su petici\u00f3n de que esta parte del Ensanche sea declarada Zona Ac\u00fasticamente Saturada (ZAS), lo que implicar\u00eda en caso afirmativo una reducci\u00f3n del horario de los bares y discotecas.<\/p>\n<p>A este\u00a0ultim\u00e1tum\u00a0a\u00f1ado el de Sinde que , m\u00e1s o\u00a0menos, niega la continuidad de las obras del Museo San\u00a0P\u00edo\u00a0V sino se le da licencia. Esta bien eso del chantaje emocional.A mi me pasa lo contrario cuando alguien me intenta someter a chantaje noto una ola de indignaci\u00f3n que me sube desde las\u00a0entra\u00f1as. Cuando ocurre eso es cuando creo en aquello de que las\u00a0emociones\u00a0te cambian la tensi\u00f3n y el cuerpo f\u00edsico es &#8220;victima&#8221; del cuerpo\u00a0an\u00edmico.<\/p>\n<p>\u00bfTendr\u00e1n raz\u00f3n los que\u00a0amenazan? \u00bfEs un sistema que hace movilizar conciencias? \u00bfEl miedo a lo que hagan, a lo que dir\u00e1n es paralizante? \u00bfPor qu\u00e9 se pasan el d\u00eda\u00a0amenaz\u00e1ndonos? Me voy a reflexionar y ya les contar\u00e9. Buenos d\u00edas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un plazo de tres meses. Es el tiempo que ha otorgado la asociaci\u00f3n de vecinos de C\u00e1novas al Ayuntamiento para que resuelva su petici\u00f3n de que esta parte del Ensanche sea declarada Zona Ac\u00fasticamente Saturada (ZAS), lo que implicar\u00eda en caso afirmativo una reducci\u00f3n del horario de los bares y discotecas. A este\u00a0ultim\u00e1tum\u00a0a\u00f1ado el de [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-1107","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts\/1107","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/comments?post=1107"}],"version-history":[{"count":0,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts\/1107\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/media?parent=1107"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/categories?post=1107"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/tags?post=1107"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}