{"id":1132,"date":"2011-10-03T08:26:20","date_gmt":"2011-10-03T06:26:20","guid":{"rendered":"http:\/\/firmas.lasprovincias.es\/carlospajuelodearcos\/?p=1132"},"modified":"2011-10-03T08:26:20","modified_gmt":"2011-10-03T06:26:20","slug":"donde-esta-el-dinero","status":"publish","type":"post","link":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/2011\/10\/03\/donde-esta-el-dinero\/","title":{"rendered":"\u00bfD\u00f3nde est\u00e1 el dinero?"},"content":{"rendered":"<p>Cada d\u00eda que pasa los diputados valencianos tienen un motivo m\u00e1s para preocuparse. No por el resto de los ciudadanos sino por lo suyo. Y hoy en d\u00eda, con la que est\u00e1 cayendo, lo \u00fanico que interesa es ingresar la n\u00f3mina al final de mes. Ni sus se\u00f1or\u00edas tienen ya seguro cobrar el sueldo. Hoy, lunes 3 de octubre, la Generalitat tampoco han ingresado la aportaci\u00f3n trimestral que Les Corts tienen que percibir para cubrir el presupuesto de la instituci\u00f3n.<\/p>\n<p>A la vista del anuncio generalizado de los\u00a0retrasos\u00a0e incluso de la posibilidad de que muchos funcionarios de toda clase y condici\u00f3n-incluidos asesores que no siendo funcionarios pudieran parecerlo- no\u00a0cobren- ver la noticia de arriba &#8211; me pregunto : \u00bfd\u00f3nde\u00a0est\u00e1\u00a0el dinero?. Me refiero al dinero que se supone que debe\u00a0tener\u00a0la Generalitat y que procede de una\u00a0combinaci\u00f3n\u00a0estatociudadana o sea de los impuestos directos,semidirectos,indirectos,\u00a0circunflejos\u00a0, agudos y cr\u00f3nicos.<\/p>\n<p>Coge el dinero y corre debe ser la\u00a0m\u00e1xima\u00a0empleada estos a\u00f1os anteriores de fiesta y bullicio eventosos. All\u00ed era la fiesta , el boato y los trajes armaniosos y el pobre engrosando la cola del paro mientras ,al\u00a0parecer, los eventos iban dejando\u00a0regueros\u00a0de millones de impacto cuya medida deber\u00eda hacerse con la vara funcionarial a dedo de : &#8220;t\u00fa pon lo que yo te diga, que la gente no lee&#8221;.<\/p>\n<p>Yo estoy contento,debo decir, porque\u00a0estamos\u00a0en el mapa. Ya. Tambi\u00e9n est\u00e1n Nigeria y Bombay. \u00bfQuiere usted estar en el mapa a costa de todo?<\/p>\n<p>Me sigo preguntando. Parece que no pagan a nadie,\u00a0entonces\u00a0\u00bfD\u00f3nde est\u00e1 el dinero?. Yo no lo tengo. \u00bf\u00a0Lo\u00a0tiene usted?. Buenos d\u00edas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cada d\u00eda que pasa los diputados valencianos tienen un motivo m\u00e1s para preocuparse. No por el resto de los ciudadanos sino por lo suyo. Y hoy en d\u00eda, con la que est\u00e1 cayendo, lo \u00fanico que interesa es ingresar la n\u00f3mina al final de mes. Ni sus se\u00f1or\u00edas tienen ya seguro cobrar el sueldo. Hoy, [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-1132","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts\/1132","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/comments?post=1132"}],"version-history":[{"count":0,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts\/1132\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/media?parent=1132"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/categories?post=1132"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/tags?post=1132"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}