{"id":1151,"date":"2011-10-15T09:56:33","date_gmt":"2011-10-15T07:56:33","guid":{"rendered":"http:\/\/firmas.lasprovincias.es\/carlospajuelodearcos\/?p=1151"},"modified":"2011-10-15T09:56:33","modified_gmt":"2011-10-15T07:56:33","slug":"se-lava-usted-bien-las-manos-yo-lo-procuro","status":"publish","type":"post","link":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/2011\/10\/15\/se-lava-usted-bien-las-manos-yo-lo-procuro\/","title":{"rendered":"\u00bfSe lava usted bien las manos? Yo lo procuro"},"content":{"rendered":"<p>Uno de cada seis dispositivos m\u00f3viles de Reino Unido est\u00e1 contaminado con E.Coli debido a la mala higiene personal de las manos de los brit\u00e1nicos despu\u00e9s de ir al ba\u00f1o. Seg\u00fan investigadores de la Escuela de Higiene y Medicina Tropical y de la Universidad Queen Mary de Londres, un 16% de estos aparatos est\u00e1n contaminados y pueden provocar una intoxicaci\u00f3n alimentaria como ocurri\u00f3 este pasado junio en Alemania con una cepa virulenta de dicha bacteria.(fuente: diario levante)<\/p>\n<p>Luego vienen lo alemanes y culpan al pepino espa\u00f1ol de ser portador de mil y una no \u00a0s\u00e9 que \u00a0cosas. Seamos justos con el pepino y demos al pepino lo que es del pepino; lo que hay que hacer, nenes y nenas o nenas y nenes, tanto monta a estos efectos, es \u00a0lavarse las manos tras miccionar o excretar ( que no quiero ser yo vulgar en las expresiones cotidianas).<\/p>\n<p>Yo no estoy en contra del\u00a0entretenimiento\u00a0posible, personalizado, de cada uno con sus partes, lo que yo digo y por fin se me ha hecho justicia( lo digo porque siempre he defendido lo de lavarse las manos en un sentido estricto de agua y jab\u00f3n) es que el guarro tiene poco recorrido y se empieza por no lavarse las manos y se acaba acaparando\u00a0\u00e1reas\u00a0del metro o del bus por expansi\u00f3n del mal olor. El mal olor deviene en vac\u00edo social.<\/p>\n<p>\u00bfHac\u00eda falta que investigar\u00e1n este asunto? \u00bfNo estaba claro? \u00bfNo nos lo dec\u00edan nuestros padres? \u00bfCarlitos te has lavado las manos? Adem\u00e1s de las manos estaban los dientes etc. En definitiva hay que reeducar al respetable. Ahora cuando me cedan un m\u00f3vil, por mucho que lo haya dise\u00f1ado el gur\u00fa de turno, preguntar\u00e9: &#8220;\u00bfUsted se ha lavado bien las manos?&#8221;. Me mirar\u00e1n con cara de pocos amigos y terminar\u00e1n pensando que\u00a0estoy\u00a0loco por preguntar esas cosas. Lo que ustedes digan, pero yo no me juego la cosa salutifera por un E.Coli manutransportado. Manos limpias herman@s en todo, que luego te vienen de una Univweridad extranjera y te sacan los colores.<\/p>\n<p>Los titulares de hoy est\u00e1n\u00a0llenos\u00a0de posibilidades, pero no quiero\u00a0mezclar\u00a0asuntos ,\u00a0aunque\u00a0el ser humano es un puzzle de entradas y salidas de informaci\u00f3n al mismo tiempo, porque\u00a0para\u00a0eso el cerebro es pl\u00e1stico, quiero decir que tiene algo que se llama plasticidad al decir de\u00a0los\u00a0neur\u00f3logos. Perdonen que me levante pero me voy a lavar las manos. Buenos d\u00edas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Uno de cada seis dispositivos m\u00f3viles de Reino Unido est\u00e1 contaminado con E.Coli debido a la mala higiene personal de las manos de los brit\u00e1nicos despu\u00e9s de ir al ba\u00f1o. Seg\u00fan investigadores de la Escuela de Higiene y Medicina Tropical y de la Universidad Queen Mary de Londres, un 16% de estos aparatos est\u00e1n contaminados [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-1151","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts\/1151","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/comments?post=1151"}],"version-history":[{"count":0,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts\/1151\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/media?parent=1151"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/categories?post=1151"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/tags?post=1151"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}