{"id":1175,"date":"2011-10-25T08:04:43","date_gmt":"2011-10-25T06:04:43","guid":{"rendered":"http:\/\/firmas.lasprovincias.es\/carlospajuelodearcos\/?p=1175"},"modified":"2011-10-25T08:04:43","modified_gmt":"2011-10-25T06:04:43","slug":"niega-usted-lo-evidente-yo-no","status":"publish","type":"post","link":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/2011\/10\/25\/niega-usted-lo-evidente-yo-no\/","title":{"rendered":"\u00bfNiega usted lo evidente? Yo no"},"content":{"rendered":"<div>\n<p>LA CHISPA<\/p>\n<p>La boina<\/p>\n<p>Carlos Pajuelo de Arcos<\/p>\n<p>Es el caso que se me han cruzado los cables con dos noticias y no me extra\u00f1a que alg\u00fan lect@r me haga llegar un \u201crecado\u201d dici\u00e9ndome: \u201cque, a veces, no se le entiende a usted\u201d y es que mezclo; lo hago sin el menor escr\u00fapulo; debe ser que como tengo poco espacio lo quiero aprovechar tanto que llego a la entrop\u00eda y a un cierto caos. V\u00e9ase.<\/p>\n<p>Observo una foto de la candidatura del PP en una terraza madrile\u00f1a y un pie de foto que hace alusi\u00f3n a la contaminaci\u00f3n que ese d\u00eda ahoga al respetable en la ciudad y para ello hace alusi\u00f3n al t\u00e9rmino boina marr\u00f3n. \u00bfEl asesor de comunicaci\u00f3n del PP- \u201ccamisa blanca G.Pons\u201d- estaba en el ajo? \u00bfQuer\u00eda liquidar por ahogo a los candidatos?\u00a0 \u00bfPor qu\u00e9 se emplea el concepto de boina en estos asuntos? \u00bfResulta pijo decir capa o nube? Todo muy sospechoso.<\/p>\n<p>Se sigue en otros diarios la noticia de la elevaci\u00f3n a los altares municipales de la Sra. Botella, concejala de medio ambiente hoy y futurible alcaldesa en el caso de que Gallard\u00f3n, el del mayordomo personal a cuenta del bolsillo de todos, sea aupado a ministro con cartera\u2026y\u00a0 mayordomo, supongo.<\/p>\n<p>La esposa de Aznar y concejala dixit: \u201cEl medio ambiente ha mejorado mucho \u201c y lo dice bajo la boina (con perd\u00f3n). Un fen\u00f3meno de veracidad atmosf\u00e9rica. As\u00ed van las cosas. \u00bfD\u00f3nde est\u00e1 el dinero, por ejemplo? \u00bfQu\u00e9 dinero me preguntar\u00e1n ustedes? Todo. \u00bfCu\u00e1l va a ser?<\/p>\n<p>Nos dicen que vamos mal, que no hay dinero y yo que a\u00fan no llevo la boina puesta- sin menoscabo de la prenda y sus usuarios- me llevo las manos a la cabeza( por eso se que no llevo boina) cuando leo esta subvenci\u00f3n.<\/p>\n<p><strong>Alianza de Civilizaciones Subvenci\u00f3n para analizar las causas de las divisiones que ponen en peligro la paz y propone una serie de medidas concretas de car\u00e1cter pol\u00edtico. Sin determinar \u00a0650.000,00 y hay m\u00e1s, muchas m\u00e1s.<\/strong><\/p>\n<p><strong>La paz se pone en peligro cuando se niega lo evidente (caso Botella y le clima) y el dinero va a chorradas y el Centro de Investigaci\u00f3n Pr\u00edncipe Felipe pone en marcha un ERE del cop\u00f3n. Buenos d\u00edas.<\/strong><\/p>\n<div><\/div>\n<\/div>\n<div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>LA CHISPA La boina Carlos Pajuelo de Arcos Es el caso que se me han cruzado los cables con dos noticias y no me extra\u00f1a que alg\u00fan lect@r me haga llegar un \u201crecado\u201d dici\u00e9ndome: \u201cque, a veces, no se le entiende a usted\u201d y es que mezclo; lo hago sin el menor escr\u00fapulo; debe ser [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-1175","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts\/1175","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/comments?post=1175"}],"version-history":[{"count":0,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts\/1175\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/media?parent=1175"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/categories?post=1175"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/tags?post=1175"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}