{"id":1179,"date":"2011-10-27T08:50:35","date_gmt":"2011-10-27T06:50:35","guid":{"rendered":"http:\/\/firmas.lasprovincias.es\/carlospajuelodearcos\/?p=1179"},"modified":"2011-10-27T08:50:35","modified_gmt":"2011-10-27T06:50:35","slug":"han-reducido-los-grupos-de-les-corts-su-presupuesto-ay-no","status":"publish","type":"post","link":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/2011\/10\/27\/han-reducido-los-grupos-de-les-corts-su-presupuesto-ay-no\/","title":{"rendered":"\u00bfHan reducido los grupos de Les Corts su presupuesto? !Ay, no!."},"content":{"rendered":"<p>El dinero que reciben los grupos se destina desde a pagar el sueldo de distintos asesores hasta comprar material de oficina. Tambi\u00e9n se ha dedicado para comprar regalos navide\u00f1os (para la prensa tambi\u00e9n) e incluso hay grupos que lo utilizan para completar el sueldo de sus se\u00f1or\u00edas seg\u00fan el cargo que ostentan. Pero la realidad es que existe mucho oscurantismo sobre los movimientos de un dinero del que no se hace p\u00fablica su utilizaci\u00f3n ni hay excesiva transparencia.(fuente: las provincias)<\/p>\n<p>No tiene soluci\u00f3n. Si a la austeridad pero no con mi dinero&#8230;parecen decir las personas de\u00a0los\u00a0grupos parlamentarios en Les Corts. Un milagro en el que todos se ponen de acuerdo y prietas las filas, como un solo hombre y en paridad,dicen que si a la\u00a0austeridad\u00a0pero no a la\u00a0suya. Bueno.Se ve\u00eda venir.<\/p>\n<p>Yo prefiero la noticia del director musical \u00a0valenciano Garc\u00e9s que, con su\u00a0doble\u00a0record Guinnes , a sus hoy 97 a\u00f1os sigue dirigiendo obras que llenan los o\u00eddos de\u00a0musicalidad\u00a0y buenos\u00a0consejos\u00a0como los de\u00a0recomendar\u00a0 mayor\u00a0formaci\u00f3n\u00a0y esfuerzo para salir de una crisis que copa los noticieros,los titulares.Todo es\u00a0crisis. Este director de orquesta me abre las ganas de ver m\u00e1s all\u00e1 y me\u00a0alegro\u00a0no solo por \u00e9l,claro, sino por todos los que tenemos la oportunidad de\u00a0o\u00edrle.<\/p>\n<p>Luego est\u00e1 el\u00a0v\u00eddeo\u00a0que muestra el como Berlusconi le mira el culo a la primera ministra danesa y entonces todo el mundo habla de\u00a0indiscreci\u00f3n. !Qu\u00e9 quiere usted! Los primeros ministros miran y las primeras ministras tambi\u00e9n.\u00a0Aqu\u00ed\u00a0mira todo el mundo que yo lo he visto.\u00a0Entre\u00a0quita griega,\u00a0recapitalizaci\u00f3n\u00a0bancaria, cortafuegos alem\u00e1n y otras &#8220;memeces&#8221;- dir\u00e1 el cavalliere- yo miro y eso no me lo quita nadie. \u00bfEs normal? Cada uno que se haga la pregunta. \u00bfA quien mira Rajoy o Z? A Urkullu. Prefiero a la primera ministra rubia del fr\u00edo Norte.<\/p>\n<p>Es tres en uno. Les Corts,el director musical Guinnes o Berlus. Esto da para mucho. Recomendaci\u00f3n antigota fr\u00eda y anticrisis. Cine, lectura, paseo bajo la lluvia,ver el mar ( la lluvia, el cielo y el mar son gratis) y un par de bocatas. Buenos d\u00edas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El dinero que reciben los grupos se destina desde a pagar el sueldo de distintos asesores hasta comprar material de oficina. Tambi\u00e9n se ha dedicado para comprar regalos navide\u00f1os (para la prensa tambi\u00e9n) e incluso hay grupos que lo utilizan para completar el sueldo de sus se\u00f1or\u00edas seg\u00fan el cargo que ostentan. Pero la realidad [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-1179","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts\/1179","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/comments?post=1179"}],"version-history":[{"count":0,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts\/1179\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/media?parent=1179"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/categories?post=1179"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/tags?post=1179"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}