{"id":1183,"date":"2011-10-29T05:42:44","date_gmt":"2011-10-29T03:42:44","guid":{"rendered":"http:\/\/firmas.lasprovincias.es\/carlospajuelodearcos\/%c2%bftienen-alma-los-animales-no-tengo-ni-idea"},"modified":"2011-10-29T05:42:44","modified_gmt":"2011-10-29T03:42:44","slug":"tienen-alma-los-animales-no-tengo-ni-idea","status":"publish","type":"post","link":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/2011\/10\/29\/tienen-alma-los-animales-no-tengo-ni-idea\/","title":{"rendered":"\u00bfTienen alma los animales? No tengo ni idea"},"content":{"rendered":"<p><strong>FLASH<\/strong><\/p>\n<p><strong><a href=\"http:\/\/www.lasprovincias.es\/v\/20111029\/salud\/animales-mios-20111029.html\" target=\"_BLANK\" rel=\"external nofollow\">\u00a1Animales m\u00edos!<\/a><\/strong><\/p>\n<p><strong>29.10.11 &#8211;<\/strong><strong> 00:19\u00a0&#8211; <\/strong><\/p>\n<p><strong>CARLOS PAJUELO DE ARCOS PERIODISTA |<\/strong><\/p>\n<p><strong>No escribas eso, me dicen. \u00bfPor qu\u00e9? Es una repetici\u00f3n de otro ya escrito. S\u00ed.<\/strong><\/p>\n<p><strong>Algunas repeticiones conviene reeditarlas porque no han pasado de moda.<\/strong><\/p>\n<p><strong>Muchos creer\u00e1n que es un insulto el titular. No. No lo es, lo niego, aunque a veces, en mi interior m\u00e1s profundo creo que si, que hay alg\u00fan animal suelto.<\/strong><\/p>\n<p><strong>Animales humanos y de los otros, que ahora parece que empiezan a tener alma las bestias del campo.<\/strong><\/p>\n<p><strong>Nos comemos a esos animales con alma de segunda en plan carne, en plan pescado.<\/strong><\/p>\n<p><strong>\u00bfTienen m\u00e1s alma los toros, los bueyes, los cabritos, con perd\u00f3n, que los pollos o el salm\u00f3n? Ni idea.<\/strong><\/p>\n<p><strong>Se lo dejo a los te\u00f3logos y a los ecologistas y s\u00ed hacen falta m\u00e1s, siempre tenemos a mano a los fil\u00f3sofos, mientras descansan de interpretar, en ingl\u00e9s, para la cosa misma de la Ciudadan\u00eda.<\/strong><\/p>\n<p><strong>Yo creo que cada d\u00eda hace m\u00e1s falta esa u otra asignatura parecida. M\u00e1s urbanidad, democracia, sostenibilidad, igualdad y todas &#8216;las dad&#8217; que los lectores quieran, porque hay mucho animal suelto.<\/strong><\/p>\n<p><strong>El otro d\u00eda vi a uno.<\/strong><\/p>\n<p><strong>Pasaba el sem\u00e1foro en rojo y casi atropella a una mam\u00e1 con su carrito y pens\u00e1ndolo m\u00e1s detenidamente, tambi\u00e9n vi a otro que hu\u00eda porque parece ser, seg\u00fan gritaba el ciego de la ONCE, que le hab\u00eda enga\u00f1ado con una falsa moneda y tambi\u00e9n otro que se quedaba con una parte sustanciosa del salario del miedo de un extranjero sin papeles.<\/strong><\/p>\n<p><strong>Pensar y observar estos acontecimientos puede ser \u00fatil para concienciarnos acerca de nuestra conducta.<\/strong><\/p>\n<p><strong>Buenos d\u00edas.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>FLASH \u00a1Animales m\u00edos! 29.10.11 &#8211; 00:19\u00a0&#8211; CARLOS PAJUELO DE ARCOS PERIODISTA | No escribas eso, me dicen. \u00bfPor qu\u00e9? Es una repetici\u00f3n de otro ya escrito. S\u00ed. Algunas repeticiones conviene reeditarlas porque no han pasado de moda. Muchos creer\u00e1n que es un insulto el titular. No. No lo es, lo niego, aunque a veces, en [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-1183","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts\/1183","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/comments?post=1183"}],"version-history":[{"count":0,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts\/1183\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/media?parent=1183"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/categories?post=1183"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/tags?post=1183"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}