{"id":1210,"date":"2011-11-14T09:26:57","date_gmt":"2011-11-14T07:26:57","guid":{"rendered":"http:\/\/firmas.lasprovincias.es\/carlospajuelodearcos\/%c2%bfusted-olvida-quien-no"},"modified":"2011-11-14T09:26:57","modified_gmt":"2011-11-14T07:26:57","slug":"usted-olvida-quien-no","status":"publish","type":"post","link":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/2011\/11\/14\/usted-olvida-quien-no\/","title":{"rendered":"\u00bfUsted olvida? Qui\u00e9n no"},"content":{"rendered":"<p><strong><br \/>\n<\/strong><\/p>\n<p><strong> El olvido es la tumba del conocimiento. Y si el olvido es m\u00e1ximo supongo que es el Alzheimer.<\/strong><\/p>\n<p><strong> Vengo yo a hablar de esto hoy despu\u00e9s del salto en la tribuna de oradores del candidato y al parecer presidente pr\u00f3ximo- hoy \u201cin pectore\u201d- el Sr. Rajoy.<\/strong><\/p>\n<p><strong> Dos a\u00f1os despu\u00e9s de decir: \u201ccontigo Paco siempre\u201d en plan contigo pan y cebolla del amante pobre, Paco no estaba entre la multitud, ni estaba entre los elegidos. \u00bfD\u00f3nde estaba?. Posiblemente jugando al tenis, al p\u00e1del o en su casa en oraci\u00f3n \u00edntima.<\/strong><\/p>\n<p><strong> El olvido es duro cuando es voluntario, supongo. No lo supongo, lo s\u00e9. \u00bfQui\u00e9n no ha sido olvidado una vez o siempre cuando parec\u00eda que el mundo estaba a los pies?<\/strong><\/p>\n<p><strong> Aquellos que te dec\u00edan que te quer\u00edan, los que te amaban hasta la muerte, han sido presa del humo variable de la ambici\u00f3n. Es el tango \u201cla ambici\u00f3n no descansa, pisito que puso Mable para acompa\u00f1ar el amor\u2026\u201d<\/strong><\/p>\n<p><strong> En el caso del pol\u00edtico, el olvido debe ser traum\u00e1tico, digo. Los psicotr\u00f3picos generados por el morbo del poder, el \u00e9xtasis de la multitud, el goce de la mano estrechada mil veces, los besos robados de ninfas y faunos adheridos a la falda del magister que imparte doctrina mediante el \u00f3bolo de la canonj\u00eda.<\/strong><\/p>\n<p><strong> Yo te perdono, yo te nombro, yo te saludo, yo te llamo\u2026el yo desaparecido en aras de un traje, o dos o vaya usted a saber; desaparecido inmerso en su lejan\u00eda de sonrisa estereotipada neg\u00e1ndose a recibir, dando su mano fr\u00eda a ser besada.<\/strong><\/p>\n<p><strong> Paco estar\u00e1 llamado a jugar grandes papeles en el futuro de la naci\u00f3n espa\u00f1ola, dixit el registrador.<\/strong><\/p>\n<p><strong> \u00bfQu\u00e9 pensar\u00e1 \u201cel olvidado\u201d? \u00bfTramar\u00e1 mil venganzas imposibles? Refugiado en la cosa consultiva debe, digo, estudiar. Buenos d\u00edas.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El olvido es la tumba del conocimiento. Y si el olvido es m\u00e1ximo supongo que es el Alzheimer. Vengo yo a hablar de esto hoy despu\u00e9s del salto en la tribuna de oradores del candidato y al parecer presidente pr\u00f3ximo- hoy \u201cin pectore\u201d- el Sr. Rajoy. Dos a\u00f1os despu\u00e9s de decir: \u201ccontigo Paco siempre\u201d en [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-1210","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts\/1210","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/comments?post=1210"}],"version-history":[{"count":0,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts\/1210\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/media?parent=1210"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/categories?post=1210"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/tags?post=1210"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}