{"id":1213,"date":"2011-11-16T08:27:46","date_gmt":"2011-11-16T06:27:46","guid":{"rendered":"http:\/\/firmas.lasprovincias.es\/carlospajuelodearcos\/?p=1213"},"modified":"2011-11-16T08:27:46","modified_gmt":"2011-11-16T06:27:46","slug":"tiene-usted-gallinas-cuidado-con-los-huevos","status":"publish","type":"post","link":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/2011\/11\/16\/tiene-usted-gallinas-cuidado-con-los-huevos\/","title":{"rendered":"\u00bfTiene usted gallinas? Cuidado con los huevos"},"content":{"rendered":"<p>El comisario de Salud y Protecci\u00f3n del Consumidor advierte que sancionar\u00e1 a Espa\u00f1a si en enero de 2012 no cumple las nuevas normas para adecuar las jaulas de las gallinas ponedoras a las exigencias europeas de bienestar animal.(fuente: nativel preciado-p\u00fablico)<\/p>\n<p>El asunto es un asunto claramente de huevos. Millones de gallinas viven su corta vida de ponedoras en\u00a0estrechos\u00a0cubiculos d\u00f3nde ponen sus huevos de manera ordenada. Se ve que no basta. No pasa nada con las personas. Este es un asunto de gallinas y su espacio vital.<\/p>\n<p>\u00bf Tengo algo contra Europa, as\u00ed en\u00a0general? No. Lo que a mi ocurre es que empiezo a estar hasta los\u00a0mismos\u00a0genitales de tanta\u00a0imposici\u00f3n\u00a0burocr\u00e1tica, de la\u00a0plutocracia que anida en los despachos de alguno cuya misi\u00f3n es mirar la paja en el ojo ajeno y no la viga en el propio. Veamos.<\/p>\n<p>Piense usted en los\u00a0desahucios,\u00a0piense\u00a0en usted en la banca que genera &#8220;bancos malos&#8221; d\u00f3nde\u00a0guardar\u00a0sus miserias, sus errores &#8230;con el\u00a0dinero\u00a0de otros y piense usted en las gentes que han ca\u00eddo bajo las\u00a0garras\u00a0de un capitalismo que tiene a socializar las p\u00e9rdidas y privatizar los beneficios.<\/p>\n<p>Eso es poner los huevos en condiciones peores que los de las gallinas. Ah\u00ed te quiero ver directiva europea. Deja a mis gallinas, por ejemplo, que quiere decir a mis\u00a0ganaderos\u00a0y de paso, ya que estamos, a mis\u00a0agricultores y pon tu ojo directivo en cuestiones m\u00e1s pr\u00f3ximas a la realidad econ\u00f3mica que nos aprieta.<\/p>\n<p>Cambiar las jaulas\u00a0requiere\u00a0una fuerte inversi\u00f3n de un sector\u00a0descapitalizado y es poner los huevos a un precio no competitivo.Seguro que\u00a0pronto\u00a0haremos tortillas con huevos de Marruecos o de China. Inventar\u00e1n algo para que lleguen bien a mi mesa y yo &#8220;tastando&#8221; la clara extranjera. Si defiendo mis huevos me llamar\u00e1n, seguro, xenofobo de los huevos. Usted mismo. Buenos d\u00edas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El comisario de Salud y Protecci\u00f3n del Consumidor advierte que sancionar\u00e1 a Espa\u00f1a si en enero de 2012 no cumple las nuevas normas para adecuar las jaulas de las gallinas ponedoras a las exigencias europeas de bienestar animal.(fuente: nativel preciado-p\u00fablico) El asunto es un asunto claramente de huevos. Millones de gallinas viven su corta vida [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-1213","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts\/1213","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/comments?post=1213"}],"version-history":[{"count":0,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts\/1213\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/media?parent=1213"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/categories?post=1213"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/tags?post=1213"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}