{"id":1226,"date":"2011-11-24T09:27:13","date_gmt":"2011-11-24T07:27:13","guid":{"rendered":"http:\/\/firmas.lasprovincias.es\/carlospajuelodearcos\/?p=1226"},"modified":"2011-11-24T09:27:13","modified_gmt":"2011-11-24T07:27:13","slug":"usted-perdonase-arrepiente-y-vuelve-a-la-carga-no-es-eso-no-es-eso","status":"publish","type":"post","link":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/2011\/11\/24\/usted-perdonase-arrepiente-y-vuelve-a-la-carga-no-es-eso-no-es-eso\/","title":{"rendered":"\u00bfUsted perdona,se arrepiente y vuelve a la carga? No es eso, no es eso"},"content":{"rendered":"<p><em><strong>La canciller alemana, Angela Merkel, ha afirmado \u00a0que los asesinatos de nueve trabajadores inmigrantes por parte de una c\u00e9lula neonazi amenazan con da\u00f1ar la imagen de Alemania en el mundo y que son un asalto contra los principios democr\u00e1ticos. En declaraciones ante el Parlamento, Merkel ha se\u00f1alado que la Polic\u00eda ha cometido muchos errores en su fracaso a la hora de detener, o incluso detectar, a la c\u00e9lula, que asesin\u00f3 a nueve trabajadores inmigrantes -ocho turcos y uno griego- y una agente de Polic\u00eda alemana entre 2000 y 2007.(fuente las\u00a0provincias)<\/strong><\/em><\/p>\n<p><strong>El caso es que ayer,por lo le\u00eddo,el Parlamento\u00a0alem\u00e1n\u00a0se puso de pie como homenaje a las\u00a0victimas\u00a0de los asesinos\u00a0neo nazis\u00a0que hab\u00edan campado por sus\u00a0respetos\u00a0antes las narices,al decir de\u00a0los\u00a0tabloides, de los servicio de seguridad germanos. Los parlamentarios se\u00a0sintieron\u00a0avergonzados y pidieron perd\u00f3n.<\/strong><\/p>\n<p><strong>A mi ese asunto del perd\u00f3n empieza mosquearme. Seg\u00fan algunos la mano de la misericordia es generosa y si uno hace una barbaridad,se\u00a0confiesa\u00a0o pide perd\u00f3n\u00a0p\u00fablicamente, est\u00e1 salvado y vuelve a empezar o no,seg\u00fan.<\/strong><\/p>\n<p><strong>Los que piden perd\u00f3n,en este caso que nos\u00a0ocupa, est\u00e1n vivos y se levantan bajo la\u00a0c\u00fapula\u00a0del poder parlamentario y los que ya no est\u00e1n por haber\u00a0sido\u00a0&#8220;liquidados&#8221;, esos\u00a0est\u00e1n muertos. !A buenas horas mangas verdes!.<\/strong><\/p>\n<p><strong>\u00bfNo ser\u00eda m\u00e1s adecuado,mejor para la sociedad, mejor para todos, que aquellos que destilan radicalismo y devienen en asesinos fueran confinados antes de realizar algo que suponga tener que pedir perd\u00f3n? Un poco larga la pregunta para una respuesta contundente en mi opini\u00f3n. SI. Ser\u00eda mejor.<\/strong><\/p>\n<p><strong>\u00bf\u00a0Queda\u00a0alg\u00fan\u00a0poso nazi en el comportamiento de\u00a0los\u00a0hijos y nietos de las camadas\u00a0hitlerianas? \u00bfLes\u00a0duele\u00a0ver turcos o chipriotas o\u00a0espa\u00f1oles\u00a0por sus calles, en sus trabajos? \u00bfY aqu\u00ed? \u00bfC\u00f3mo vamos aqu\u00ed con la cosa de la extranjer\u00eda?<\/strong><\/p>\n<p><strong>Como siempre leer m\u00e1s, estudiar , comprender otras culturas, aceptar e intentar que\u00a0los\u00a0otros respeten tus costumbres, se adapten a tu cultura, es un\u00a0esfuerzo\u00a0combimnado de comprensi\u00f3n y paciencia.<\/strong><\/p>\n<p><strong>La clave puede que est\u00e9 en el idioma. Rajoy aprende alem\u00e1n. Buenos d\u00edas.<\/strong><\/p>\n<p><strong><br \/>\n<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La canciller alemana, Angela Merkel, ha afirmado \u00a0que los asesinatos de nueve trabajadores inmigrantes por parte de una c\u00e9lula neonazi amenazan con da\u00f1ar la imagen de Alemania en el mundo y que son un asalto contra los principios democr\u00e1ticos. En declaraciones ante el Parlamento, Merkel ha se\u00f1alado que la Polic\u00eda ha cometido muchos errores en [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-1226","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts\/1226","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/comments?post=1226"}],"version-history":[{"count":0,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts\/1226\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/media?parent=1226"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/categories?post=1226"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/tags?post=1226"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}