{"id":1270,"date":"2011-12-21T09:49:09","date_gmt":"2011-12-21T07:49:09","guid":{"rendered":"http:\/\/firmas.lasprovincias.es\/carlospajuelodearcos\/?p=1270"},"modified":"2011-12-21T09:49:09","modified_gmt":"2011-12-21T07:49:09","slug":"que-esta-pasando-demasiadas-cosas-para-asumirlas","status":"publish","type":"post","link":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/2011\/12\/21\/que-esta-pasando-demasiadas-cosas-para-asumirlas\/","title":{"rendered":"\u00bfQu\u00e9 est\u00e1 pasando? Demasiadas cosas para asumirlas"},"content":{"rendered":"<p><em>Amigos para siempre<\/em>, como dice la canci\u00f3n de los Juegos Ol\u00edmpicos de Barcelona, as\u00ed parece que han quedado Cayetano Mart\u00ednez de Irujo, conde de Salvatierra, y los l\u00edderes del Sindicato Andaluz de Trabajadores (SAT) Diego Ca\u00f1amero y Juan Manuel S\u00e1nchez Gordillo.(fuentes\u00a0diversas escritas coincidentes)<\/p>\n<p>Mientras encuentro un\u00a0remedio\u00a0natural para combatir mi caspa,por ejemplo lo de jugo de manzana y me alegro porque este a\u00f1o se llevar\u00e1n las coletas, por fin,en el peinado, bajas, este \u00a0Cayetano, al decir de la prensa, se hace medio amigo de los lideres de la protesta en las puertas de su campo andaluz.<\/p>\n<p>Siempre me alegra esto y se nota, digo, que el caballista tiene una educaci\u00f3n al m\u00e1s alto nivel.\u00a0Primero\u00a0se declara antivagos y ahora comparte proyectos. Un dechado de diplomacia desde la grupa de su caballo. Veremos.<\/p>\n<p>Esta noticia no me desvela tanto como esta otra que anuncia para el 2013 una tormenta\u00a0del\u00a0cop\u00f3n\u00a0en el Sol y que nos \u00a0va a dejar sin luz,sin \u00a0telecomunicaciones \u00a0y nos va a\u00a0producir\u00a0de todo en materia de desastres. Ya nos est\u00e1n jodiendo la Navidad,los Reyes, las Fallas y lo que venga por delante. No descansan. \u00bfAlguien podr\u00eda darles fiesta a estos agoreros del mal?<\/p>\n<p>No descanso. Entre Rajoy que viene apretando m\u00e1s, Chac\u00f3n que\u00a0amenaza\u00a0con un nuevo partido renovado socialista y que pronto habr\u00e1\u00a0menos\u00a0jam\u00f3n ib\u00e9rico, porque las bellotas son\u00a0menos\u00a0en Extremadura, no pego ojo. Todo es demasiado.<\/p>\n<p>Se me\u00a0encoge\u00a0la entrepierna, me\u00a0duele\u00a0la cabeza y me mareo. Debo estar chocho porque no asimilo y todo me pasa por querer leerlo todo.<\/p>\n<p>Esta cultura de mosaico, este llenarse la cabeza de un salpimentado de noticias me preocupa. Debo\u00a0concentrarme\u00a0m\u00e1s. Despejar la duda acerca de si eso que dice el defensor\u00a0del\u00a0ya\u00a0famoso\u00a0Undargar\u00edn, que se\u00f1ala que est\u00e1 siendo objeto de un &#8220;linchamiento\u00a0moral&#8221;, es verdad. Vaya papel\u00f3n el de algunos defensores.<\/p>\n<p>Voy a seguir con lo de la caspa y yo voy a seguir escribiendo\u00a0aunque\u00a0Luc\u00eda Etchevarr\u00eda haya dicho que ella no.Un descanso,nena, viene bien, lo se&#8230;para todos. Buenos d\u00edas.<\/p>\n<p>Nota: Aprovecho para dar las gracias a quienes me reciben y me aguantan y\u00a0tambi\u00e9n\u00a0para desearles paz para Navidad y el resto del a\u00f1o.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Amigos para siempre, como dice la canci\u00f3n de los Juegos Ol\u00edmpicos de Barcelona, as\u00ed parece que han quedado Cayetano Mart\u00ednez de Irujo, conde de Salvatierra, y los l\u00edderes del Sindicato Andaluz de Trabajadores (SAT) Diego Ca\u00f1amero y Juan Manuel S\u00e1nchez Gordillo.(fuentes\u00a0diversas escritas coincidentes) Mientras encuentro un\u00a0remedio\u00a0natural para combatir mi caspa,por ejemplo lo de jugo de [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-1270","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts\/1270","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/comments?post=1270"}],"version-history":[{"count":0,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts\/1270\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/media?parent=1270"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/categories?post=1270"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/tags?post=1270"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}