{"id":1285,"date":"2011-12-27T09:46:06","date_gmt":"2011-12-27T07:46:06","guid":{"rendered":"http:\/\/firmas.lasprovincias.es\/carlospajuelodearcos\/?p=1285"},"modified":"2011-12-27T09:46:06","modified_gmt":"2011-12-27T07:46:06","slug":"usted-manda-mucho-la-nina-de-rajoy-mas-que-usted-y-yo","status":"publish","type":"post","link":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/2011\/12\/27\/usted-manda-mucho-la-nina-de-rajoy-mas-que-usted-y-yo\/","title":{"rendered":"\u00bfUsted manda mucho? La ni\u00f1a de Rajoy m\u00e1s que usted y yo."},"content":{"rendered":"<p>LA CHISPA<\/p>\n<p>La ni\u00f1a<\/p>\n<p>Carlos Pajuelo de Arcos<\/p>\n<p>El presidente de la mayor\u00eda absoluta dijo e hizo carne su verbo con lo de la ni\u00f1a. Sorpresa a medias. Inc\u00f3gnita suficientemente despejada.<\/p>\n<p>La que lleg\u00f3, al parecer, de la mano de su propio historial acad\u00e9mico y humano, cristaliz\u00f3 nuevamente en el capullo enorme del Palacio monclovita.<\/p>\n<p>Ya mariposa volvi\u00f3 a devenir en cris\u00e1lida y ahora luce sus mejores colores p\u00fablicos. La admiro.<\/p>\n<p>De hormiga obrera, con pedigr\u00ed acad\u00e9mico demostrado, se afan\u00f3 hasta dominar el hormiguero y hoy es reina que pretende, seguro, ser libada por muchos que antes no la ten\u00edan ni por obrera. \u00a1Cosas!<\/p>\n<p>No me parece a m\u00ed que la tal ni\u00f1a haya mamado pijer\u00edo y no parece pija en el lenguaje y la pose. Es competente y si la dejan las circunstancias, los n\u00fameros y la pol\u00edtica barriobajera de las envidias, aqu\u00ed tenemos una mujer interesante para los objetivos del pa\u00eds. Sus tacones cuasiagujas no deben molestarnos. Es bajita y nada m\u00e1s.<\/p>\n<p>Estos p\u00e1rrafos laudatorios son el fruto de lo le\u00eddo, lo entrevisto y lo interpretable de todo lo apreciado por estos ojitos que la tierra consumir\u00e1.<\/p>\n<p>Supongo que a estas alturas ya muchas lenguas se preguntar\u00e1n las unas a las otras \u00bfSer\u00e1 mangoneadora? Lo dir\u00e1n porque su influencia tras la estrella del presiabsoluto ha hecho poner en puestos pol\u00edticorelumbrosos a algunos de sus colaboradores m\u00e1s cercanos. Natural, digo yo.<\/p>\n<p>\u00bfSer\u00e1 \u201cmangui\u201d?. No se la han visto maneras y si hubiera algo yo creo que a estas alturas la liebre hubiera saltado; no se le conoce \u201c\u00f1apa\u201d (estafa) alguna y su habla no es la un papagayo, es pausada, vocaliza bien y aunque dibuja morritos al empezar e incluso en las pausas, es un moh\u00edn que ahora no molesta, otrosi ser\u00eda si la \u201cni\u00f1a\u201d fuera menos ni\u00f1a y los morritos llegar\u00e1n ser el origen de baba.<\/p>\n<p>Al ser el CNI responsabilidad final suya, entrar\u00e1 a conocer secretos, los que le cuenten, que dar\u00edan para una serie de novela negra y es ah\u00ed donde yo le pedir\u00eda, si fuera el caso, una prudencia desmedida no dando p\u00e1bulo a radio macuto.<\/p>\n<p>Debe haber por all\u00ed, en los jardines de la Moncloa, por ejemplo, mucho runr\u00fan, mucho ruido de lenguas. \u00c1nimo nena. Buenos d\u00edas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>LA CHISPA La ni\u00f1a Carlos Pajuelo de Arcos El presidente de la mayor\u00eda absoluta dijo e hizo carne su verbo con lo de la ni\u00f1a. Sorpresa a medias. Inc\u00f3gnita suficientemente despejada. La que lleg\u00f3, al parecer, de la mano de su propio historial acad\u00e9mico y humano, cristaliz\u00f3 nuevamente en el capullo enorme del Palacio monclovita. [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-1285","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts\/1285","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/comments?post=1285"}],"version-history":[{"count":0,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts\/1285\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/media?parent=1285"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/categories?post=1285"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/tags?post=1285"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}