{"id":1373,"date":"2012-01-31T16:04:46","date_gmt":"2012-01-31T16:04:46","guid":{"rendered":"http:\/\/blogs.lasprovincias.es\/carlospajuelo\/?p=1373"},"modified":"2012-01-31T16:04:46","modified_gmt":"2012-01-31T16:04:46","slug":"el-miedo","status":"publish","type":"post","link":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/2012\/01\/31\/el-miedo\/","title":{"rendered":"El miedo"},"content":{"rendered":"<p>Las Provincias \/ 31-01<\/p>\n<p>LA CHISPA<br \/>\nEl miedo<br \/>\nCarlos Pajuelo de Arcos<br \/>\nEl juego permanente de los medios para reflejar una situaci\u00f3n peligrosa,  a trav\u00e9s de la agorera amenaza del hundimiento de la econom\u00eda, del medio ambiente, de la sanidad, de la educaci\u00f3n, cada d\u00eda m\u00e1s en el aire, del posible recorte de la libertad, de una justicia atascada, da miedo.<br \/>\n\u00bfSobreviviremos? Claro que s\u00ed.<br \/>\nLos medios reflejan lo que a ellos llega por diversas fuentes y ahora, las fuentes aparecen contaminadas por un virus. Es el virus de la codicia, la ambici\u00f3n, la chabacaner\u00eda y la corrupci\u00f3n como moneda de cambio visible.<br \/>\nHay otros mundos m\u00e1s all\u00e1 de ese panorama.<br \/>\nParece que estamos ante la puerta de un hundimiento y quienes mandan o aspiran a hacerlo de nuevo, se entretienen en pintar un horizonte maldito. Una pena.<br \/>\nEsa no es toda la verdad. Hay otra cara m\u00e1s numerosa, m\u00e1s generosa, m\u00e1s dada a servir. Son los miembros m\u00e1s mayores de las familias que soportan solidariamente el esfuerzo y de eso se habla poco. Pasee usted por las puertas de los colegios privados o p\u00fablicos.<br \/>\nAbuel@s, hermanos mayores, t\u00edas solteras, madres esperando recoger al ni\u00f1o, abrazos y besos.<br \/>\nTenemos que combatir el miedo<br \/>\nEl miedo se contagia y en cierto modo, pensaba yo, los periodistas contribuimos a difundir el virus. \u00bfSer\u00e1 cierto?<br \/>\nPor eso el que este diario haya puesto en marcha una especie de grito de El Palleter para animarnos y para hacernos creer que a pesar de todo, a pesar de algunos, conseguiremos vencer y abatir la bandera del miedo es un ejercicio valiente.<br \/>\nEl miedo se presenta como un demonio que desgarra de ansiedad el interior del cerebro hasta asentarse en el mismo, hasta conseguir una cierta paralizaci\u00f3n de su capacidad de reaccionar y cada d\u00eda el territorio que conquista parece mayor.<br \/>\nHay que combatirlo y debe hacerlo cada uno alegr\u00e1ndose de estar vivo primero, de poder decir lo que estoy diciendo yo aqu\u00ed y pensar que representa un espacio de libertad.<br \/>\nHemos trabajado mucho para tener esa libertad y no conseguiremos avanzar m\u00e1s si nuestro cerebro queda atenazado. Pensar en positivo, pensar en vivir cada d\u00eda plenamente es bueno y yo lo hice el domingo mientras paseaba cerca del mar. Buenos d\u00edas<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las Provincias \/ 31-01 LA CHISPA El miedo Carlos Pajuelo de Arcos El juego permanente de los medios para reflejar una situaci\u00f3n peligrosa, a trav\u00e9s de la agorera amenaza del hundimiento de la econom\u00eda, del medio ambiente, de la sanidad, de la educaci\u00f3n, cada d\u00eda m\u00e1s en el aire, del posible recorte de la libertad, [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-1373","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts\/1373","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/comments?post=1373"}],"version-history":[{"count":0,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts\/1373\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/media?parent=1373"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/categories?post=1373"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/tags?post=1373"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}