{"id":1390,"date":"2012-02-09T09:13:45","date_gmt":"2012-02-09T09:13:45","guid":{"rendered":"http:\/\/blogs.lasprovincias.es\/carlospajuelo\/?p=1390"},"modified":"2012-02-09T09:13:45","modified_gmt":"2012-02-09T09:13:45","slug":"que-es-una-nueva-masculinidad-no-tengo-ni-idea","status":"publish","type":"post","link":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/2012\/02\/09\/que-es-una-nueva-masculinidad-no-tengo-ni-idea\/","title":{"rendered":"\u00bfQu\u00e9 es una nueva masculinidad? No tengo ni idea"},"content":{"rendered":"<div>EL DESPILFARRO DEL D\u00cdA<\/div>\n<h1>Paj\u00edn se despidi\u00f3 del cargo subvencionando cursos de &#8220;nuevas masculinidades&#8221;fuente: Libre mercado<\/h1>\n<p>M\u00e1s de 4 millones de euros fueron distribuidos entre organizaciones diversas cuyo objetivo es conseguir avanzar en la\u00a0igualdad\u00a0llamada de &#8220;g\u00e9nero&#8221; a cargo de los\u00a0presupuestos\u00a0generales- que\u00a0recuerdo\u00a0aqu\u00ed que son la suma de\u00a0los\u00a0dineros que ingresamos todos v\u00eda\u00a0impuestos\u00a0directos e indirectos.<\/p>\n<p>La\u00a0igualdad\u00a0de\u00a0derechos\u00a0y deberes me parece un objetivo esencial y lucho d\u00eda a \u00a0d\u00eda\u00a0por ella intentando hacerla real en mi entorno. Lo que ya me parece menos\u00a0adecuado\u00a0es el reparto de los dineros p\u00fablicos en este asunto en plan bomba de racimo y caiga d\u00f3nde caiga.<\/p>\n<p>Para argumentar esto \u00faltimo recomiendo se lea la distribuci\u00f3n hecha en los\u00a0\u00faltimos\u00a0momentos de la\u00a0ministra\u00a0como tal y puede hacerlo acudiendo a la misma fuente que yo: &#8221; libre mercado&#8221;.<\/p>\n<p>Unos importantes dineros van a parar a investigar la llamada &#8220;nueva masculinidad&#8221;.<\/p>\n<p>La llamada &#8220;nueva masculinidad&#8221; es un concepto nuevo para mi. No tengo nada contra los nuevos conceptos pero me\u00a0gusta\u00a0entenderlos y este no lo entiendo.\u00a0Tenemos\u00a0en el pa\u00eds, o sea en\u00a0Espa\u00f1a, al \u00a0parecer un problema de\u00a0entendimiento\u00a0de lo que uno lee; de\u00a0comprensi\u00f3n\u00a0de\u00a0lo\u00a0escrito y por tanto\u00a0tenemos\u00a0una\u00a0nueva\u00a0frontera de analfabetismo. \u00bfDe que sirve saber leer, juntar unas letras con otras, decirlas en voz alta si uno no sabe lo que dice porque no lo comprende? \u00bfCuantas veces\u00a0repetimos\u00a0argumentos, expresiones etc que no comprendemos?<\/p>\n<p>\u00bfQu\u00e9 es una nueva masculinidad? \u00bfSe trata de un nuevo tipo de hombre? \u00bfTiene este nuevo tipo una mutaci\u00f3n? \u00bfLes han disminuido,crecido,eliminado sus partes pudendas y son sustituidas por alg\u00fan grifo de\u00a0extra\u00f1a\u00a0configuraci\u00f3n? \u00bfLos\u00a0habituales\u00a0pelos en pecho, espalda en plan &#8220;cuanto\u00a0m\u00e1s feo m\u00e1s hermoso&#8221; han caido\u00a0consecuencia\u00a0de alg\u00fan mecanismo hormonal y\u00a0ahora\u00a0somos m\u00e1s o\u00a0debemos\u00a0 ser m\u00e1s Madrid fashion no se\u00a0qu\u00e9?.<\/p>\n<p>\u00bfEl nuevo hombre es carne de gimnasio porque eso &#8220;pone&#8221; y adem\u00e1s\u00a0impresiona\u00a0al enclenque como yo hasta el extremo de por la noche llevar pa\u00f1os en\u00a0los\u00a0calzoncillos para evitar que el miedo se abra camino v\u00eda colon irritable,por ejemplo?<\/p>\n<p>Que cante la gallina o sea que alguien explique aqu\u00ed que es eso de la &#8220;nueva\u00a0masculinidad&#8221; y lo quiero saber pronto por si debo acudir a alguna conferencia d\u00f3nde tuviese que explicarlo. Yo amo a Paj\u00edn y lo hago con respeto porque parte de la pastizara\u00a0ha\u00a0ido a departamentos universitarios y yo supongo que de esa forma seremos m\u00e1s competitivos y saldremos del agujero cantando y mirando las estrellas como iguales. Buenos d\u00edas.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>EL DESPILFARRO DEL D\u00cdA Paj\u00edn se despidi\u00f3 del cargo subvencionando cursos de &#8220;nuevas masculinidades&#8221;fuente: Libre mercado M\u00e1s de 4 millones de euros fueron distribuidos entre organizaciones diversas cuyo objetivo es conseguir avanzar en la\u00a0igualdad\u00a0llamada de &#8220;g\u00e9nero&#8221; a cargo de los\u00a0presupuestos\u00a0generales- que\u00a0recuerdo\u00a0aqu\u00ed que son la suma de\u00a0los\u00a0dineros que ingresamos todos v\u00eda\u00a0impuestos\u00a0directos e indirectos. La\u00a0igualdad\u00a0de\u00a0derechos\u00a0y deberes me [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-1390","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts\/1390","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/comments?post=1390"}],"version-history":[{"count":0,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts\/1390\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/media?parent=1390"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/categories?post=1390"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/tags?post=1390"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}