{"id":1436,"date":"2012-03-24T08:12:40","date_gmt":"2012-03-24T08:12:40","guid":{"rendered":"http:\/\/blogs.lasprovincias.es\/carlospajuelo\/?p=1436"},"modified":"2012-03-24T08:12:40","modified_gmt":"2012-03-24T08:12:40","slug":"ensena-usted-el-culo-para-la-tv-m-mila-si","status":"publish","type":"post","link":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/2012\/03\/24\/ensena-usted-el-culo-para-la-tv-m-mila-si\/","title":{"rendered":"\u00bfEnse\u00f1a usted el culo para la TV? M.Mil\u00e1 si."},"content":{"rendered":"<p>Poco le quedaba ya a <a href=\"\/20120229\/estilo-gente\/abci-mercedes-mila-padre-muere-201202291440.html\">Mercedes Mil\u00e1 <\/a>por hacer en el plat\u00f3 de \u00abGH\u00bb. Hab\u00eda defendido a ultranza la rutina de hacer pis en la ducha y se hab\u00eda besado en varias ocasiones con los concursantes del programa, entre otras an\u00e9cdotas. Pero anoche, la popular presentadora quiso superarse a s\u00ed misma y decidi\u00f3 hacer un calvo, para m\u00e1s inri sin llevar ropa interior. Cierto es que Mil\u00e1 llevaba medias, pero lo suficientemente poco tupidas como para permitir mostrar claramente su trasero. (fuente: abc)<\/p>\n<p>Noto como esto de informar y entretener se est\u00e1 poniendo cada d\u00eda m\u00e1s dificil. Rosa M\u00aa Calaf periodista de raza, con a\u00f1os sobre sus espaldas informadoras, ha puesto en la l\u00ednea de su cr\u00edtica a Sara Carbonero por frivolizar,dice, su gesti\u00f3n informativa basada en su belleza. No s\u00e9. Ahora sucede que la otrora valiente reportera M.Mil\u00e1 ense\u00f1a el culo, se deja tocar una teta y digo yo si ser\u00e1 porque est\u00e1 de vuelta, est\u00e1 pasada de vueltas o es que se le acaba el tiempo y nos ense\u00f1a el culo para mejorar su imagen de atrevida que puede con todo.<\/p>\n<p>Yo he visto reproducidos los culos de los taxistas- que por cierto no s\u00e9 si ha servido para algo en materia de tarifas- y ahora ha proliferado el argumento &#8220;calvista&#8221; es decir lo que se llama, al parecer hacer&#8221; un calvo&#8221; con raya enmedio , a\u00f1ado yo.<\/p>\n<p>Imagino que si la moda se impone, los que est\u00e9n indignados en general, los ereliquidados, los descontentos con las tarifas de Iberdrola, un decir, llenar\u00e1n pantallas\u00a0, calles y cruces de peatones con calvos e incluso aquellos que sometidos a citaciones varias en consultas ambulatorias lucir\u00e1n traseros de diferente volumen y estructura. Pronto &#8220;por su hechos los conocereis&#8221; ser\u00e1 sustituido por sus culos los conocereis.<\/p>\n<p>Me resito a esa moda calvista. Es una regresi\u00f3n orangutaniana y un hecho que suma desprecio para el observador. Un &#8220;toma ese calvo&#8221; supone una burla y si para conseguir audiencia hay que ense\u00f1ar el culo, por mi que hay otras formas de uso del mismo.<\/p>\n<p>Tengo la sensaci\u00f3n de que pronto surgir\u00e1 un movimiento llamado, por ejemplo &#8220;contracalvos&#8221; y se evidenciar\u00e1 mediante el uso del smoking, del uso de la expresi\u00f3n correcta cuanod te diriges a los dem\u00e1s incluso podr\u00eda llegar a ocurrir que pronto se sorprenda uno cuando le saluden y le den las gracias por algo que uno ha hecho. He tenido mucho gusto y le doy las gracias por haberme le\u00eddo. Buenos d\u00edas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Poco le quedaba ya a Mercedes Mil\u00e1 por hacer en el plat\u00f3 de \u00abGH\u00bb. Hab\u00eda defendido a ultranza la rutina de hacer pis en la ducha y se hab\u00eda besado en varias ocasiones con los concursantes del programa, entre otras an\u00e9cdotas. Pero anoche, la popular presentadora quiso superarse a s\u00ed misma y decidi\u00f3 hacer un [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-1436","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts\/1436","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/comments?post=1436"}],"version-history":[{"count":0,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts\/1436\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/media?parent=1436"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/categories?post=1436"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/tags?post=1436"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}