{"id":1448,"date":"2012-04-01T07:46:24","date_gmt":"2012-04-01T07:46:24","guid":{"rendered":"http:\/\/blogs.lasprovincias.es\/carlospajuelo\/?p=1448"},"modified":"2012-04-01T07:46:24","modified_gmt":"2012-04-01T07:46:24","slug":"esta-usted-con-la-hora-del-planeta-prepare-la-cartera","status":"publish","type":"post","link":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/2012\/04\/01\/esta-usted-con-la-hora-del-planeta-prepare-la-cartera\/","title":{"rendered":"\u00bfEst\u00e1 usted con la hora del Planeta? Prepare la cartera"},"content":{"rendered":"<p>MADRID, 31 Mar. (EUROPA PRESS) &#8211;<\/p>\n<p>\u00a0\u00a0 Espa\u00f1a se ha sumado a la hora del planeta con el apag\u00f3n de sus edificios m\u00e1s emblem\u00e1ticos, desde la Sagrada Familia de Barcelona hasta el monasterio de El escorial en Madrid, y el mosacio de un panda en el que han participado m\u00e1s de 500 personas, en una iniciativa mundial que sirve como s\u00edmbolo de lucha contra el cambio clim\u00e1tico.<\/p>\n<p>\u00bfQui\u00e9n se niega, asi de salida, a estar con el Planeta?, Tiene risa, por no decir huevos, la cosa. Si yo vivo aqu\u00ed, en el Planeta como no voy a estar con el esf\u00e9rico mundo que me hace girar sin yo darme cuenta. Es una &#8220;boutade&#8221;. \u00bfPara estar hay que apagar la luz? Yo apago la luz porque acabo de enterarme que me han vuelto a subir la tarifa. Usted es un insolidario, me dir\u00e1. Puede. \u00bfPuedo yo apagar El Escorial, el Ayuntamiento, los plat\u00f3s de TV? Es obvio que no. \u00bfMe han pedido permiso a mi para apagar las luces de la fachada de El Prado, un decir. Pues no, no me lo han pedido. \u00bfLo hubiera dado, el permiso? Hombre seg\u00fan me lo pidan. La gente somos as\u00ed.Es cuesti\u00f3n de pedirlo. Claro que todos no somos iguales.<\/p>\n<p>Ayer caminaba yo por una acera esquivando bicicletas, carritos de beb\u00e9 con madre,abuela,nenes m\u00e1s grandecitos que ocupan todo lo ancho de la acera ( ahora comprendo al Bar\u00f3n Haussman que dise\u00f1o esas grandes avenidas en Paris ,para que las masas no se escondieran de sus cargas de caballer\u00eda) cuando de un portal salen dos perros de regulares dimensiones atados a una correa de dos bifurcaciones y en una urgencia se cagan doble sobre la misma acera dejando muestra amarilla de su existencia y su due\u00f1a no recog\u00edo.<\/p>\n<p>Un momento de estupor prodigioso. un silencio mayest\u00e1tico sobre y en el aire y las miradas concentradas sobre los ojos retadores de la due\u00f1a que nos dio la espalda y cuando alguien dijo &#8220;recoja usted las cagadas&#8221; se volvi\u00f3 desde\u00f1osa y sigui\u00f3.<\/p>\n<p>Hoy pasar\u00e9 a mirar si sigue la muestra sobre el adoqu\u00edn que en su sufrimiento mineral padece de todo. No basta con pedir. A lo mejor hay que exigir. \u00bfAhora, digame usted, como obliga a USA y a\u00a0 otros a firmar lo del protocolo de Kyoto? Yo aqu\u00ed miro como apagan y siendo bueno lo de apagar me cimbreo sobre mi mismo de la risa.<\/p>\n<p>De momento apago mi flexo por la tarifa disuasoria, voy andando- no porque me guste- sino porque el combustible se ha puesto a caer de un burro y no como langosta o cosas asi, no por la depredaci\u00f3n sitem\u00e1tica de los mares sino porque el precio est\u00e1 por un ri\u00f1\u00f3n y yo solo tengo dos.<\/p>\n<p>\u00bfAmo al Planeta?. Claro que lo amo. No tengo m\u00e1s hue&#8230;\u00bfHay otro sitio? Es como decir \u00bfAma usted a Rajoy o a Rubalcaba, o a Cospedal o a Valenciano? Ya, ya s\u00e9 que no es lo mimso, pero se le acerca. No tengo m\u00e1s remedio. Me voy al Sol. Buenos d\u00edas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>MADRID, 31 Mar. (EUROPA PRESS) &#8211; \u00a0\u00a0 Espa\u00f1a se ha sumado a la hora del planeta con el apag\u00f3n de sus edificios m\u00e1s emblem\u00e1ticos, desde la Sagrada Familia de Barcelona hasta el monasterio de El escorial en Madrid, y el mosacio de un panda en el que han participado m\u00e1s de 500 personas, en una [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-1448","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts\/1448","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/comments?post=1448"}],"version-history":[{"count":0,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts\/1448\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/media?parent=1448"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/categories?post=1448"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/tags?post=1448"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}