{"id":1470,"date":"2012-04-11T05:29:46","date_gmt":"2012-04-11T05:29:46","guid":{"rendered":"http:\/\/blogs.lasprovincias.es\/carlospajuelo\/?p=1470"},"modified":"2012-04-11T05:29:46","modified_gmt":"2012-04-11T05:29:46","slug":"es-la-propina-una-limosna","status":"publish","type":"post","link":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/2012\/04\/11\/es-la-propina-una-limosna\/","title":{"rendered":"\u00bfEs la propina una limosna?"},"content":{"rendered":"<p>LA PROPINA<\/p>\n<p>Stacy Knutson es una camarera de Minnesota con muchos problemas econ\u00f3micos. Su sueldo apenas le da para mantener cada mes a sus cinco hijos. Alguien que conoc\u00eda sus apuros le dej\u00f3 en una caja una propina extraordinaria por haberles atendido bien en el bar: 12.000 d\u00f3lares.<\/p>\n<p>Eso es una propina y no los dos o tres euros que deja usted si fuera el caso.<\/p>\n<p>Hace a\u00f1os una acomodadora en un cine Paris me mantuvo la luz de la linterna durante casi un minuto enfocada\u00a0 a la cara porque no le hab\u00eda dado propina. Me enfad\u00e9 y luego me dijeron que aquella propina estaba establecida porque formaba parte de su salario. O sea que yo estaba atentando contra su sueldo, pero el precio de la entrada no era m\u00e1s barato. Un ejemplo este de abuso del empresario.<\/p>\n<p>Ahora que propinas como est\u00e1 para m\u00ed las quisiera yo. Eso ayuda a preocuparte un poco menos.<\/p>\n<p>Por cierto y aunque est\u00e1 lejos del n\u00facleo de la noticia y reflexi\u00f3n \u00a0\u201cpropinesca\u201d es el caso que entr\u00e9 a ver una pel\u00edcula de Aurora Bautista y Paco Rabal en Paris hace a\u00f1os y entr\u00e9 porque en las fotos de la pel\u00edcula-no me acuerdo del t\u00edtulo &#8211; pero s\u00e9 que era un drama pasional que se desarrollaba en el Sur-mostraban a la Sra. Bautista \u201cen pelota picada\u201d y eso era en plena aplicaci\u00f3n de la censura en Espa\u00f1a; en algunos cines de colegios los besos se tapaban con la mano del proyectista seglar o religioso. Imperaba la idea de la castidad como bien supremo.<\/p>\n<p>Al parecer se rodaban dos versiones una nacional y otra para el extranjero d\u00f3nde el gui\u00f3n \u201cobligaba \u201ca la actriz a mostrar sus encantos. Pasabas de Locura de Amor de \u201cla Bautuista\u201d a la lozana andaluza que era generosa en sus carnes desnudas para goce visual\u2026si estabas fuera de las fronteras. Una discriminaci\u00f3n carnal, es obvio.<\/p>\n<p>De vez en cuando nos iluminaban con Mar\u00eda Goretti que prefiri\u00f3 morir a perder, entre otras, cosas lo que se llamaba el bien supremo de la virginidad. Era un don- el no perder la virginidad- que se dejaba para despu\u00e9s de haber pasado por el altar y eso,. Por cierto generaba a los novios en estado de merecer grandes problemas de dolor en sus santos atributos; unas orquitis de caballo y unas visitas a los prost\u00edbulos que estaban regulados y hab\u00eda muchos en la ciudad concentrados en un \u00e1rea hoy sobrepasada<\/p>\n<p>Ahora hay menos orquitis y sin embargo, por lo que uno lee, hay m\u00e1s putas. Debe ser la crisis.<\/p>\n<p>\u00bfEs la propina un acto de humillaci\u00f3n para quien la recibe? \u00bfEs la propina a manera de un anticuerpo protector para quien la da?<\/p>\n<p>Soy partidario del salario justo y no de las propinas que siempre quedan al socaire de la generosidad y\/o disponibilidad de \u201cpropinador\u201d. Hay sitios d\u00f3nde te aconsejan que dejes del orden del 10 % del valor de la factura.<\/p>\n<p>\u00bfEs la propina un acto de limosna limpiadora de un cierto sentido de la culpabilidad por haber comido y porque te hayan servido?<\/p>\n<p>Dejo en sus mentes la semilla de la duda y me apresuro a ver si hoy hace menos aire en Valencia y me curo el constipado que esos catarros llamados primaverales te dejan de propina mocos y fatiga. Buenos d\u00edas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>LA PROPINA Stacy Knutson es una camarera de Minnesota con muchos problemas econ\u00f3micos. Su sueldo apenas le da para mantener cada mes a sus cinco hijos. Alguien que conoc\u00eda sus apuros le dej\u00f3 en una caja una propina extraordinaria por haberles atendido bien en el bar: 12.000 d\u00f3lares. Eso es una propina y no los [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-1470","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts\/1470","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/comments?post=1470"}],"version-history":[{"count":0,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts\/1470\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/media?parent=1470"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/categories?post=1470"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/tags?post=1470"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}