{"id":1499,"date":"2012-05-07T06:43:14","date_gmt":"2012-05-07T06:43:14","guid":{"rendered":"http:\/\/blogs.lasprovincias.es\/carlospajuelo\/?p=1499"},"modified":"2012-05-07T06:43:14","modified_gmt":"2012-05-07T06:43:14","slug":"bruni-y-ahora-que","status":"publish","type":"post","link":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/2012\/05\/07\/bruni-y-ahora-que\/","title":{"rendered":"Bruni. \u00bfY ahora qu\u00e9?"},"content":{"rendered":"<p>Carla Bruni lleg\u00f3 a la vida del presidente franc\u00e9s poco despu\u00e9s de hacerse efectivo su divorcio con C\u00e9cilia. La que fuera una modelo y cantante italiana de reconocido talento se ha convertido en un pilar fundamental en su vida y un arma eficaz para su prop\u00f3sito de alejarse de su imagen de nuevo rico. Las declaraciones p\u00fablicas de Bruni se afanan en denotar la sencillez y normalidad del dirigente galo:\u00a0<strong>\u201cSomos gente modesta\u201d<\/strong>\u00a0o \u201cAl lado de madame Pompidou, yo soy Lady Gaga\u201d.<\/p>\n<p>La biograf\u00eda del perdedor , autorizada, franc\u00e9s &#8220;Sarko&#8221; titulada &#8220;el Impetuoso&#8221; narra sus amor\u00edos y otras facetas del hombre que no ha resitido la austeridad global.A mi siempre me han interesado las mujeres y sobre todo las llamadas primeras damas y su papel antes, durante y despues del mandato de sus maridos- que son antes maridos que presidentes- y eso no debe olvidarse. Los presidentes y las presidentas huelen tambi\u00e9n por las ma\u00f1anas e incluso por las tardes.<\/p>\n<p>Ahora me pregunto por esta se\u00f1ora Bruni. \u00bfAguantar\u00e1 el segundo plano al que deliberadamente ha pasado en la segunda vuelta? \u00bfSe ol\u00eda &#8220;madame&#8221; el batacazo? \u00bfEscribir\u00e1 un libro bajo el titulo : &#8220;Mis a\u00f1os en el Eliseo&#8221; o &#8220;Sarko no es tan impetuoso como dec\u00edan&#8221;?. \u00bfSe lanzar\u00e1 a la moda o volvera a la canci\u00f3n ligera? !Voil\u00e1!<\/p>\n<p>Durante un tiempo las primeras damas han obtenido titulares a la sombra de sus maridos, acompa\u00f1andolos en campa\u00f1a, sonriendo cuando tocaba e incluso haciendo algo en el mundo de las inauguraciones. Algunas han tenido y tienen vida p\u00fablica propia. Muchas surgen como estrellas rutilantes de mundos p\u00fablicos como el periodismo y \u00bfdeliberadamente? renuncian a su ejercicio. \u00bfEs el amor? \u00bfBasta con la sombra del poderoso? \u00bfEs el privilegio de tener siempre entradas gratuitas para los mejores shows o &#8220;papear&#8221; siempre de 5 tenedores o es &#8220;mira mam\u00e1 como lo he conseguido? Un interesante mundo por investigar. \u00bfLa conversi\u00f3n en &#8220;figamolla&#8221;- localismo sem\u00e1ntico sin acento malvado- es lo habituial en las primeras damas?<\/p>\n<p>Aqu\u00ed hay una tesis o dos sobre la evoluci\u00f3n de las primeras damas que pasan a ser simplemente &#8220;Mar\u00eda&#8221;. Ya nuestra Leticia no competir\u00e1 con Bruni para ver quien va mejor ataviada; sus disfraces de alta costura, ajustada a l\u00edneas f\u00edsicas que dan en anorexicas, ser\u00e1n objeto de mediciones distintas y con diferentes damas. Es el vaiv\u00e9n de la democracia en unos casos\u00a0 verusus\u00a0la institucionalidad del servicio para siempre, del buen papel que las monarqu\u00edas- seg\u00fan el socialista Gonzales\u00a0devenido a monarquico nos dice estos d\u00edas-. \u00bfSe desgastan las primeras damas o se gastan menos las princesas, futuribles reinas?<\/p>\n<p>Seguir\u00e9 el rastro de Bruni. La primera dama nuestrs es tan discreta como &#8220;il suo marito&#8221; a quien s ele ehca de menos un pco. Solo se ve en reuniones de alto nivel y vemos, eso si, a otras mujeres ministras y secretarias de partido a todo meter en la TV. La discreci\u00f3n tendente al mutismo habita ahora en la Moncloa. \u00bfBueno, malo,regular? Ni idea. El Sol est\u00e1 ya fuera y la casa sin barrer. !Uff! Me voy, parto a lo ignoto.Buenos d\u00edas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Carla Bruni lleg\u00f3 a la vida del presidente franc\u00e9s poco despu\u00e9s de hacerse efectivo su divorcio con C\u00e9cilia. La que fuera una modelo y cantante italiana de reconocido talento se ha convertido en un pilar fundamental en su vida y un arma eficaz para su prop\u00f3sito de alejarse de su imagen de nuevo rico. Las [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-1499","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts\/1499","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/comments?post=1499"}],"version-history":[{"count":0,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts\/1499\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/media?parent=1499"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/categories?post=1499"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/tags?post=1499"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}