{"id":1523,"date":"2012-05-22T06:04:40","date_gmt":"2012-05-22T06:04:40","guid":{"rendered":"http:\/\/blogs.lasprovincias.es\/carlospajuelo\/?p=1523"},"modified":"2012-05-22T06:04:40","modified_gmt":"2012-05-22T06:04:40","slug":"demasiado-consenso-en-el-congreso-del-pp","status":"publish","type":"post","link":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/2012\/05\/22\/demasiado-consenso-en-el-congreso-del-pp\/","title":{"rendered":"\u00bfDemasiado consenso en el Congreso del PP?"},"content":{"rendered":"<p><strong>LA CHISPA<\/strong><\/p>\n<p><strong>El resultado<\/strong><\/p>\n<p><strong>Carlos Pajuelo de arcos<\/strong><\/p>\n<p><strong>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0Tengo noticia del fin del Congreso del PP en la Comunidad y tengo noticia de algunos titulares d\u00f3nde se duda de la victoria del actual Sr. Fabra que es el Presidente de la Comunidad- obvio si es usted de aqu\u00ed y no tan obvio si es de fuera de este id\u00edlico lugar d\u00f3nde las flores se dan por doquier junto la basura no recogida (faltar\u00eda aqu\u00ed alguna sucursal de los Soprano).<\/strong><\/p>\n<p><strong>El hombre que preside debe estar \u201cmosca\u201d porque le ha salido un grano que aporta m\u00e1s d\u00e9ficit a la cosa p\u00fablica\u00a0\u00a0y para el uso de argumentos de la oposici\u00f3n y supongo que no lo esperaba. Es un for\u00fanculo en salva sea la parte democr\u00e1tica y eso le resta credibilidad en G\u00e9nova\u00a0<em>street<\/em>.<\/strong><\/p>\n<p><strong>La credibilidad est\u00e1 ahora en horas bajas<\/strong><\/p>\n<p><strong>El resultado congresual\u00a0\u00a0\u201cdudoso\u201d arroja del orden de m\u00e1s de un 80%\u00a0\u00a0de votos. \u00bfQu\u00e9 querr\u00edan? Un congreso\u00a0\u00a0a la \u201cb\u00falgara\u201d d\u00f3nde como m\u00ednimo es del 100 % y digo m\u00ednimo, porque\u00a0\u00a0a lo mejor podr\u00edan llegar los votos a superar a los asistentes, en un ejercicio m\u00e1ximo de favor \u201cal gran l\u00edder\u201d.<\/strong><\/p>\n<p><strong>Parece que ha habido unos votos en blanco, otros en contra y en total un poco m\u00e1s del 15\/16% que se manifiesta en oposici\u00f3n. Eso, dir\u00edan los polit\u00f3logos, sirve para afianzar el concepto de democracia y es la savia elaborada de un partido en pleno vigor etc, etc.<\/strong><\/p>\n<p><strong>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0Los que ganan crecen en volumen y alcanzan una masa cr\u00edtica que puede resultar peligrosa para los ciudadanos. \u00bfPeligrosa? Si.<\/strong><\/p>\n<p><strong>Esta masa cr\u00edtica privatiza el poder y democratiza los errores, de tal suerte que el Gobierno tiene que salir a decir: \u201cNo pasa\u00a0n\u00e1\u201d.<\/strong><\/p>\n<p><strong>Eso de que la gente ha perdido la confianza en los bancos es un error de interpretaci\u00f3n y el que muchos dep\u00f3sitos hayan \u201cvolado\u201d\u00a0\u00a0no es que se lo lleven crudo sino que est\u00e1n destinados a gastos de casa. La casa es cara.<\/strong><\/p>\n<p><strong>Rajoy en Chicago en plan OTAN y con sus aprox. 30 millones de nada para el tema del escudo de misiles en Rota y el ejercito sin casi papel higi\u00e9nico. Toma ya Chicago. Buenos d\u00edas.<\/strong><\/p>\n<p><strong>\u00a0Buenos d\u00edas.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>LA CHISPA El resultado Carlos Pajuelo de arcos \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0Tengo noticia del fin del Congreso del PP en la Comunidad y tengo noticia de algunos titulares d\u00f3nde se duda de la victoria del actual Sr. Fabra que es el Presidente de la Comunidad- obvio si es usted de aqu\u00ed y no tan obvio si es de [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-1523","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts\/1523","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/comments?post=1523"}],"version-history":[{"count":0,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts\/1523\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/media?parent=1523"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/categories?post=1523"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/tags?post=1523"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}