{"id":1527,"date":"2012-05-26T07:25:55","date_gmt":"2012-05-26T07:25:55","guid":{"rendered":"http:\/\/blogs.lasprovincias.es\/carlospajuelo\/?p=1527"},"modified":"2012-05-26T07:25:55","modified_gmt":"2012-05-26T07:25:55","slug":"le-tocan-a-usted-algo-en-las-concentraciones-de-masas-el-culola-cartera-ojo","status":"publish","type":"post","link":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/2012\/05\/26\/le-tocan-a-usted-algo-en-las-concentraciones-de-masas-el-culola-cartera-ojo\/","title":{"rendered":"\u00bfLe tocan a usted algo en las concentraciones de masas?\u00bf El culo,la cartera? !Ojo!"},"content":{"rendered":"<p>El toc\u00f3n (Flash del Suplemento de salud del 26-05-12)<\/p>\n<p>El domingo pasado en\u00a0 la Virgen lo he visto otra vez. Era el toc\u00f3n y en valenciano \u201cpalpaculs\u201d.<\/p>\n<p>Posee una mano tonta, abierta la palma, y cachea impunemente la &#8220;galta&#8221; trasera, preferentemente del sexo opuesto.<\/p>\n<p>El \u00e1rea de predaci\u00f3n del &#8220;palpaculs&#8221; es la concentraci\u00f3n de masas.<\/p>\n<p>Un depredador que satisface su instinto gluteotocador por la v\u00eda de la multitud que , a veces, surge en su entorno con un esc\u00e1ndalo mientras huye, sin pudor, entre las filas apretadas de fieles al acto. Una especie que va a m\u00e1s.<\/p>\n<p>Por eso me veo en la obligaci\u00f3n antropol\u00f3gica de hacer de vocero del pudor y advertir que el sujeto se ha retirado a sus cuarteles de primavera en espera de la pr\u00f3xima ocasi\u00f3n en que la Dipu, por ejemplo, traiga, a nuestra costa, a alg\u00fan grupo al circo masivo de electores y consumidores del pan y circo correspondiente para ahuyentar la crisis y las peticiones de facturas de corte y confecci\u00f3n. Ese es su campo. El &#8220;palpaculs&#8221; acecha,no duerme.<\/p>\n<p>Cerca ha estado el traslado de la Verge y ah\u00ed, mientras las madres devotas dejaban a sus hijos volar entre las manos alzadas de los que &#8220;prietas las filas&#8221; no dejan caer una hoja de papel al suelo, &#8220;el palpaculs&#8221; acechaba \u00a0encubierto de seguidor de la Virgen. Desconf\u00eden del &#8220;gritador&#8221; que piropea y deja caer la mano abierta y tonta. Es \u00e9l. Ha llegado. Le\u00f1a al mono y luego no digan que no aviso.<\/p>\n<p>Otras manos buscan otras a\u00e9reas del cuerpo vestido como es el caso de la chaqueta o el pantal\u00f3n d\u00f3nde reposa inocente la cartera.<\/p>\n<p>Pronto vendr\u00e1n m\u00e1s concentraciones- ahora salimos a una diaria- y pronto se quejar\u00e1n los sindicalistas, los profesores, los enfermeros y enfermeras y lo har\u00e1n tambi\u00e9n los funcionarios y los accionistas de Bankia acompa\u00f1ados de los del Banco de Valencia, haciendo pi\u00f1a con los de la CAM.! Valencians tots a una veu!. Aqu\u00ed si hay que pitar. \u00a0Ojo al dato.\u201d Palpaculs\u201d y carteristas est\u00e1n al acecho. Buenos d\u00edas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El toc\u00f3n (Flash del Suplemento de salud del 26-05-12) El domingo pasado en\u00a0 la Virgen lo he visto otra vez. Era el toc\u00f3n y en valenciano \u201cpalpaculs\u201d. Posee una mano tonta, abierta la palma, y cachea impunemente la &#8220;galta&#8221; trasera, preferentemente del sexo opuesto. El \u00e1rea de predaci\u00f3n del &#8220;palpaculs&#8221; es la concentraci\u00f3n de masas. [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-1527","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts\/1527","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/comments?post=1527"}],"version-history":[{"count":0,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts\/1527\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/media?parent=1527"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/categories?post=1527"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/tags?post=1527"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}