{"id":1535,"date":"2012-06-01T06:52:23","date_gmt":"2012-06-01T06:52:23","guid":{"rendered":"http:\/\/blogs.lasprovincias.es\/carlospajuelo\/?p=1535"},"modified":"2012-06-01T06:52:23","modified_gmt":"2012-06-01T06:52:23","slug":"esta-usted-solo-no-se-lo-consienta","status":"publish","type":"post","link":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/2012\/06\/01\/esta-usted-solo-no-se-lo-consienta\/","title":{"rendered":"\u00bfEst\u00e1 usted solo? No se lo consienta"},"content":{"rendered":"<p><em>La Guardia civil investiga la identidad del cad\u00e1ver hallado en una casa de la localidad de Ca\u00f1izal (Zamora) que podr\u00eda corresponder a su morador, un hombre desaparecido hace unos veinte a\u00f1os y que en la actualidad tendr\u00eda 73 a\u00f1os. El esqueleto fue encontrado tendido en el pasillo del inmueble en la noche del pasado viernes por el sobrino de este hombre. (fuente ABC).<\/em><\/p>\n<p><strong>Debemos hacernos visibles,sociales,estar. Se lo ten\u00eda dicho a D.Juanito un profesor de Historia del Derecho que compart\u00eda conmigo Universidad, emeritaje y tertulia.Esto \u00faltimo era lo m\u00e1s interesante.Una delicia de persona y un ilustrado como ya no quedan. Lo quer\u00eda. Y eso que era muy bajito pero era inteligente y me pueden los inteligentes. Su voz aguda e infantil me daba risa tierna y sus argumentos juridicos eran impecables. No s\u00e9 porque uno de los \u00faltimo d\u00edas nos dio por hablar en torno a la soledad y aquello deriv\u00f3 en el analisis filosofico del&#8221;vicio solitario&#8221; como s\u00edntoma definitivo de soledad integral. <\/strong><\/p>\n<p><strong>Otros estupendos compa\u00f1eros argumentaron con algun \u00a0refran al uso. como ese : &#8220;El buey solo bien se lame&#8221;<\/strong><\/p>\n<p><strong>Era una tertulia corta de gentes e intensa de contenido. Sirven las tertulias, a mi juicio, para establecer, a veces, un debate que no se queda solo frente a la pared o a la cuartilla en blanco. Supongo que luego de esa tertulia cada uno se va a su casa con la misma idea del origen, pero con el alma contenta por haber sido capaz de estar ah\u00ed y salir con la misma tensi\u00f3n con la que entr\u00f3. D.Juanito desaperci\u00f3 y todos sentimos una pena honda y no nos hemso vuelto a reunir. Era el alma.<\/strong><\/p>\n<p><strong>No va la columna, eso se dice as\u00ed ahora, de D.Juanito, sino de la soledad<\/strong><\/p>\n<p><strong>La soledad era uno de nuestros temas estrella.Todos tenemos y ten\u00edamos familia, pero el tiempo, se ve, erosiona el contacto humano distanciandolo y llenandolo de prisas convertidas en murallas de Berlin de difcil derribo.<\/strong><\/p>\n<p><strong>Uno cree que est\u00e1 y de repente deja de estar y si eres un individuo semip\u00fablico por esta acci\u00f3n de dar opiniones sobre todo y a veces sobre todos, lo eres como sujeto de pie o sentado( seg\u00fan tu mismo seas de vanidoso) sobre un soporte que no es tuyo sino prestado .En este caso m\u00edo es la columna digital de un diario que me deja decir cosas en diferentes formatos y soportes. Un detalle.<\/strong><\/p>\n<p><strong>Un d\u00eda dejas de acudir a la cita digital a la de papel ,a la del Suplemnto y dejar de escribir novelas de dudoso \u00e9xito p\u00faiblico y ya no est\u00e1. Un instante y docenas de sujetos se dar\u00e1n nuevas citas y el breve tiempo que va de un lector \u00a0asiduo a otro menos asiduo es suficiente para desaparecer. Ese es el primer paso. A lo mejor si est\u00e1s m\u00e1s solo dicen que has cumplido tu sue\u00f1o de dar la vuelta al mundo antes de que sea tarde. Qu\u00e9 no se\u00a0 sepa nada de ti. Un d\u00eda te encuentran frente a un ordenador que tiene la pantalla en blanco y tu mirda perdida en quien sabe d\u00f3nde.<\/strong><\/p>\n<p><strong>Como se ve la cosa no ha resultado optimista. Siempre nos queda el futbol,Nadal, la prima de riesgo y la mam\u00e1 que pari\u00f3 a los que nos han hecho la famosa bicicleta. El sol.sombre y una nueva tertulia me espera.Buenos d\u00edas.<\/strong><\/p>\n<p><strong>NOTA: A partir de hoy apunten, amables amigos, en sus agendas que mi nueva novela &#8220;El demonio del Mediod\u00eda&#8221; se presentar\u00e1 en El Corte Ingl\u00e9s de la calle Col\u00f3n- Ambito Cultural el 21 de Junio a las 19 horas. Cuanto m\u00e1s vengan me sentir\u00e9 menos solo y a lo mejor vendo alguna.Gracias.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Guardia civil investiga la identidad del cad\u00e1ver hallado en una casa de la localidad de Ca\u00f1izal (Zamora) que podr\u00eda corresponder a su morador, un hombre desaparecido hace unos veinte a\u00f1os y que en la actualidad tendr\u00eda 73 a\u00f1os. El esqueleto fue encontrado tendido en el pasillo del inmueble en la noche del pasado viernes [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-1535","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts\/1535","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/comments?post=1535"}],"version-history":[{"count":0,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts\/1535\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/media?parent=1535"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/categories?post=1535"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/tags?post=1535"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}