{"id":1541,"date":"2012-06-06T06:30:07","date_gmt":"2012-06-06T06:30:07","guid":{"rendered":"http:\/\/blogs.lasprovincias.es\/carlospajuelo\/?p=1541"},"modified":"2012-06-06T06:30:07","modified_gmt":"2012-06-06T06:30:07","slug":"casanovas-de-burundanga","status":"publish","type":"post","link":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/2012\/06\/06\/casanovas-de-burundanga\/","title":{"rendered":"casanovas de burundanga"},"content":{"rendered":"<p>La b<strong>urundanga<\/strong>,<br \/>\nuna droga de origen vegetal que tiene el poder de suprimir la voluntad y la<br \/>\nmemoria de las personas durante el tiempo que dura su efecto, es conocida y<br \/>\nusada desde hace 30 siglos como base para envenenamientos, conspiraciones y<br \/>\np\u00f3cimas de amor.(fuente: agencia efe)<\/p>\n<p>Han detenido en Madrid , afectado de enanismo,\u00a0 a un individuo acusado de violar a m\u00e1s de 38 mujeres usando la droga obtenida de una flores en forma de trompeta. Una especie de droga &#8220;musical&#8221; que sirvi\u00f3 al &#8220;enano&#8221; ( sin menoscabo de otros) para perge\u00f1ar tocamientos y violaciones partiendo de un inicial proceso de credibilidad cuando se anunciaba como &#8220;cham\u00e1n&#8221;.<\/p>\n<p>Paralelamente y seg\u00fan otras fuentes existen estudiosos de Giacomo Casanova ( casanovistas) al que se le atribuye la seducci\u00f3n de una 122 mujeres. Muchas de las cuales \u00a0han sido localizadas hist\u00f3ricamente, lo que da un cierto viso de realidad a lo que ese mismo cuenta. En todo caso\u00a0 la belleza de Giacomo y el enanismo citado no parecen influir en el enamoramiento cuyo origen est\u00e1 , alo mejor, en la predisposici\u00f3n a creer.<\/p>\n<p>Las ciencias ocultas, los fenomenos llamados paranormales, la afici\u00f3n a la lectura del porvenir y otras t\u00e9cnicas de &#8220;embobameiento credulo&#8221; est\u00e1n en muchos de nuestros compatiotras,por ejemplo. No me considera exento o a salvo, Se dice que el amor es ciego, que transforma un grano en una ligera peca a los ojos del que ama. Is possible.<\/p>\n<p>\u00bfNo? Piense usted conmigo en las llamadas &#8220;preferentes&#8221; por algunos bancos y piense usted en cuantos ahorradores han sido cogidos de la mano porque quienes\u00a0 teniendo la confianza de clientes-impositores- han conducido a la ruina a tantas familias que como desahogo- quiz\u00e1s no saben o no pueden hacer otra cosa- se manifiestan frente a la Generalitat o se visten de &#8220;yayo-flautas- para forzar una soluci\u00f3n.<\/p>\n<p>Han cre\u00eddo, una vez m\u00e1s han creido, que el poder est\u00e1 en el pueblo y en la &#8220;toma de la calle&#8221;. A lo mejor no terminan de ver con la claridad de algunos Presidentes que la Justicia &#8220;soy yo&#8221;. Dijo Rajoy, ayer en el Senado, que la opini\u00f3n popular,de la calle, se da cada cuatro a\u00f1os. Pensaba en elecciones y suger\u00eda no ponerse nerviosos.<\/p>\n<p>Yo deseo creer tambi\u00e9n en la buena voluntad de aquellos que me aconsejan pero empiezo a pensar que no todos desean ayudarme y empiezo a creer que emplean con nosotros una especie de burundanga. Nos tocan la trompeta y su sustancia. Espero que no sigan tocandonos otras partes blandas.<\/p>\n<p>Habr\u00e1 que hacer como PipiCalzaslargas aquella ni\u00f1a &#8220;anarco&#8221; que , al parecer, han reeditado algunos editores. La ni\u00f1a no cre\u00eda en el dinero, ni en el trabajo, ni en lavarse, ni en demasiadas cosas. La ni\u00f1a de origen sueco se hac\u00eda la idem. Yo disfrut\u00e9, ya mayor claro, aquella serie que romp\u00eda con todo. Y fijate que en esa \u00e9poca la RTVE la dirig\u00eda Adlfo Suarez y era un choque contra la educaci\u00f3n clasica. Lo dec\u00edan ayer en RNE en &#8220;asuntos propios&#8221; y yo creo que ten\u00edan raz\u00f3n. Me voy a airear y a quitarme &#8220;burundangas&#8221; de encima.Buenos d\u00edas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La burundanga, una droga de origen vegetal que tiene el poder de suprimir la voluntad y la memoria de las personas durante el tiempo que dura su efecto, es conocida y usada desde hace 30 siglos como base para envenenamientos, conspiraciones y p\u00f3cimas de amor.(fuente: agencia efe) Han detenido en Madrid , afectado de enanismo,\u00a0 [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-1541","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts\/1541","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/comments?post=1541"}],"version-history":[{"count":0,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts\/1541\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/media?parent=1541"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/categories?post=1541"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/tags?post=1541"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}