{"id":1545,"date":"2012-06-09T07:57:03","date_gmt":"2012-06-09T07:57:03","guid":{"rendered":"http:\/\/blogs.lasprovincias.es\/carlospajuelo\/?p=1545"},"modified":"2012-06-09T07:57:03","modified_gmt":"2012-06-09T07:57:03","slug":"me-sobra-gpr17","status":"publish","type":"post","link":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/2012\/06\/09\/me-sobra-gpr17\/","title":{"rendered":"Me sobra Gpr17"},"content":{"rendered":"<p><em>Para confirmar que el receptor est\u00e1 implicado en el control del apetito, los investigadores inyectaron un activador de Gpr17 en ratones normales, aumentando su apetito. A la inversa, cuando a los ratones se les administr\u00f3 un inhibidor de Gpr17, su apetito disminuy\u00f3.<\/em><\/p>\n<p><em>\u00a0\u00a0 Seg\u00fan Accili, hay varias razones por las que Gpr17, que tambi\u00e9n se encuentra en los seres humanos, ser\u00eda un buen objetivo para crear medicamentos contra la obesidad. (fuente: europa press)<\/em><\/p>\n<p><strong>Acabo de terminar de liquidar un paquete de fartons mientras leo esta estimulante noticia sobre un inhibidor del apetito. Tengo claro que no es la obesidad el \u00fanico objetivo de los laboratorios que en el mundo son. Est\u00e1 claro. <\/strong><\/p>\n<p><strong>Quieren quitarnos el apetito que es lo \u00faltimo que nos quedaba por regular y si, lo ver\u00e1n como yo, no tenemos apetito nos har\u00e1 falta menos dinero para comer y si es as\u00ed ,todas las manifestaciones que a la saz\u00f3n se producen d\u00eda y tarde tras tarde cesar\u00e1n.<\/strong><\/p>\n<p><strong>La cosa se calmara mientras los que se manifiestan encuentran otra fuente, hay muchas,de d\u00f3nde emanen el sentido de la Justicia, con permiso del Presidente de la misma.<\/strong><\/p>\n<p><strong>Que la prima de riesgo se dispara , que si el rescate est\u00e1 pr\u00f3ximo.,que si son 40 mil los millones para que estos chicos de la banca\u00a0 han de &#8220;levantar&#8221; y \u00a0as\u00ed vuelvan a capitalizarse y sigan haciendo como si no fuera con ellos, Vale. <\/strong><\/p>\n<p><strong>Como no tendr\u00e9 hambre me convertir\u00e9 en un indignado pasivocopulativo ( esta es una figura que me acabo de inventar porque estoy pasivo y ya se sabe que el tonto para distraerse se dedica a follar y a tener hijos\u00a0 o sin ser tonto al t\u00edo le gusta o es que les gustan los ni\u00f1os. Yo que s\u00e9. Haber algo, hay ah\u00ed)<\/strong><\/p>\n<p><strong>Si la gente tiene m\u00e1s hambre o sea que va sobrada del Gpr17 vas listo. <\/strong><\/p>\n<p><strong>Ah\u00ed tienes el vaso de agua, las bofetadas contra dos se\u00f1oras que pusieron a parrir,se ve, al lider de la cosa neonazi en Grecia y el t\u00edo- al que le sobra testosterona o diplomacia o educaci\u00f3n-\u00a0\u00a0\u00a0se levanta y tira agua y da un par de manporros a diestro y siniestro y en un diesstro o en un siniestro estaba la tertuliana que deb\u00eda ser un poco roja o algo de emigrante porque al neonazi se le sub\u00edo la nueva svastica al hipotalamo, por ejemplo. Tiene que adegazar.Es obvio.<\/strong><\/p>\n<p><strong>El asunto de las declaraciones de MAFO ( el alias del ex gobernador de Espa\u00f1a) son expectantes o sea que no ha dicho nada y deja entrever que el Gobierno no le permite decir esta boca es m\u00eda y por lo bajini acepta que ha habido alg\u00fan error. Le falra Gpr17.<\/strong><\/p>\n<p><strong>La t\u00e1ctica es siempre la misma. Querer hasta el meter ( es de la zona del Quijote el refr\u00e1n) y luego una melifua sonrisa mientras me voy a casa y digo: &#8220;ya hablar\u00e9 cuando me dejen&#8221;. Un listo m\u00e1s. \u00bfA este le har\u00e1n alg\u00fan homenaje? Deber\u00edan hacerselo los que se han forrado con \u00e9l.\u00a0<\/strong><strong>\u00a0<\/strong><\/p>\n<p><strong>Coinciden, que casualidad, con la c\u00fapula bancaria de los que ahora piden rescate.<\/strong><\/p>\n<p><strong>He llamado al servicio aereo de rescate a Castell\u00f3n y como aun no tiene aviones no pueden ponerse.Estaba solo el de los pajaros y se ve que alguien m\u00e1s porque se o\u00eda una voz femenina.<\/strong><\/p>\n<p><strong>\u00a0En la cosa de los animales que est\u00e1n ahi en plan halcones para evitar que torcaces las palomas y otros vuelen sobre territorio prohibido o en las cabinas de los aviones o buques de pasajeros las compa\u00f1\u00edas femeninas- que no\u00a0 s\u00e9 porque se han empe\u00f1ado en bautizarlas de malas- est\u00e1n prohibidas no sea que se precipiten al mar\u00a0 que \u00a0luego en las cajas negras se sabe casi todo.<\/strong><\/p>\n<p><strong>Honor y gloria al Gpr17. Ir\u00e9 a por su ingesta cuando haya acabado el roast beef en honor de la soberana inglesa que lo hago por los a\u00f1os que lleva arriba del carrito y por ver si cambia de atuendo y sombreros. Qu\u00e9 Ascot.<\/strong><\/p>\n<p><strong>Bien. Ahora voy a intentar el doble salto mortal inform\u00e1tico que supone a\u00f1adir una invitaci\u00f3n a que hagan el favor de venir a tomar cava conmigo el 21 de Junio a\u00a0las siete de la tarde en El Corte Ingl\u00e9s de Valencia-C\/Col\u00f3n en la 5\u00aa planta y ya una vez all\u00ed sentarse conmigo a ver que digo sobre la \u00faltima novela que acabo de publicar.Gracias por atenderme y m\u00e1s por venir, si es el caso y por la paciencia porque esto lo voy a repetir dos veces m\u00e1s.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Para confirmar que el receptor est\u00e1 implicado en el control del apetito, los investigadores inyectaron un activador de Gpr17 en ratones normales, aumentando su apetito. A la inversa, cuando a los ratones se les administr\u00f3 un inhibidor de Gpr17, su apetito disminuy\u00f3. \u00a0\u00a0 Seg\u00fan Accili, hay varias razones por las que Gpr17, que tambi\u00e9n se [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-1545","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts\/1545","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/comments?post=1545"}],"version-history":[{"count":0,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts\/1545\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/media?parent=1545"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/categories?post=1545"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/tags?post=1545"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}