{"id":1566,"date":"2012-06-28T07:54:59","date_gmt":"2012-06-28T07:54:59","guid":{"rendered":"http:\/\/blogs.lasprovincias.es\/carlospajuelo\/?p=1566"},"modified":"2012-06-28T07:54:59","modified_gmt":"2012-06-28T07:54:59","slug":"la-fobia","status":"publish","type":"post","link":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/2012\/06\/28\/la-fobia\/","title":{"rendered":"La fobia"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p><strong>LA FOBIA<\/strong><\/p>\n<p><strong>Hannah Matthews tiene koumpounophobia, es decir, siente p\u00e1nico cuando se<br \/>\ntopa con un bot\u00f3n y si los toca, el miedo se multiplica. S\u00f3lo puede llevar ropa<br \/>\ncon cremalleras.<\/strong><\/p>\n<p><strong>Por lo menos se puede abrochar el vestido.<\/strong><\/p>\n<p><strong>La palabra me encanta y eso que no la entiendo y me tengo que fijar para<br \/>\npoder pronunciarla. Recuerdo los ejercicios que hac\u00edamos algunos, de ni\u00f1os,<br \/>\npara ver que palabra era la m\u00e1s larga. Yo me acuerdo de alguna que luego creo<br \/>\nque no es la m\u00e1s larga. \u201cesternocleidomastoideo\u201d, ese m\u00fasculo.<\/strong><\/p>\n<p><strong>As\u00ed que Hannah dice:<\/strong><\/p>\n<p><strong>&#8220;Hay algo en la textura o en la forma de los botones que me apabulla. Mi madre siempre dice que<br \/>\ncuando era peque\u00f1a me asustaba que se acercara la hora de ir a la escuela.<br \/>\nGritaba y lloraba y cuando me hice mayor, empec\u00e9 a tener ataques de miedo cuando<br \/>\nse pon\u00eda ante m\u00ed la sola posibilidad de llevarlos puestos o tocarlos&#8221;,<br \/>\ndijo la chica.(fuente : Las provincias)<\/strong><\/p>\n<p><strong>Lo de la fobia lo entiendo.<\/strong><\/p>\n<p><strong>Eso de tener un miedointenso y desproporcionado ante objetos y situaciones determinados lo entiendo.<\/strong><\/p>\n<p><strong>He visto a muchos que recientemente se llevan la mano al pecho, a la altura del coraz\u00f3n, como queri\u00e9ndose<br \/>\nproteger cuando pasan frente a un banco, por ejemplo.<\/strong><\/p>\n<p><strong>Con eso, adem\u00e1s de dar pistas a quienes son amigos de lo ajeno, significan su acendrado temor a la<br \/>\ncosa misma de la banca.<\/strong><\/p>\n<p><strong>Otros huyen de las mujeres y hacen gestos y mantienen opiniones contrarias al bello y misterioso<br \/>\nsexo. No entiendo ni a unos ni a otras, pero estoy cerca de hacerlo.<\/strong><\/p>\n<p><strong>Hay gentes que han tomado miedo a la vida en general y se hacen construir habitaciones llamadas<br \/>\ndel \u201cp\u00e1nico\u201d e incluso se ruedan pel\u00edculas con el asunto.<\/strong><\/p>\n<p><strong>Hay que someterse a tratamientoy yo recomiendo unas pautas auto gestionadas (estamos en crisis).<\/strong><\/p>\n<p><strong>Por ejemplo. Usted quiere ver se\u00f1oras. Adem\u00e1s de ir a un gran almac\u00e9n o gran superficie y quedarse<br \/>\nmirando mucho \u201ca \u00a0la pasa\u201d frente a una buena cerveza con algo de picar puede usted, de vez en cuando, dirigirse a una<br \/>\nde las paseantes-compradoras de forma educada y preguntarle la hora o una direcci\u00f3n<br \/>\ny ah\u00ed pegar la hebra. No olvide el truco de un perrito, que es una cosa mona.<\/strong><\/p>\n<p><strong>En cuanto al p\u00e1nico bancario usted debe entrar en sucursales varias y preguntar si le conceden, por<br \/>\nejemplo, un cr\u00e9dito y cuando le digan las condiciones no salir corriendo, como<br \/>\nsi huyera usted en franca retirada, si no re\u00edrse y fingir un ataque de risa-<br \/>\ncuidado no se haga pipi encima sobre todo si tiene usted la pr\u00f3stata flojilla-<br \/>\nhasta medio caer semi extenuado sobre el mostrador del director, si est\u00e1 a mano,<br \/>\no sobre la interventora \u2013 esto es mejor porque las mujeres son las mujeres.<\/strong><\/p>\n<p><strong>Se me acaba elespacio. Seguir\u00e9. Buenos d\u00edas.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; LA FOBIA Hannah Matthews tiene koumpounophobia, es decir, siente p\u00e1nico cuando se topa con un bot\u00f3n y si los toca, el miedo se multiplica. S\u00f3lo puede llevar ropa con cremalleras. Por lo menos se puede abrochar el vestido. La palabra me encanta y eso que no la entiendo y me tengo que fijar para [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-1566","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts\/1566","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/comments?post=1566"}],"version-history":[{"count":0,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts\/1566\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/media?parent=1566"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/categories?post=1566"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/tags?post=1566"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}