{"id":1570,"date":"2012-07-01T14:48:42","date_gmt":"2012-07-01T14:48:42","guid":{"rendered":"http:\/\/blogs.lasprovincias.es\/carlospajuelo\/?p=1570"},"modified":"2012-07-01T14:48:42","modified_gmt":"2012-07-01T14:48:42","slug":"son-de-otro-mundo","status":"publish","type":"post","link":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/2012\/07\/01\/son-de-otro-mundo\/","title":{"rendered":"Son de otro mundo"},"content":{"rendered":"<p>Los duques m\u00e1s sus cuatro hijos, m\u00e1s el servicio, m\u00e1s la seguridad, que por cierto pagan todo los espa\u00f1oles, se instalaron en un hotel de superlujo en Las Vegas durante cuatro d\u00edas y con un coste total que supera los dieciocho mil euros.(fuente: vanitatis-paloma barrientos)<\/p>\n<p>El anta\u00f1o Undargar ( as\u00ed parece que era llamado por el Rey el ahora inonbrable yerno) se costea con dinero de usted y m\u00edo, de parte de los medicamentos que ahora pagar\u00e1n en parte. \u00bfEs la Justicia lenta? \u00bfEs la justicia humana y dem\u00f3cratica\u00a0 justa?<\/p>\n<p>Debe ser lo que digo en el titular. Son de otro mundo. Tambi\u00e9n son de otro mundo los que est\u00e1n hoy en Ibiza d\u00f3nde el novio de Naomi Campell se ha gastado 50 mil euros en 50 entradas. El ruso cuyo nombre no me s\u00e9, es multisupermillonetis y se ve que \u00a0&#8220;el pavo&#8221; le ha dicho a la &#8220;pava&#8221; la canci\u00f3n popular nuestra. &#8220;Echale guindas al pavo que yo se las echar\u00e9 a la pava&#8221;. Y ah\u00ed est\u00e1 echandole guindas a la Venus de color, de \u00e9bano ( no confundir con ebanista). \u00bfC\u00f3mo responder\u00e1 esta noche la de \u00e9bano? A lo mejor ni por esas.<\/p>\n<p>Ah\u00ed est\u00e1n oyendo a Elton Jhon y otros, mientras, la brisa del Ibiza crepuscular a\u00fan no se ti\u00f1e de la bruma y las cenizas de nuestro m\u00e1s reciente devastador incendio con su 50 mil hectareas, digo bien ,50 mil hectareas m\u00e1s que a lo mejor tiene ahora la Duqesa de Alba por seguir con otro mundo.<\/p>\n<p>Miles de habitantes que van de uno a otro lado lament\u00e1ndose de la p\u00e9rdida personal de casa y de la p\u00e9rdida colectiva de paisaje.<\/p>\n<p>El tango dice que 20 a\u00f1os no son nada y ser\u00e1 as\u00ed para la Naturaleza misma pero para el tiempo humano si son. Eso es lo que hab\u00eda tardado desde el \u00faltimo incendio que arras\u00f3 Millares hace eso, unos 20 a\u00f1os.<\/p>\n<p>Hoy no salgo de casa. El calor, las cenizas sobre la ciudad y la pena que me da y otras cosas me empujan a refugiarme en la Roja pronto. Veremos que nos dice el augur de turno. Yo adelanto. Si perdemos es que ese Del Bosque se ha equivocado y si ganamos hemoos ganado todos. !Que cosas! Buenas tardes. Rosas en el mar para los del otro mundo y cenizas en el monte para los del incendio.La vida<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los duques m\u00e1s sus cuatro hijos, m\u00e1s el servicio, m\u00e1s la seguridad, que por cierto pagan todo los espa\u00f1oles, se instalaron en un hotel de superlujo en Las Vegas durante cuatro d\u00edas y con un coste total que supera los dieciocho mil euros.(fuente: vanitatis-paloma barrientos) El anta\u00f1o Undargar ( as\u00ed parece que era llamado por [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-1570","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts\/1570","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/comments?post=1570"}],"version-history":[{"count":0,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts\/1570\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/media?parent=1570"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/categories?post=1570"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/tags?post=1570"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}