{"id":1591,"date":"2012-07-15T09:48:33","date_gmt":"2012-07-15T09:48:33","guid":{"rendered":"http:\/\/blogs.lasprovincias.es\/carlospajuelo\/?p=1591"},"modified":"2012-07-15T09:48:33","modified_gmt":"2012-07-15T09:48:33","slug":"vuelven-las-novenas-la-novena-no-es-un-botellonjovenes-descreidos-de-nueve-dias","status":"publish","type":"post","link":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/2012\/07\/15\/vuelven-las-novenas-la-novena-no-es-un-botellonjovenes-descreidos-de-nueve-dias\/","title":{"rendered":"\u00bfVuelven las novenas? La novena no es un botell\u00f3n,jovenes descreidos, de nueve d\u00edas"},"content":{"rendered":"<p>Hace tiempo las novenas estaban a la orden del d\u00eda. Las gentes piadosas y algunos acompa\u00f1antes del &#8220;por si acaso&#8221; ibamos a ver si el santo invocado nos daba un respiro, un algo de aire para cuando las cosa, los asuntos, ven\u00edan mal dados. \u00bfEs tiempo de renovar las novenas? \u00bfA que santos acogerse en esta hora de desconcierto y de Bolsa a la baja? \u00bfQui\u00e9n es el patr\u00f3n de la prima de riesgo? \u00bfSe sabe a quien hay que ir a rezar para que Rajoy se vaya unos d\u00edas de vacaciones y con \u00e9l su santa ni\u00f1a?.<\/p>\n<p>Imaginemos un s\u00e1bado despu\u00e9s del viernes de dolores del consejo de ministros ( lo pongo todo en minuscula porque estoy harto de mayusculizar a quien no lo merece) y ante la avalancha de proporciones ciclop\u00e9as que tienen los ajustes y perdida la batalla de las marchas negras, mediante la inflexibilidad de los presupuestos montorianos, solo nos queda acogernos al Ser Supremo ( no confundir con aquellas declaraciones del Buitre haciendo referencia a Florentino\u00a0 el hombre que presid\u00eda y preside ahora el Real Madrid y as\u00ed calificado antes de refinanciar su deuda de unos 1600 milllones de euros nada ) y a los numerosos santos que deben poblar el universo celeste, Se tratar\u00eda de escoger uno.<\/p>\n<p>Yo he seleciconado a San Expedito que es , al parecer el abogado de negocios dif\u00edciles, y casos urgentes y favorecedor de su pronta soluci\u00f3n. Ah\u00ed es nada. Tengo delante el librito y en la portada su imagen. Joven,gallardo y vestido de legionario romano ( no es moco de pavo esto , pero no se recomienda hacer la novena de esta guisa porque los Cuerpos de Seguridad del Estado- como dicen siempre los pol\u00edticos para no dejarse a nadie en el tintero- podr\u00edan intervenir y ya se sabe)En su mano izquierda una cuz con la palabra HOY (Hodie), la mano derecha se\u00f1ala al mir\u00f3n,a mi por ejemplo, cmo instandome a seguir su camino, Yo tengo miedo. \u00bfPor qu\u00e9 he morir a manos de interrogadores sin flexibilidad \u00e1vidos de persecuciones?<\/p>\n<p>\u00bfPor qu\u00e9 me persigues Mariano? ( lo digo en plan moderno). San Expedito- que lo sepas- aplasta con su pie a un cuervo,s\u00edmbolo de Satan\u00e1s tentado. Me da igual que no decaigas ante el justo Cayo el que anuncia, con voz de seguidor de Mao, el fin de tus tiempos. \u00bfTe vas de vacaiones,por cierto? \u00bfDo vas? \u00bfMorar\u00e1s cerca del Codice en eterna custodia? \u00bfHar\u00e1s ciclismo urbano saludando a paisanos que se enorgullecen de haber sido el \u00fanico que dio la cara con el asunto del Prestige? \u00bfDedicar\u00e1s un s\u00f3lido recuerdo a Trillo\u00a0 &#8220;viento del Este&#8221;en el aniversario de Perejil? Loa a los heroes, loa a todos, de paso.<\/p>\n<p>Yo har\u00e9 novenas sin fin. Una detr\u00e1s de otra para ver si cuaja la cosa y Merkel nos deja de tocar los santos huevos. \u00bfO no es Merkel la que espectacularmente me produce una orquitis que no est\u00e1 prevista en cr\u00f3nicos porque Mato me la ha quitado- los medicamentos no la orquitis que sigue?<\/p>\n<p>Bueno se acaba el espacio. Se acaba todo. Me han dicho que Internet est\u00e1 chungo. Me dar\u00e9 una ducha que es m\u00e1s barato que ir a la piscina&#8230;y luego he o\u00eddo que la gente ,algunos,hacen pip\u00ed alli. No somos nada. Buenos d\u00edas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hace tiempo las novenas estaban a la orden del d\u00eda. Las gentes piadosas y algunos acompa\u00f1antes del &#8220;por si acaso&#8221; ibamos a ver si el santo invocado nos daba un respiro, un algo de aire para cuando las cosa, los asuntos, ven\u00edan mal dados. \u00bfEs tiempo de renovar las novenas? \u00bfA que santos acogerse en [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-1591","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts\/1591","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/comments?post=1591"}],"version-history":[{"count":0,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts\/1591\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/media?parent=1591"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/categories?post=1591"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/tags?post=1591"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}