{"id":1592,"date":"2012-07-16T06:00:32","date_gmt":"2012-07-16T06:00:32","guid":{"rendered":"http:\/\/blogs.lasprovincias.es\/carlospajuelo\/?p=1592"},"modified":"2012-07-16T06:00:32","modified_gmt":"2012-07-16T06:00:32","slug":"1-500-asesores-para-madrid-y-183-coches-oficiales-que-fem","status":"publish","type":"post","link":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/2012\/07\/16\/1-500-asesores-para-madrid-y-183-coches-oficiales-que-fem\/","title":{"rendered":"1.500 asesores para Madrid y 183 coches oficiales \u00bfQu\u00e9 &#8220;fem&#8221;?"},"content":{"rendered":"<p>Cuando cont\u00e9, a modo de ejemplo, que la <strong>alcaldesa de Madrid<\/strong> y sus concejales tienen <strong>1.500 asesores<\/strong> con un sueldo medio de 47.000 euros y <strong>183 coches oficiales<\/strong> de uso personal, no me crey\u00f3. As\u00ed de simple. Tuve que pedirle que tecleara en Google \u201cAsesores ayuntamiento Madrid\u201d. Se qued\u00f3 boquiabierto. El alcalde de Washington, al igual que el de Nueva York, ni siquiera tiene coche oficial y va en metro cada d\u00eda a su trabajo. Cuando le expliqu\u00e9 que en Espa\u00f1a hay m\u00e1s de 30.000 coches oficiales, que <strong>desde 1978 se han contratado dos millones de empleados p\u00fablicos<\/strong> <em>a dedo<\/em>, entre amigos y correligionarios, que <strong>las CCAA tienen m\u00e1s de 200 embajadas en el extranjero<\/strong> o que disponen de casi 50 canales de TV con una p\u00e9rdida anual de 2.400 millones no se lo pod\u00eda creer.(fuente:el confidencial \/roberto centeno)<\/p>\n<p>Siento &#8220;pegar&#8221; un texto tan largo pero no sab\u00eda por donde cortar. Parece que no tiene uno demasiadas cosas que a\u00f1adir sin perder la calma. Ni los paises m\u00e1s ricos se atreven a ese despilfarro p\u00fablico y nadie se atreve a subir a una tribuna para defender un modelo, me refiero al de las autonom\u00edas, que ha omodio el terreno a la honestidad y al oncepto del dinero como fuente que hay que respetar.<\/p>\n<p>Yo creo que har\u00eda falta un examen , en \u00faltimo caso, que contuviera adem\u00e1s de la aptitud para el desempe\u00f1o del cargo que sea, un test de actitud relacionada con la caja com\u00fan. El dinero del Estado y el que recaudan &#8220;motu propio&#8221; es de todos y el Estado,la autonom\u00eda,la diputaci\u00f3n o el municipio no son entes independientes que se nutren de un man\u00e1 ca\u00eddo del cielo en una temporada de nubes o lluvia.<\/p>\n<p>Alguien aqu\u00ed tiene que cambiar y no debe ser a costa de mandar a la medio miseria o a la miseria entera a millones de espa\u00f1oles. \u00bfNo cabe otra soluci\u00f3n? \u00bfEs la m\u00e1s sencilla? \u00bfPasa algo con desmontar al m\u00e1ximo las autonom\u00edas? Es que hay que cambiar la Constituci\u00f3n. Cambienla.<\/p>\n<p>Hoy ha amanecido medio nublado y un poco de lluvia alegrar\u00eda , al tiempo de refrescar,el ambiente que aparece estos di\u00edas con un exceso de carga el\u00e9ctrica.Anoche eran m\u00e1s los que se disputaban el resto de enseres y comoida de los contenedores y el n\u00famero de perosnas que usan a lso ni\u00f1os como excusa, o no, para pedir era mayor.<\/p>\n<p>Es que ha ganado la &#8220;rojilla&#8221; el campeonato de Europa de futbol y es que Nadal llevar\u00e1 la bandera en los Ol\u00edmpicos. Y a mi , con la que est\u00e1 cayendo, que co\u00f1o me importa. Resuelvan primero el pago parcial de las medicinas a los que tienen una pensi\u00f3n no contributiva y luego ya mandaremos un texto de enhorabuena y ya tendremos tiempo de dar homenajes, Pobre de mi. La fiesta se ha acabado pero ya hace mucho tiempo. Ahora toca encerrar a los toros del desaliento y a los &#8220;merendones&#8221; que no dejan a nadie vivo. A pasarlo bien. Y a las que han roto aguas una hora cortita, y a sus mam\u00e1s serenidad, Traer al mundo espa\u00f1oles hoy es una heroicidad conjunta.Buenos d\u00edas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cuando cont\u00e9, a modo de ejemplo, que la alcaldesa de Madrid y sus concejales tienen 1.500 asesores con un sueldo medio de 47.000 euros y 183 coches oficiales de uso personal, no me crey\u00f3. As\u00ed de simple. Tuve que pedirle que tecleara en Google \u201cAsesores ayuntamiento Madrid\u201d. Se qued\u00f3 boquiabierto. El alcalde de Washington, al [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-1592","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts\/1592","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/comments?post=1592"}],"version-history":[{"count":0,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts\/1592\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/media?parent=1592"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/categories?post=1592"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/tags?post=1592"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}