{"id":1607,"date":"2012-07-29T07:07:14","date_gmt":"2012-07-29T07:07:14","guid":{"rendered":"http:\/\/blogs.lasprovincias.es\/carlospajuelo\/?p=1607"},"modified":"2012-07-29T07:07:14","modified_gmt":"2012-07-29T07:07:14","slug":"llegan-a-marte-han-llegado-de-verdad-a-la-luna-es-la-duda-permanente","status":"publish","type":"post","link":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/2012\/07\/29\/llegan-a-marte-han-llegado-de-verdad-a-la-luna-es-la-duda-permanente\/","title":{"rendered":"Llegan a Marte \u00bfHan llegado de verdad a la Luna? Es la duda permanente"},"content":{"rendered":"<p>Marte<\/p>\n<p>Parece que pronto \u2013en Agosto- pondremos otro veh\u00edculo en Marte. Yo me asombro aunque, si quieren ustedes la verdad, yo me asombro ahora casi por todo y eso me permite estar ojipl\u00e1tico todo el d\u00eda, tanto que algunos me han dicho que vaya a ver a un neur\u00f3logo. Yo digo que si, que voy a ir e incluso a alguno le he dicho que he ido dada su contumacia.<\/p>\n<p>En realidad me he ido a la playa antes de que la quiten o hagan pagar por entrar (hace a\u00f1os pague en Yugoslavia por entrar a la playa y nunca supe si es que hab\u00eda que pagar o es que me vieron la cara de \u201cguiri\u201d) Hay mucha gente en la playa. Van de la cola del paro a la playa y de all\u00ed, m\u00e1s calentitos, a la cola del paro. Estamos en el 24 y pico pero no pasa \u201cn\u00e1\u201d. Se ralentizan en verano las manifas. Ya volver\u00e1n como las oscuras golondrinas.<\/p>\n<p>Lo de Marte es una de esas cosas que luego hay muchos que dudan, como en el caso de La Luna-est\u00e1 esta, por cierto, de un cuarto creciente hermoso aqu\u00ed; digo aqu\u00ed por lo de los cielos claros.<\/p>\n<p>El Curiosyty es el nombre dado al veh\u00edculo que tiene sobre si m\u00e1s de 2.000 millones de euros para llegar y todo para ver si ha habido vida o no<\/p>\n<p>\u00bfSer\u00e1 por la cosa de los minerales? Yo gusto de la ciencia ficci\u00f3n y enseguida o sea dentro de 300 a\u00f1os veo unas idas y venidas llenas de minerales de Marte ida y vuelta y todo tan lleno como, dicen, que \u00a0van, estos d\u00edas ol\u00edmpicos, los vagones de metro en Londres. Es un Big Ben total.<\/p>\n<p>He le\u00eddo que hay emergencia en el Gobierno y que estar\u00e1n por aqu\u00ed, prestos a acudir a la llamada, en Agosto lo que me da mal de ojo.<\/p>\n<p>Yo cre\u00eda que nos iban a dejar tranquis y que los recortes se los iban hacer ellos en salva sea la parte y que ense\u00f1ar\u00edan sus verg\u00fcenzas en sus lugares de origen en ambientes luxury rodeados de sus asesores que son muchos.<\/p>\n<p>Hay un concejal- no me hagan caso si en vez de Asturias es en otra parte del pa\u00eds son tan parecidos- me refiero a los concejales- que tiene 6 y el t\u00edo est\u00e1 tan tranquilo. Uno para cada d\u00eda laborable de la semana y uno de refuerzo. Eso es un concejal y lo dem\u00e1s son mariconadas.<\/p>\n<p>Vuelvo a lo de Marte.<\/p>\n<p>No es nada f\u00e1cil el descenso a la superficie de otro mundo. La NASA lo ha logrado con \u00e9xito en seis ocasiones, pero la estrategia de aterrizaje del <em>Curiosity<\/em> es nueva, nunca se ha intentado antes.(fuente: el pa\u00eds)<\/p>\n<p>Estos de la NASA no se enteran. Que hablen con Ana Mato-la ministra de Sanidad-que dice que han descubierto que hay m\u00e1s de 150 mil SIPS- los de la tarjeta que teniendo que estar m\u00e1s muerto que \u201cCarracuca\u201d (nunca he sabido quien es) \u00a0est\u00e1n m\u00e1s que vivos . O sea que es dif\u00edcil el descenso al inframundo, ni siquiera siendo minero.<\/p>\n<p>No s\u00e9. No me creo nada. Sigo ojipl\u00e1tico. Hoy ver\u00e9 a los chinos jugar contra los nuestros a baloncesto. \u00bfPor qu\u00e9 diremos los nuestros y m\u00e1s si ganan y ellos si pierden? El lenguaje emocional es un misterio. Adieu. Buenos d\u00edas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Marte Parece que pronto \u2013en Agosto- pondremos otro veh\u00edculo en Marte. Yo me asombro aunque, si quieren ustedes la verdad, yo me asombro ahora casi por todo y eso me permite estar ojipl\u00e1tico todo el d\u00eda, tanto que algunos me han dicho que vaya a ver a un neur\u00f3logo. Yo digo que si, que voy [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-1607","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts\/1607","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/comments?post=1607"}],"version-history":[{"count":0,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts\/1607\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/media?parent=1607"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/categories?post=1607"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/tags?post=1607"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}