{"id":1621,"date":"2012-08-15T07:20:29","date_gmt":"2012-08-15T07:20:29","guid":{"rendered":"http:\/\/blogs.lasprovincias.es\/carlospajuelo\/?p=1621"},"modified":"2012-08-15T07:20:29","modified_gmt":"2012-08-15T07:20:29","slug":"que-hace-usted-con-el-dedo-nombrar-cargos-los-dedos-son-multiuso","status":"publish","type":"post","link":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/2012\/08\/15\/que-hace-usted-con-el-dedo-nombrar-cargos-los-dedos-son-multiuso\/","title":{"rendered":"\u00bfQue hace usted con el dedo? \u00bfNombrar cargos? Los dedos son multiuso"},"content":{"rendered":"<p>Cuidado con el dedo<\/p>\n<p>Boonsong Kowawisarat, de 56 a\u00f1os, cenaba con una ametralladora Uzi encima de la mesa, pero afirma que no quer\u00eda disparar.(fuente: La gaceta)<\/p>\n<p>El senador tailand\u00e9s (era un senador) dispar\u00f3 contra su secretaria y la pobre ha muerto en el hospital.<\/p>\n<p>Si no fuera el resultado tan tr\u00e1gico, me gustar\u00eda poner \u00e9nfasis en el hecho de ir a comer o cenar con una UZI y que conste que conozco la escalada de precios a la que nos est\u00e1 sometiendo el sector y tambi\u00e9n conozco que la calidad y el precio no siempre\u00a0 van unidos y s\u00e9, me lo han dicho, que los motivos de amores frustrados llevan a un exceso de celo.<\/p>\n<p>No justifica nada de todo lo anterior el cenar con una ametralladora como compa\u00f1\u00eda.<\/p>\n<p>Ya ha pasado el tiempo \u2013muy lejano tanto, que fue reci\u00e9n terminada la guerra( cualquier guerra) en la que algunos, se dice, vestidos de uniforme se examinaban de cualquier oposici\u00f3n con la pistola al cinto o encima de la mesa.<\/p>\n<p>\u00bfTendr\u00edan miedo los del tribunal? \u00bfMiedo al dedo?<\/p>\n<p>Ahora lo del dedo ha tomado forma de designaci\u00f3n sin violencia. Basta pertenecer a un partido vencido o vencedor, para que te arreglen \u201cel saquito\u201d y te nombren y por eso a lo mejor Rubio- aqu\u00ed en Valencia- ha pedido se diga quienes y cuantos han sido contratados \u201ca dedo\u201d, si oposici\u00f3n, ni pistolas.<\/p>\n<p>Imagino que Rubio amigo de sus amigos, honesto pol\u00edtico no se limitar\u00e1 a una sola parte de la orilla y explorar\u00e1 ambas orillas del caudaloso r\u00edo de los contratados a \u201da dedo\u201d.<\/p>\n<p>El dedo ha sido siempre m\u00e1gico para mi. Desde el dedo romano del emperador de turno que daba o quitaba la vida a los gladiadores, como el dedo acusador de los testigos de cargo en juicios paralelos o el dedo que sirve para quitarse los mocos de la nariz que siendo guarro el asunto, es menos guarro que todo lo anterior \u00bfNo?.<\/p>\n<p>Uno me dice que no es el mismo dedo. Se ve que es el \u00edndice el que sirve para se\u00f1alar, nombrar, acusar etc. y el otro es el me\u00f1ique, un dedo \u00edntimo, como si dij\u00e9ramos.<\/p>\n<p>Jugar con el dedo puede tener malas consecuencias, aunque siempre recordar\u00e9 que Hopkings se escap\u00f3 con su enfermera y eso que solo pod\u00eda usar un dedo.<\/p>\n<p>La mente brillante del hombre que puso en tela de juicio la teor\u00eda de la relatividad de Einstein reivindic\u00f3 el dedo para la Humanidad\u00a0 y si no fue as\u00ed al menos para mi fue objeto de asombro.<\/p>\n<p>Me voy con el dedo a otra parte pero antes les deseo buenos d\u00edas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cuidado con el dedo Boonsong Kowawisarat, de 56 a\u00f1os, cenaba con una ametralladora Uzi encima de la mesa, pero afirma que no quer\u00eda disparar.(fuente: La gaceta) El senador tailand\u00e9s (era un senador) dispar\u00f3 contra su secretaria y la pobre ha muerto en el hospital. Si no fuera el resultado tan tr\u00e1gico, me gustar\u00eda poner \u00e9nfasis [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-1621","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts\/1621","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/comments?post=1621"}],"version-history":[{"count":0,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts\/1621\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/media?parent=1621"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/categories?post=1621"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/tags?post=1621"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}