{"id":1632,"date":"2012-08-28T06:27:18","date_gmt":"2012-08-28T06:27:18","guid":{"rendered":"http:\/\/blogs.lasprovincias.es\/carlospajuelo\/?p=1632"},"modified":"2012-08-28T06:27:18","modified_gmt":"2012-08-28T06:27:18","slug":"ustedes-se-preocupan-mucho-de-lo-material-rajoy-dixit","status":"publish","type":"post","link":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/2012\/08\/28\/ustedes-se-preocupan-mucho-de-lo-material-rajoy-dixit\/","title":{"rendered":"Ustedes se preocupan mucho de lo material (Rajoy dixit)"},"content":{"rendered":"<p>La Chispa<\/p>\n<p>Lo material<\/p>\n<p>Carlos Pajuelo de Arcos<\/p>\n<p>Hace unos d\u00edas el presidente Rajoy, de vacaciones en el Sur, \u00a0planteaba la necesidad de pensar menos en lo material y m\u00e1s en lo espiritual.<\/p>\n<p>Pensamiento elevado. Es imprescindible resituarlo, al pensamiento, porque a \u00e9l ya lo resituaran, si fuera el caso.<\/p>\n<p>Estaba en conocer \u00a0a Do\u00f1ana que es Patrimonio de los espa\u00f1oles y de uso restringido, tanto que , al parecer, dispone de un resort para Presidentes en acto de servicio; servicio en vacaciones, porque \u00a0se sabe que un Presidente e incluso un pol\u00edtico de infanter\u00eda \u00a0est\u00e1 24 horas ,d\u00eda y noche ( en plan lucecita que nunca se apagaba en El Pardo) pensando y sirviendo.<\/p>\n<p>Al ser mitad monje, mitad soldado, como un miembro m\u00e1s de la honorable familia templaria, hab\u00eda que dedicar, dar un toque, al alma hispana. Eso justifica que se apele a lo espiritual como valor que conviene hacer crecer.<\/p>\n<p>Se supone que cuando llaman a la puerta para desahuciarte, digo, o cuando contemplas con frialdad la escasez de alimentos en la nevera, cuando haces n\u00fameros para calcular el coste de libros, colegios etc. tu debes asumir que eso es pura materia o en todo caso ofrecer ese sacrificio A.M.D ( ad major gloriam Dei)<\/p>\n<p>La espada flam\u00edgera de la conciencia del Presidente, que lo hace todo por salvar a Espa\u00f1a de una cat\u00e1strofe, llenar\u00e1 de orgullo a su entorno y mientras contempla ,digo, las esforzadas maniobras de los atletas en Ol\u00edmpicos Juegos, muchos se pierden en el asqueroso lodo de lo material.<\/p>\n<p>Hermanos: falta sacrificio. Esos pobres bancarios que tienen limitado a un miserable sueldo de 500.000.- euros (euro arriba, euro abajo) sufren en sus carnes la mordedura de lo material.<\/p>\n<p>Entretanto los enga\u00f1ados por las preferentes deben ir a los bancos duros de las iglesias para rezar, porque sus derechos de enga\u00f1ados sean repuestos y encender velas.<\/p>\n<p>Aquellos que flaqueen en su devoci\u00f3n espiritual deben fustigarse con el cilicio de un Conde que vuelve. Mario est\u00e1 aqu\u00ed. Honor y gloria a un pa\u00eds que permite que la democracia albergue bajo su paraguas generoso a etarras en tercer grado y\u00a0 a Houdinis bancarios.<\/p>\n<p>\u00bfSi eso no es espiritual, Presidente, dime que lo es? Buenos d\u00edas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Chispa Lo material Carlos Pajuelo de Arcos Hace unos d\u00edas el presidente Rajoy, de vacaciones en el Sur, \u00a0planteaba la necesidad de pensar menos en lo material y m\u00e1s en lo espiritual. Pensamiento elevado. Es imprescindible resituarlo, al pensamiento, porque a \u00e9l ya lo resituaran, si fuera el caso. Estaba en conocer \u00a0a Do\u00f1ana [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-1632","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts\/1632","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/comments?post=1632"}],"version-history":[{"count":0,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts\/1632\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/media?parent=1632"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/categories?post=1632"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/tags?post=1632"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}