{"id":1634,"date":"2012-09-02T09:07:15","date_gmt":"2012-09-02T09:07:15","guid":{"rendered":"http:\/\/blogs.lasprovincias.es\/carlospajuelo\/?p=1634"},"modified":"2012-09-02T09:07:15","modified_gmt":"2012-09-02T09:07:15","slug":"usteddigaha-sido-disuelto-alguna-vez","status":"publish","type":"post","link":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/2012\/09\/02\/usteddigaha-sido-disuelto-alguna-vez\/","title":{"rendered":"\u00bfUsted,diga,ha sido disuelto alguna vez?"},"content":{"rendered":"<p>Disolver<\/p>\n<p>Esta noche he pensado- es buena hora para hacer balance- que pronto el verbo que da t\u00edtulo a esta columna se pondr\u00e1 de moda. \u00bfPor qu\u00e9?<\/p>\n<p>Repase usted conmigo, si hace el favor. Las \u00faltimas manifestaciones celebradas en el pa\u00eds- quiero decir en Espa\u00f1a- en los \u00faltimos 7 meses (no cuento Agosto porque manifestantes y vigilantes de la manifestaci\u00f3n descansan y toman fuerzas en las cuevas personales de cada uno, en los pueblos a los que volver un poco menos ricos que otros a\u00f1os, a las playas con la nevera port\u00e1til reinventada e incluso recluidos en sus casa urbanas esperando, en camiseta sin mangas, la hora de disolver o disolverse que es diferente).<\/p>\n<p>Conviene estar preparado, me digo, y en ese sentido he decidido estos d\u00edas disolverme un poquito. He pasado unos d\u00edas en plan huelga ca\u00edda de ordenador- antes m\u00e1quina de escribir- y no he escrito nada- con gran alegr\u00eda, supongo, de los sufridos lectores o lo que es mucho peor con la m\u00e1s absoluta indiferencia de los otros. (Ah\u00ed le duele, le duele la indiferencia).<\/p>\n<p>Como no soy un vampiro- seg\u00fan las leyendas los vampiros no se ven reflejados en los espejos- me he mirado en el \u00a0espejo del armario ropero y es evidente que no soy un vampiro porque mi imagen est\u00e1 ah\u00ed- fuera del armario \u2013 y de cuerpo presente\u00a0 reflejado. No me disuelvo por mucho que lo intente y eso que hago movimientos r\u00e1pidos, como de exhalaci\u00f3n ,pero est\u00e1 claro que no me hurto a mi mismo.<\/p>\n<p>Antes de que me disuelvan tengo alternativas. Primero no voy a manifestaci\u00f3n alguna y ya est\u00e1\u2026pero luego , cuando lo veo en la tele-me entra un cierto sentido de culpa y me digo que ir\u00e9 a la pr\u00f3xima. Como estoy un poco \u00a0gag\u00e1 me tomar\u00e9 Mentis para la memoria, no sea que se me vaya a \u00a0olvidar o equivocarme de fecha que ya me ha pasado.<\/p>\n<p>Me he comprado unas zapatillas multiuso. Para correr delante de los que antes eran grises y ahora no s\u00e9 de que color van vestidos, con tanta protecci\u00f3n no se ve. Me he entrenado y creo que no sirvo ya para correr porque tiro el bofe a las 50 metros 50,<\/p>\n<p>Lo siento. Seguir\u00e9 escribiendo. Buenos d\u00edas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Disolver Esta noche he pensado- es buena hora para hacer balance- que pronto el verbo que da t\u00edtulo a esta columna se pondr\u00e1 de moda. \u00bfPor qu\u00e9? Repase usted conmigo, si hace el favor. Las \u00faltimas manifestaciones celebradas en el pa\u00eds- quiero decir en Espa\u00f1a- en los \u00faltimos 7 meses (no cuento Agosto porque manifestantes [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-1634","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts\/1634","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/comments?post=1634"}],"version-history":[{"count":0,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts\/1634\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/media?parent=1634"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/categories?post=1634"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/tags?post=1634"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}