{"id":1651,"date":"2012-09-18T05:55:14","date_gmt":"2012-09-18T05:55:14","guid":{"rendered":"http:\/\/blogs.lasprovincias.es\/carlospajuelo\/?p=1651"},"modified":"2012-09-18T05:55:14","modified_gmt":"2012-09-18T05:55:14","slug":"cataluna-le-fatiga","status":"publish","type":"post","link":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/2012\/09\/18\/cataluna-le-fatiga\/","title":{"rendered":"\u00bfCatalu\u00f1a le fatiga?"},"content":{"rendered":"<p>La Chispa<\/p>\n<p>La fatiga<\/p>\n<p>Carlos Pajuelo de Arcos<\/p>\n<p>Tensa la cuerda \u201cel noi\u201d Mas. Mire usted por donde creo que le asiste la raz\u00f3n. La fatiga es una sensaci\u00f3n sostenida que abruma y que nubla el pensamiento hasta distorsionarlo. \u00bfNo comen bien los catalanes? \u00bfNo duermen bien? \u00bfTrabajan bajo un stress\u2026los que trabajan? Hay que investigar el discurso del \u201cnoi\u201d. Es una necesidad higi\u00e9nica de contenidos. \u00bfQu\u00e9 \u201cvol\u201d \u201cel noi\u201d?<\/p>\n<p>Est\u00e1 la fatiga respiratoria que se da en el caso de que cada vez que ve una bandera \u201cnacional\u201d o sea constitucional, o sea de Espa\u00f1a, a Mas se le corte el resuello y entre en ca\u00edda libre pulmonar.<\/p>\n<p>Yo no intento comprender, razonar \u00a0este problema obsesivo compulsivo. Cada vez que me falta dinero, digo que dir\u00e1, mira la bandera y encuentra una raz\u00f3n para justificar la cosa del apretamiento colectivo. Espa\u00f1a tiene la culpa.<\/p>\n<p>Supongo que \u00a0dir\u00e1: \u201cme duele Catalu\u00f1a\u201d y tendr\u00e1 una erecci\u00f3n en su sue\u00f1o europe\u00edsta y se ver\u00e1 recibido con honores de Jefe de Estado all\u00ed, a las puertas \u00a0del Eliseo (me gusta mucho Francia y est\u00e1 m\u00e1s cerca que Washington o la vieja Pek\u00edn)<\/p>\n<p>Luego viene la variante \u201cfatiga mental\u201d. Afecta a la memoria colectiva y a la individual y que puede darse como consecuencia de mirarse el ombligo todo el d\u00eda y que a fuerza de mir\u00e1rselo parece \u00b4\u00b4\u00fanico\u201d y sobre todo indivisible. Se ha pasado su ciulegislatura sugiriendo que se miren el ombligo y ha sabido reunir un mill\u00f3n de ombligos que ya son y que por tanto hay que tener en cuenta.<\/p>\n<p>De todas estas posibles fatigas se ha podido decantar una fatiga moral. Conviene que se confiese ante el \u00a0tribunal merkeliano y diga si ha sido o no culpable y que entone el \u201cyo me acuso\u201d;le gustar\u00eda, a lo mejor, el nuestro, el Tribunal de las Aguas pero ese es m\u00e1s peligroso. Es r\u00e1pido, contundente y en el \u201ccalle vost\u00e9 y parle vost\u00e9\u201d la fatiga no cuenta. Cuenta el que ha robado agua indebidamente. \u00bfEs caso del \u201cnoi\u201d de Les Rambles? \u00bfEs el caso=<\/p>\n<p>Yo tambi\u00e9n estoy fatigado. No del \u201cnoi\u201d solo sino que estoy hasta las pelo\u2026de tanto quejica, de tanto rescate y de tanto ajuste. \u00a1Faltan \u201csegadors\u201d!. Bon d\u00eda.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Chispa La fatiga Carlos Pajuelo de Arcos Tensa la cuerda \u201cel noi\u201d Mas. Mire usted por donde creo que le asiste la raz\u00f3n. La fatiga es una sensaci\u00f3n sostenida que abruma y que nubla el pensamiento hasta distorsionarlo. \u00bfNo comen bien los catalanes? \u00bfNo duermen bien? \u00bfTrabajan bajo un stress\u2026los que trabajan? Hay que [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-1651","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts\/1651","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/comments?post=1651"}],"version-history":[{"count":0,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts\/1651\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/media?parent=1651"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/categories?post=1651"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/tags?post=1651"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}