{"id":1676,"date":"2012-10-09T05:57:29","date_gmt":"2012-10-09T05:57:29","guid":{"rendered":"http:\/\/blogs.lasprovincias.es\/carlospajuelo\/?p=1676"},"modified":"2012-10-09T05:57:29","modified_gmt":"2012-10-09T05:57:29","slug":"cosa-de-huevos-esa-es-la-cuestion","status":"publish","type":"post","link":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/2012\/10\/09\/cosa-de-huevos-esa-es-la-cuestion\/","title":{"rendered":"Cosa de huevos.Esa es la cuesti\u00f3n"},"content":{"rendered":"<p>Cuesti\u00f3n de huevos<\/p>\n<p>Investigadores de Mind Lab Internacional afirman haber descubierto esta relaci\u00f3n estad\u00edstica despu\u00e9s de entrevistar a 1010 adultos en todo el Reino Unido, con preguntas sobre sus preferencias sobre c\u00f3mo tomar los huevos y aspectos de su estilo de vida, informa <a href=\"http:\/\/www.digitalspy.co.uk\/odd\/news\/a409808\/eggs-can-reveal-your-personality-type.html\" target=\"_blank\" rel=\"external nofollow\">Digital Spy.<\/a>(Fuente Informativos Tele5)<\/p>\n<p>Lo de la relaci\u00f3n estad\u00edstica es que han \u201ccogido\u201d a 1010 o algo as\u00ed \u201chueveros\u201d y los han hecho consumir huevos de diversa forma y tama\u00f1o,<\/p>\n<p>Una vez, digo yo, hartos de tanto huevo les habr\u00e1n preguntado 4 cosas acerca de si fritos, escalfados, en tortilla, cocidos y se han liado a sacar conclusiones.<\/p>\n<p>\u00bfUsted no cree en esas investigaciones? Me pregunta mi otro yo cr\u00edtico. No mucho. Eso de las muestras y las preguntas nos lleva a sacar conclusiones que luego se transforman en criterios para quienes han hecho las preguntas, a elaborar conclusiones y a significar teor\u00edas que pueden llevar a tendencias y al final los 1010 encuestados hueveros nos hacen afirmar en reuniones que si los huevos esto o lo otro.<\/p>\n<p>Por ejemplo, dicen (sigo con los huevos del Consejo) que si las mujeres los prefieren cocidos y que eso significa que son tendentes al desorden. Bobadas. Yo creo que los quieren cocidos porque los ponen en agua, los dejas ah\u00ed y si te he visto no me acuerdo.<\/p>\n<p>Luego est\u00e1n los fritos que por lo visto es cosa de hombres y significa deseo sexual ya experimentado (el hombre, no el deseo). Otra bobada. Yo creo que la cosa es que coges los huevos, los tiras a la sart\u00e9n y ya est\u00e1 .Un poco aqu\u00ed te pillo aqu\u00ed te mato. No s\u00e9.<\/p>\n<p>Lo que est\u00e1 claro es que cada d\u00eda nos inventan una cosa nueva y el llamado British Council Egg , una especie de Consejo Brit\u00e1nico del Huevo, (que yo no s\u00e9 si aqu\u00ed tenemos algo parecido, aunque ya s\u00e9 que tenemos de \u201ct\u00f3\u201d) funciona como lo de los asesores aqu\u00ed. Hablan con cuatro y enseguida dicen que quieren ser independientes.<\/p>\n<p>Las encuestas tienen un valor relativo y cuanta menos gente consultas m\u00e1s relativo es el asunto. Es cuesti\u00f3n de huevos.<\/p>\n<p>Luego est\u00e1n los mentideros. Qu\u00e9 si Rita ha perdido peso, que si Fabra est\u00e1 d\u00e9bil, \u00a1Bah! Buenos d\u00edas.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cuesti\u00f3n de huevos Investigadores de Mind Lab Internacional afirman haber descubierto esta relaci\u00f3n estad\u00edstica despu\u00e9s de entrevistar a 1010 adultos en todo el Reino Unido, con preguntas sobre sus preferencias sobre c\u00f3mo tomar los huevos y aspectos de su estilo de vida, informa Digital Spy.(Fuente Informativos Tele5) Lo de la relaci\u00f3n estad\u00edstica es que han [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-1676","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts\/1676","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/comments?post=1676"}],"version-history":[{"count":0,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts\/1676\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/media?parent=1676"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/categories?post=1676"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/tags?post=1676"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}