{"id":1692,"date":"2012-10-21T08:44:52","date_gmt":"2012-10-21T08:44:52","guid":{"rendered":"http:\/\/blogs.lasprovincias.es\/carlospajuelo\/?p=1692"},"modified":"2012-10-21T08:44:52","modified_gmt":"2012-10-21T08:44:52","slug":"se-siente-arrogante-hagaselo-mirar","status":"publish","type":"post","link":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/2012\/10\/21\/se-siente-arrogante-hagaselo-mirar\/","title":{"rendered":"\u00bfSe siente arrogante? Hagaselo mirar"},"content":{"rendered":"<p>El arrogante<\/p>\n<p>Se da el caso que hoy me he levantado un poco m\u00e1s tarde y estoy contento porque he dormido un poco m\u00e1s- la pastilla que \u00a0tomo hace a\u00f1os se ve que empieza a hacer efecto. No s\u00e9 que hacer si ir a la media marat\u00f3n que se celebra en Valencia con final en la Marina Juan Carlos y de paso ver el azul del mar, o\u00edr el uuu de las sirenas graves de los transatl\u00e1nticos que escalan el aire con su m\u00faltiples cubiertas o los esqueletos de las gr\u00faas con se\u00f1ales de verde n sus arcos sustentadores,<\/p>\n<p>Como hoy estoy solo me siento arrogante como contrapartida y me digo a mi mismo Vete a hacer surf, por ejemplo,<\/p>\n<p>Lo digo porque en la Marina, al lado en Las Arenas, junto a la peque\u00f1a escollera, un grupo min\u00fasculo de aspirantes a surfistas,vestidos de neopreno al estilo California, lo digo porque lo he visto en las pel\u00edculas que nos han pasado de la zona, y con pocas \u201cvigilantes de la playa\u201d- esperan pacientes como budistas \u00a0a que una ola de un metro llegue y entretanto saludan a sus admiradores, familiares que desde arriba, junto al local de nombre latitud marina 39\u00ba 27, los admiran<\/p>\n<p>De repente siento un dolor en la vejiga , conforme bajas a la izquierda, y me doy cuenta de \u00a0que no me acuerdo y ni siquiera s\u00e9 si puedo correr y me doy cuenta de que no tengo traje de neopreno y que aguanto algo en el agua a condici\u00f3n de que sea \u201cpa tras\u201d y que no haya oleaje. No soy nada. Ni surf, ni media, ni cuarta, marat\u00f3n.<\/p>\n<p>\u00bfEntonces? Siempre me quedan los libros y adem\u00e1s como he quedado con mi editor ma\u00f1ana pensar\u00e9 que le digo a ver si promocionamos m\u00e1s.<\/p>\n<p>Continuo arrogante pero menos. Ese dolorcito me marca el d\u00eda un poco. \u00bfTengo faja? Faja de deportista que es como las otras pero en color negro. Me tomar\u00e9 un algo. Un ibiprofeno- todo el mundo se lo toma y suele estar medio vivo. A lo mejor una hierba.<\/p>\n<p>Como me siento un poco chulo me castigo haciendo m\u00e1s corta la columna para descanso de mis lectores. Seguir\u00e9 informando.<\/p>\n<p>Yo me he tomado esto de las columnas como un reportero de guerra, de guerra contra m\u00ed mismo. Es menos peligroso para m\u00ed y m\u00e1s barato para el editor. Buenos d\u00edas<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El arrogante Se da el caso que hoy me he levantado un poco m\u00e1s tarde y estoy contento porque he dormido un poco m\u00e1s- la pastilla que \u00a0tomo hace a\u00f1os se ve que empieza a hacer efecto. No s\u00e9 que hacer si ir a la media marat\u00f3n que se celebra en Valencia con final en [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-1692","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts\/1692","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/comments?post=1692"}],"version-history":[{"count":0,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts\/1692\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/media?parent=1692"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/categories?post=1692"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/tags?post=1692"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}