{"id":1693,"date":"2012-10-22T06:37:08","date_gmt":"2012-10-22T06:37:08","guid":{"rendered":"http:\/\/blogs.lasprovincias.es\/carlospajuelo\/?p=1693"},"modified":"2012-10-22T06:37:08","modified_gmt":"2012-10-22T06:37:08","slug":"sorteo-trabajo-temporal","status":"publish","type":"post","link":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/2012\/10\/22\/sorteo-trabajo-temporal\/","title":{"rendered":"Sorteo trabajo temporal"},"content":{"rendered":"<p>El trabajo a sorteo<\/p>\n<p>La cadena de zapater\u00edas &#8216;<a href=\"https:\/\/maps.google.es\/maps?q=Calle+Evora,+15,+Jerez+de+la+Frontera&#038;hl=es&#038;ie=UTF8&#038;sll=40.524724,-3.816153&#038;sspn=3.603094,4.938354&#038;oq=evora,+15,+jerez&#038;hnear=Calle+Evora,+15,+11402+Jerez+de+la+Frontera,+C%C3%A1diz,+Andaluc%C3%ADa&#038;t=m&#038;z=17\" target=\"_blank\" rel=\"external nofollow\">Calzados Loremar<\/a>&#8216; ha iniciado esta semana una particular campa\u00f1a de promoci\u00f3n para incentivar las compras entre los ciudadanos de Jerez de la Frontera. Bajo el formato de un sorteo entre los clientes, la cadena ha organizado <strong>una particular loter\u00eda en la que el \u2018premio gordo&#8217; son tres contratos laborales(fuente: p\u00fablico)<\/strong><\/p>\n<p><strong>La Constituci\u00f3n tan usada estos d\u00edas como base argumentativa contempla el derecho al trabajo. Ahora lo sortean.<\/strong><\/p>\n<p><strong>El \u201cavispado\u201d comerciante ha visto que lo que falta es trabajo y \u00e9l ha pensado: Yo puedo ofrecer en mis tiendas algo de lo que falta y lo puedo hacer a lotes de tres meses y rotativo\u201d<\/strong><\/p>\n<p><strong>O sea que parecer ser que necesita personal.\u00a0 <\/strong><\/p>\n<p><strong>Como tambi\u00e9n necesita dinero, como todo el mundo, ofrece ese trabajo a todos mediante el sencillo m\u00e9todo de que me vengan a comprar, dejen primero un dinero aqu\u00ed, yo les doy unas papeletas, como la loter\u00eda de la falla del barrio y negocio redondo.<\/strong><\/p>\n<p><strong>En esta Espa\u00f1a nuestra se ha sorteado de todo. Jamones, bicicletas, lavadoras, vajillas \u00a0y entradas para ver a la Pantoja a cambio de comprar un jam\u00f3n. Se ve que detr\u00e1s de cada comerciante, de cada emprendedor bulle la creatividad.<\/strong><\/p>\n<p><strong>La cuesti\u00f3n ser\u00eda preguntarse cu\u00e1l es el l\u00edmite. \u00bfRoza la dignidad lo de someterse a un parado a un sorteo previa compra?<\/strong><\/p>\n<p><strong>Hago cort\u00edsima hoy la columna. Me he dado un toque de austeridad sem\u00e1ntica. Debo frenar mi posible facundia. Buenos d\u00edas.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El trabajo a sorteo La cadena de zapater\u00edas &#8216;Calzados Loremar&#8216; ha iniciado esta semana una particular campa\u00f1a de promoci\u00f3n para incentivar las compras entre los ciudadanos de Jerez de la Frontera. Bajo el formato de un sorteo entre los clientes, la cadena ha organizado una particular loter\u00eda en la que el \u2018premio gordo&#8217; son tres [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-1693","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts\/1693","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/comments?post=1693"}],"version-history":[{"count":0,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts\/1693\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/media?parent=1693"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/categories?post=1693"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/tags?post=1693"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}