{"id":1762,"date":"2012-12-20T07:41:52","date_gmt":"2012-12-20T07:41:52","guid":{"rendered":"http:\/\/blogs.lasprovincias.es\/carlospajuelo\/?p=1762"},"modified":"2012-12-20T07:41:52","modified_gmt":"2012-12-20T07:41:52","slug":"el-turista","status":"publish","type":"post","link":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/2012\/12\/20\/el-turista\/","title":{"rendered":"El turista"},"content":{"rendered":"<p>El turista<\/p>\n<p>Imaginemos que le quitamos el art\u00edculo \u00bfQu\u00e9 queda? Un elemento inconexo, suelto y sin embargo lleno de posibles connotaciones.<\/p>\n<p>Ah\u00ed tenemos que anoche o\u00ed un corte de una entrevista que se ve que le hicieron en la radio p\u00fablica \u2013 la llamada Nacional- al Presidente del Consejo del Poder Judicial del que se desprend\u00eda su valoraci\u00f3n de que mandemos al Presidente en clase turista cuando viaja en avi\u00f3n en representaci\u00f3n de los jueces y supongo que en nombre y a costa nuestra. No le terminaba de gustar\u2026sobre todo por la imagen del cargo, dec\u00eda.<\/p>\n<p>Por eso digo que \u201cturista\u201d tiene muchas posibilidades. Aqu\u00ed parec\u00eda a modo de un descredito que este se\u00f1or vuele en turista no siendo turista y se quejaba. \u00bfTiene o no raz\u00f3n? Supongo que habr\u00e1 para todos los gustos. La gente usar\u00e1 desde el empleo de un Andreu Fabra coloquial a la reivindicaci\u00f3n de la funci\u00f3n.<\/p>\n<p>Turista era un apelativo al que si le a\u00f1ad\u00edas un mill\u00f3n sol\u00eda coincidir con una escalerilla de avi\u00f3n, una rubia a la saz\u00f3n despampanante, un ramo de flores, un jefe de algo que con su corbata y canes\u00fa daba la bienvenida y le daba dos besos( se habla de gente que daba hasta cuatro y ten\u00edan que llamarle la atenci\u00f3n porque era muy \u201cqueredor\u201d y se hab\u00eda tomado la pasi\u00f3n hispana a pecho y la se\u00f1orita, que no sab\u00eda nada, tampoco dec\u00eda esta boca es m\u00eda porque no habl\u00e1bamos ingl\u00e9s y menos polaco)<\/p>\n<p>Turista en si mismo puede no ser nada. Apenas una exclamaci\u00f3n de alguien que se queja por ver a otro estar en la oficina mirando mucho al exterior y rasc\u00e1ndose sus partes en la intimidad de la bajamesa; es entonces cuando, a lo mejor, dice \u201cese es un turista\u201d.<\/p>\n<p>Yo exijo aqu\u00ed y ahora que se forme un movimiento popular \u2013 no descarto manifestaciones- para la defensa del turista y sus turisteces. No olvidemos que se trata de una industria creciente que aporta muchos eurod\u00f3lares y como siempre nos dicen que \u201cno est\u00e1 el horno para bollos\u201d pues ah\u00ed est\u00e1 usted conmigo que no podemos envilecer el t\u00e9rmino.<\/p>\n<p>En consecuencia reclamo, sin tasas al Sr, Presidente de la cosa Judicial que viaje con dignidad y si hay que hacerlo en turista es por aquellos polvos \u201cdivarianos\u201d que traen estos lodos viajeros.<\/p>\n<p>Otro si digo que la restauraci\u00f3n en Valencia es m\u00e1s cara, te hace un roto en la cartera. que en Par\u00eds- que a m\u00ed me gusta mucho decir lo de Paris &#8211; es que me ha entrado esa man\u00eda urbana por los bulevares y Museos y la limpieza de sus calles que se adornan, como las nuestras, con sendos ciudadanos en el suelo medio muertos de hambre y alcohol.<\/p>\n<p>All\u00ed como aqu\u00ed al respetable se le importa \u201cuna higa\u201d el asunto. Bueno me voy a pasear a mirar las viandas del Mercado Central que eso me gusta mucho a m\u00ed. Si veo algo ya les contar\u00e9. Bon jour.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El turista Imaginemos que le quitamos el art\u00edculo \u00bfQu\u00e9 queda? Un elemento inconexo, suelto y sin embargo lleno de posibles connotaciones. Ah\u00ed tenemos que anoche o\u00ed un corte de una entrevista que se ve que le hicieron en la radio p\u00fablica \u2013 la llamada Nacional- al Presidente del Consejo del Poder Judicial del que se [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-1762","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts\/1762","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/comments?post=1762"}],"version-history":[{"count":0,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts\/1762\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/media?parent=1762"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/categories?post=1762"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/tags?post=1762"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}