{"id":1792,"date":"2013-01-11T07:24:26","date_gmt":"2013-01-11T07:24:26","guid":{"rendered":"http:\/\/blogs.lasprovincias.es\/carlospajuelo\/?p=1792"},"modified":"2013-01-11T07:24:26","modified_gmt":"2013-01-11T07:24:26","slug":"los-consortes","status":"publish","type":"post","link":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/2013\/01\/11\/los-consortes\/","title":{"rendered":"Los consortes"},"content":{"rendered":"<p><strong>Los consortes<\/strong><\/p>\n<p><strong><em>Consorte<\/em><\/strong><em>, una palabra que halla su origen en el lat\u00edn <\/em><em>consors<\/em><em>, es un t\u00e9rmino que describe a quien <strong>acompa\u00f1a a uno o a varios sujetos en la misma realidad<\/strong>. El concepto se utiliza asimismo para hacer referencia al <strong>esposo de una mujer y al rev\u00e9s: a la esposa de un hombre respecto a \u00e9l<\/strong>.<\/p>\n<p><\/em><\/p>\n<p>Es el caso que ahora \u00a0vivimos acontecimientos varios que dan juego a los consortes, Mientras la periodista, hoy princesa, Leticia es acogida en la llamada Real Maestranza de Valencia en su calidad de Princesa de Asturias, otro consorte de nombre Undargar\u00edn, jugador de balonmano de la \u00e9lite en su d\u00eda y a la saz\u00f3n esposo de la infanta Cristina est\u00e1 sometido al Imperio de la Ley, dicen,<\/p>\n<p>El consorte, se escribe, que le ha pedido a su suegro, o sea el Rey, unos dineros para afrontar la posible fianza que el juez puede ponerle y hoy El Confidencial da cuenta de la puesta en venta de su palacete en Barcelona porque, tambi\u00e9n se dice, que su suegro le ha dicho que no por la v\u00eda interpuesta de su suegra, o sea la Reina, que a su vez har\u00eda portavoz de su hija la infanta.<\/p>\n<p>El asunto es normal entre miembros de familias, sean reales o ficticias. El consorte tiene un papel y quien dice habitualmente: \u201cYo firmaba lo que \u00a0mi marido me pon\u00eda delante. Yo no s\u00e9 nada\u201d se expone a un trato por compartir la misma realidad.<\/p>\n<p>No se\u00f1ora, no. Usted debe exigir, saber no sea que \u201cla pasma\u201d, por orden judicial, venga y la registre y en pleno registro usted insista con su cantinela. \u201cYo no sab\u00eda, yo no sab\u00eda\u201d.<\/p>\n<p>Mientras tomaba esas gambas al ajillo o esos langostinitos de Benicarl\u00f3, por ejemplo, sabiendo \u00a0lo caro que est\u00e1 el pescado (acu\u00e9rdese del cuadro de Sorolla con aquello de \u201caun dicen que el pescado es caro\u201d) \u00bfUsted no pregunt\u00f3 a su consorte : Mi amor, digo, \u00bfde d\u00f3nde sacas para tanto que destacas?.<\/p>\n<p>Consortes del mundo un\u00edos\u2026no vaya a ser que vuestro acompa\u00f1ante os meta en un l\u00edo de tres pares de pelotas y ni el Rey os puede bajar la prima de riesgo. He dicho. Buenos d\u00edas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los consortes Consorte, una palabra que halla su origen en el lat\u00edn consors, es un t\u00e9rmino que describe a quien acompa\u00f1a a uno o a varios sujetos en la misma realidad. El concepto se utiliza asimismo para hacer referencia al esposo de una mujer y al rev\u00e9s: a la esposa de un hombre respecto a [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-1792","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts\/1792","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/comments?post=1792"}],"version-history":[{"count":0,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts\/1792\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/media?parent=1792"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/categories?post=1792"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/tags?post=1792"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}