{"id":1866,"date":"2013-06-04T05:45:38","date_gmt":"2013-06-04T05:45:38","guid":{"rendered":"http:\/\/blogs.lasprovincias.es\/carlospajuelo\/?p=1866"},"modified":"2013-06-04T05:45:38","modified_gmt":"2013-06-04T05:45:38","slug":"el-soborno","status":"publish","type":"post","link":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/2013\/06\/04\/el-soborno\/","title":{"rendered":"El soborno"},"content":{"rendered":"<p>El soborno<\/p>\n<p>El MI6, el servicio de espionaje brit\u00e1nico, soborn\u00f3 a generales espa\u00f1oles para que estos disuadieran al dictador Francisco Franco de entrar en la Segunda Guerra Mundial del lado de Hitler. Documentos secretos ahora desclasificados revelan que se pagaron el equivalente a 232 millones de d\u00f3lares de hoy.(El Pa\u00eds)<\/p>\n<p>A m\u00ed no me extra\u00f1a. \u00bfQui\u00e9n de nosotros no ha sido sobornado de alguna forma a la largo de su vida? Es la pol\u00edtica del premio. Es el palo y la zanahoria.<\/p>\n<p>A m\u00ed nunca me han sobornado o a mi no me compra nadie, Estas rotundas afirmaciones no se sostienen. Veamos algunos posibles actos de soborno.<\/p>\n<p>\u00bfEs el cortejo amoroso un acto limpio, \u00e9tico, cuyo final est\u00e1 por escribir en funci\u00f3n de la habilidad del cortejador? Oiga, usted hila muy fino. Puede ser. Todos queremos lograr algo y para ello usamos sin medida las armas que la Naturaleza nos ha dado,<\/p>\n<p>Ahora se habla mucho- solo unos d\u00edas porque habr\u00e1 otras noticias -de Fabra y su \u00e1nimo de ser &#8220;cohachado&#8221; por un vendedor de humo positivo (supongo que este humo ser\u00e1 blanco y llegar\u00e1 un momento en que diremos &#8220;habemus Fabra&#8221;)<\/p>\n<p>Lea a Maquiavelo .Es m\u00e1s barato.<\/p>\n<p>Digo yo si no hay que llegar a esto de la pol\u00edtica. del profesorado, de la medicina o del noble ejercicio de poner ladrillos( o sea alba\u00f1il) ya hecho.<\/p>\n<p>\u00bfHabr\u00e1 que reciclarse, no? dicen algunos que suelen ser del mismo partido y debidamente engrasados(sobornados) por la maquinaria partidista mediante el sobre, la promesa en la lista o la colocaci\u00f3n de un sobrino o hijo en aquella conseller\u00eda, concejal\u00eda o empresa af\u00edn. \u00bfQu\u00e9 no har\u00eda uno por un hij@? Estoy seguro que muchos dir\u00e1n a Rus : &#8220;Qu\u00e9 templado y alto te veo&#8221; ( todos sabemos que Rus es bajito , a mi me cae bien el tipo pero es un hecho que es bajito).<\/p>\n<p>Esto del soborno, del cohecho, del favor, est\u00e1 y ha estado a la orden del d\u00eda .Lo s\u00e9. Lo \u00fanico que me molesta es que se haga con mi dinero, con mi esfuerzo y que adem\u00e1s me digan que lo hacen por mi bien. Parafraseando a la bella hija del otro Fabra. !No me jodan!. Buenos d\u00edas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El soborno El MI6, el servicio de espionaje brit\u00e1nico, soborn\u00f3 a generales espa\u00f1oles para que estos disuadieran al dictador Francisco Franco de entrar en la Segunda Guerra Mundial del lado de Hitler. Documentos secretos ahora desclasificados revelan que se pagaron el equivalente a 232 millones de d\u00f3lares de hoy.(El Pa\u00eds) A m\u00ed no me extra\u00f1a. [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-1866","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts\/1866","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/comments?post=1866"}],"version-history":[{"count":0,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts\/1866\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/media?parent=1866"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/categories?post=1866"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/tags?post=1866"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}