{"id":1884,"date":"2013-06-21T10:40:03","date_gmt":"2013-06-21T10:40:03","guid":{"rendered":"http:\/\/blogs.lasprovincias.es\/carlospajuelo\/?p=1884"},"modified":"2013-06-21T10:40:03","modified_gmt":"2013-06-21T10:40:03","slug":"duelo-al-sol","status":"publish","type":"post","link":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/2013\/06\/21\/duelo-al-sol\/","title":{"rendered":"Duelo al Sol"},"content":{"rendered":"<p><strong>Duelo al Sol<\/strong><\/p>\n<p><strong>Hace calor y el \u00e1nimo se envalentona. En vez de dorados o plateados rev\u00f3lveres son las actas de diputados, los dossiers que sacan a la luz historias para no dormir, desempolvan peque\u00f1as o grandes prevaricaciones que, como rayos en la tormenta iluminan , para asombro e ira de muchos votantes, el lado oscuro de la pol\u00edtica cicatera, de la miseria de las pasiones, de la ,lujuria y la ambici\u00f3n desmedida de poder y dinero. <\/strong><\/p>\n<p><strong>Un drama nacional que da asco.<\/strong><\/p>\n<p><strong>Blasco y Fabra. Dos caciques &#8211; en el uso del t\u00e9rmino secular- midiendo sus fuerzas y usando intermediarios para amenazarse. \u00bfQui\u00e9n fajar\u00e1 m\u00e1s?. Es raro que esto no sea objeto de apuestas en el mercado cual de si un reto entre boxeadores se tratase. El de Alcira contra el de Castell\u00f3n.\u00bf Peso pesado contra uno ligero?.<\/strong><\/p>\n<p><strong>Te ir\u00e1s. Veremos si puedes. <\/strong><\/p>\n<p><strong><em>&#8221;\u00a0<\/em><\/strong><strong><em>El l\u00edder del PPCV apunt\u00f3 adem\u00e1s la posibilidad de aplicar sanciones a quienes disfrutan de incontinencia verbal. Pese a que la declaraci\u00f3n fue gen\u00e9rica, el destinatario \u00fanico del mensaje era Blasco, que en la entrevista de la noche del mi\u00e9rcoles arremeti\u00f3 con dureza contra Fabra por su doctrina contra los imputados.(Las provincias)&#8221;<\/em><\/strong><\/p>\n<p><strong>Si no fuera dram\u00e1tico dar\u00eda hasta risa. Ah\u00ed es nada el combate. Hace a\u00f1os se daban combates de lucha libre llamada americana y las plazas de toros se iluminaban con las puntas de los cigarrillos, siempre en danza, en gradas de oscuras intenciones ,mientras alguna voz femenina saltaba en el aire diciendo: M\u00e1talo.<\/strong><\/p>\n<p><strong>Primero un silencio denso y enseguida una carcajada un\u00e1nime. Buenos d\u00edas.<\/strong><strong><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Duelo al Sol Hace calor y el \u00e1nimo se envalentona. En vez de dorados o plateados rev\u00f3lveres son las actas de diputados, los dossiers que sacan a la luz historias para no dormir, desempolvan peque\u00f1as o grandes prevaricaciones que, como rayos en la tormenta iluminan , para asombro e ira de muchos votantes, el lado [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-1884","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts\/1884","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/comments?post=1884"}],"version-history":[{"count":0,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts\/1884\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/media?parent=1884"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/categories?post=1884"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/tags?post=1884"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}