{"id":4182,"date":"2019-08-24T04:06:38","date_gmt":"2019-08-24T04:06:38","guid":{"rendered":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/?p=4182"},"modified":"2019-08-24T04:06:38","modified_gmt":"2019-08-24T04:06:38","slug":"homo-floresiensis-papel-y-digital","status":"publish","type":"post","link":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/2019\/08\/24\/homo-floresiensis-papel-y-digital\/","title":{"rendered":"HOMO FLORESIENSIS \/papel y digital"},"content":{"rendered":"<div dir=\"ltr\">HOMO FLORESIENSIS<\/div>\n<div dir=\"ltr\"><\/div>\n<div dir=\"ltr\"><\/div>\n<div dir=\"ltr\">Trata de la microcefalia de los elegidos para la gloria y el honor de dirigirnos que no dan una, mientras habitan en palacios mantenidos y regados con &#8220;la guita&#8221; del respetable, entre los que me encuentro. Veamos.<\/div>\n<div dir=\"ltr\"><\/div>\n<div dir=\"ltr\"><\/div>\n<div dir=\"ltr\">Digo\u00a0 que\u00a0 soy lento a la hora de asumir los &#8220;best sellers&#8221;. Hab\u00eda le\u00eddo que un libro llamado &#8220;Sapiens&#8221; estaba en su 38 edici\u00f3n y que hab\u00eda logrado m\u00e1s de 15 millones de lectores\u00a0 y ayer lo compr\u00e9 porque la recomendaci\u00f3n de Mu\u00f1oz Molina era buena y, en general, me f\u00edo den D. Antonio.<\/div>\n<div dir=\"ltr\"><\/div>\n<div dir=\"ltr\"><\/div>\n<div dir=\"ltr\">Y ah\u00ed leo: Homo floresiensis, conocido como El hombre de Flores y apodado Hobbit,2 es una especie extinta del g\u00e9nero Homo. Es extraordinaria por el peque\u00f1o tama\u00f1o de su cuerpo de apenas un metro de estatura, y 25 kg de peso, su cerebro de menos de 400 c. c.<\/div>\n<div dir=\"ltr\"><\/div>\n<div dir=\"ltr\"><\/div>\n<div dir=\"ltr\">La isla est\u00e1 en Indonesia, que tampoco est\u00e1 tan lejos. \u00bfNo? Y me digo: no est\u00e1 extinto. Habita En La Moncloa y en la oposici\u00f3n. Microcefalia pura y esencial.<\/div>\n<div dir=\"ltr\"><\/div>\n<div dir=\"ltr\"><\/div>\n<div dir=\"ltr\">Siento un escalofr\u00edo. Al repasar el calendario temporal hist\u00f3rico, recuerdo que la materia lleva por aqu\u00ed del orden de 13 mil millones de a\u00f1os y los humanos solo entre 4 y 2,5 millones de a\u00f1os.\u00a0 Un suspiro c\u00f3smico.<\/div>\n<div dir=\"ltr\"><\/div>\n<div dir=\"ltr\"><\/div>\n<div dir=\"ltr\">Yo sab\u00eda algo pero no le daba importancia, preocupado en m\u00ed mismo y en unos cuantos m\u00e1s. Tambi\u00e9n s\u00e9 que la gente se mov\u00eda mucho e iba de continente en continente sin trabas oce\u00e1nicas y que Salvini no exist\u00eda, Iglesias no hab\u00eda sido concebido y S\u00e1nchez ya pensaba en la Moncloa.<\/div>\n<div dir=\"ltr\"><\/div>\n<div dir=\"ltr\"><\/div>\n<div dir=\"ltr\">Seres enanos, diminutos, micro cef\u00e1licos y que se les ha bautizado comercialmente con el nombre de &#8220;Hobbits&#8221; y que al `parecer cohabitaban con mis primos Neandertales. Todos somos familia.<\/div>\n<div dir=\"ltr\"><\/div>\n<div dir=\"ltr\"><\/div>\n<div dir=\"ltr\">\u00bfTodo esto a que viene? A nada en especial, solo a que creo que nos est\u00e1n tomando el pelo entre tanto juego interdigitales.<\/div>\n<div dir=\"ltr\"><\/div>\n<div dir=\"ltr\"><\/div>\n<div dir=\"ltr\">Que te doy, que me das, que te quito, que no puede ser, que un poco menos, que un poco m\u00e1s\u2026y el pa\u00eds\u00a0 funcionando con presupuesto de la era del Registrador Rajoy con la Sra. Calvo, con todo los planes parados a esperar.<\/div>\n<div dir=\"ltr\"><\/div>\n<div dir=\"ltr\"><\/div>\n<div dir=\"ltr\">Somos m\u00e1s tontos que Pichote- que, por cierto, no s\u00e9 qui\u00e9n era. Estamos perdiendo fuelle.<\/div>\n","protected":false},"excerpt":{"rendered":"<p>HOMO FLORESIENSIS Trata de la microcefalia de los elegidos para la gloria y el honor de dirigirnos que no dan una, mientras habitan en palacios mantenidos y regados con &#8220;la guita&#8221; del respetable, entre los que me encuentro. Veamos. Digo\u00a0 que\u00a0 soy lento a la hora de asumir los &#8220;best sellers&#8221;. Hab\u00eda le\u00eddo que un [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-4182","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts\/4182","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/comments?post=4182"}],"version-history":[{"count":1,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts\/4182\/revisions"}],"predecessor-version":[{"id":4183,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts\/4182\/revisions\/4183"}],"wp:attachment":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/media?parent=4182"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/categories?post=4182"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/tags?post=4182"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}