{"id":4396,"date":"2020-03-17T09:32:46","date_gmt":"2020-03-17T09:32:46","guid":{"rendered":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/?p=4396"},"modified":"2020-03-17T09:32:46","modified_gmt":"2020-03-17T09:32:46","slug":"diario-de-un-encierro-i2","status":"publish","type":"post","link":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/2020\/03\/17\/diario-de-un-encierro-i2\/","title":{"rendered":"DIARIO DE UN ENCIERRO (I+2)"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>DIARIO DE UN ENCIERRO (I +II)<\/strong><\/p>\n<p><strong>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 En general el respetable no es un cartujo y por tanto el silencio, la entrega a la soledad y el confinamiento voluntario no son monedas de cambio de curso corriente.<\/strong><\/p>\n<p><strong>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 No digo que no es legal porque esto s\u00ed que lo es y si te lo saltas te puede caer la de Dios en materia econ\u00f3mica y se sabe que a medida que el autorizado nota que puede amedrentar (coloquialmente &#8220;acojonar&#8221; con alguna multa de esas que son algo m\u00e1s que la del aparcamiento, la cosa puede convertirse en algo &#8220;chungo&#8221;).<\/strong><\/p>\n<p><strong>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Me parece que hay que emplear alguna expresi\u00f3n de la&#8221;calle&#8221; para hacer m\u00e1s comestible la opini\u00f3n o el relato(que se dice ahora).<\/strong><\/p>\n<p><strong>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Dado que ya est\u00e1 uno confinado y habiendo le\u00eddo que hay listos, en Vigo uno alquila un perro por horas, la cuesti\u00f3n es c\u00f3mo organizarse para combatir el posible s\u00edndrome de encierro involuntario.<\/strong><\/p>\n<p><strong>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Lo primero es evitar lo del chiste que me han enviado. Dice uno &#8220;Mi mujer me ha dicho que ella me paga la multa, pero que me vaya a tomar el aire&#8221;<\/strong><\/p>\n<p><strong>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Yo les voy a contar mi plan de encierro.<\/strong><\/p>\n<p><strong>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Lo primero buscarse un lema y este debe depender de la edad del encerrado. Los ni\u00f1os pueden decir &#8220;te quiero mam\u00e1&#8221; y los viejos de riesgo, mi caso, un &#8220;que me quede como estoy&#8221;- suponiendo que viva uno medio bien.<\/strong><\/p>\n<p><strong>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Al levantarse y habiendo realizado las abluciones cl\u00e1sicas- o sea lavarse bien la cara etc., (cuidado con lavarse con desinfectante que nos libraremos del virus pero acabaremos en la sala de espera del oftalm\u00f3logo o del dermat\u00f3logo, o del ur\u00f3logo, seg\u00fan sea la parte atacada con el desinfectante).<\/strong><\/p>\n<p><strong>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Haci\u00e9ndome caso a m\u00ed mismo, cosa que no siempre ocurre, mi lema es: &#8221; La Macarena&#8221; y me digo canturreando con un minimeneo para evitar lumbago o luxsacion es, &#8220;dale a tu cuerpo alegr\u00eda\u2026etc.).<\/strong><\/p>\n<p><strong>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Rompo a mi favor el no ponerme smoking, ni chaqueta, pero estoy bien me ha comprado mi mujer, en el \u00faltimo momento, un pijama chulo y una bata que no es a cuadros haciendo juego con las alpargatas o sea zapatillas, porque dicen que eso hace de viejos, de maduros antiguos y yo intento un Calvin Klein que me han dicho que tiene un cierto peso en la moda.<\/strong><\/p>\n<p><strong>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Por otra parte no s\u00e9 para qu\u00e9 ,porque no va a venir a verme nadie, salvo la vecina a pedirme aceite o az\u00facar, como se hac\u00eda antes, que eso si que era un principio de relaci\u00f3n social.<\/strong><\/p>\n<p><strong>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Se sabe de vecinas que empezaron as\u00ed y luego han terminado en el altar o en el juzgado y m\u00e1s ahora como est\u00e1 el tema del feminismo.<\/strong><\/p>\n<p><strong>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Imaginen que llaman. \u00bfAbro o no abro?<\/strong><\/p>\n<p><strong>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Si miro por el ojo esp\u00eda de la puerta, que solo abarca medio cuerpo, se me va a notar y yo me puedo entregar a un cierto sentido de la culpabilidad y yo no estoy ya para esos trotes; me han dicho que por ah\u00ed empieza la depresi\u00f3n. Ya ver\u00e9 que hago.<\/strong><\/p>\n<p><strong>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Ya estoy listo y huelo bien. \u00bfA qu\u00e9 parte de la casa voy?<\/strong><\/p>\n<p><strong>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Tengo un amigo que vive en un apartamento de una sola habitaci\u00f3n, mona pero solo una habitaci\u00f3n, y ese no se puede plantear esa duda<\/strong><\/p>\n<p><strong>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 He mirado y he escrito m\u00e1s 500 palabras y ya seguir\u00e9 ma\u00f1ana\u2026porque, hermanos, esto va para largo. Queda mucho d\u00eda por delante<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; &nbsp; DIARIO DE UN ENCIERRO (I +II) \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 En general el respetable no es un cartujo y por tanto el silencio, la entrega a la soledad y el confinamiento voluntario no son monedas de cambio de curso corriente. \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 No digo que no es legal porque esto s\u00ed que lo es y si te [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-4396","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts\/4396","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/comments?post=4396"}],"version-history":[{"count":1,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts\/4396\/revisions"}],"predecessor-version":[{"id":4397,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts\/4396\/revisions\/4397"}],"wp:attachment":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/media?parent=4396"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/categories?post=4396"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/tags?post=4396"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}