{"id":4535,"date":"2020-07-02T19:57:50","date_gmt":"2020-07-02T19:57:50","guid":{"rendered":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/?p=4535"},"modified":"2020-07-02T19:57:50","modified_gmt":"2020-07-02T19:57:50","slug":"que-pague-europa","status":"publish","type":"post","link":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/2020\/07\/02\/que-pague-europa\/","title":{"rendered":"!Que pague Europa!"},"content":{"rendered":"<p>\u00a1QUE PAGUE EUROPA!<\/p>\n<p>Que el calor est\u00e1 apretando no es una noticia o solo se convierte en noticia cuando pasa de los 40 grados, como ya ha ocurrido ayer en un pueblo de la Comunidad; la gente sopla y es motivo de comentario, aunque he de decirles que desde que yo era peque\u00f1o- o sea hace mucho- en las escaleras-no todos los edificios ten\u00edan ascensor- y m\u00e1s tarde, unos veranos adelante, en el ascensor, los que se acompa\u00f1aban en el viaje del sube y baja no hac\u00edan sino referirse al calor abrasador o al fr\u00edo irredento cundo era invierno.<\/p>\n<p>De ah\u00ed es de donde yo he extra\u00eddo la observaci\u00f3n literaria de que en los ascensores solo se habla del tiempo o en todo caso se establece un silencio marcado por el correr de los pisos, que la botonera en su versi\u00f3n moderna, marca sobre una pantallita. Y nada el silencio se adue\u00f1a del ambiente cerrado adornado ahora con una mascarilla<\/p>\n<p>Sin embargo, ha surgido un rumor que recorre ascensores, escaleras, calles y jardines.; se trata de intentar averiguar qui\u00e9n va a pagar todos los dineros que este honorable Gobierno populista, ha prometido d\u00eda s\u00ed, d\u00eda no.<\/p>\n<p>Yo tengo la secreta convicci\u00f3n de que seremos los de siempre y de hecho ya se habla de subir impuestos, de subir el IVA y de subirlo todo.<\/p>\n<p>Como estamos en fase reconstructiva nacional yo propongo estudiar la tradici\u00f3n en materia de rogativas.<\/p>\n<p>\u00bfSe ha rezado bastante para que el asunto no recaiga sobre nuestras espaldas? \u00bfSe han convocado a los que saben de sortilegios para atacar esta ausencia de liquidez?<\/p>\n<p>\u00a1Qui\u00e9n no recuerda aquellas procesiones que atravesaban los pueblos pidiendo que nos visitase la lluvia?<\/p>\n<p>Se llevaba una Virgen local o un Cristo especial y el cura del pueblo encabezaba la procesi\u00f3n seguido de sendas mujeres vestidos de negro- color de moda en la Espa\u00f1a de los 50- que entonaban salves y rezaban rosarios interminables y, oiga, a veces llov\u00eda.<\/p>\n<p>No pasar\u00eda nada si en Madrid y desde la Moncloa se habilitasen sendas andas para llevar a figuras de imitaci\u00f3n \u201cfallera\u201d de la Sra. Merkel y de alguien de Holanda, un jefe mayormente y todos pasar\u00edan por delante de las Embajadas y en vez de rezar- los extranjeros son muy ateos, ya se sabe- se acompa\u00f1ar\u00e1n las peticiones con el himno de la alegr\u00eda muy europeo \u00e9l y se deber\u00eda cerrar con bailes regionales al estilo de Educaci\u00f3n y Descanso.<\/p>\n<p>Invitando a acompa\u00f1ar con grupos de b\u00e1varos bebiendo cerveza y otros ahumando salm\u00f3n, para dar un toque internacional y para que se sepa que nosotros conocemos las debilidades y virtudes de esos barbaros descendientes de vikingos.<\/p>\n<p>Por otra parte, tengo cierto temor a que resuciten en ellos sentimientos contra nuestros Tercios que en su d\u00eda les dieron para el pelo.<\/p>\n<p>Pediremos perd\u00f3n que ahora est\u00e1 de moda por todo en general y por eso tambi\u00e9n,<\/p>\n<p>La cosa es que suelten la mosca y si hay que n\u00f3mbrarles falleros de honor lo haremos.<\/p>\n<p>Mire usted por probar no cuesta nada. Ah\u00ed tiene usted, por ejemplo, a D. Silvio Berlusconi con sus 83 a\u00f1os que se ha echado una novia de 30 y ha despedido a la anterior mediante una especie de comunicado de prensa.<\/p>\n<p>El t\u00edo est\u00e1 que se rompe y tiene una autoestima que para mi y mis vecinos- por poner un ejemplo querr\u00eda yo.<\/p>\n<p>O sea que adem\u00e1s de los viajes previstos por nuestro presidente y ad lateres insisto en la puesta en marcha de procesiones con rogativas.<\/p>\n<p>Algunos establecimientos de gerencia china nos vender\u00edan banderas de esos pa\u00edses e incluso trajes regionales.<\/p>\n<p>S\u00e9 que hay contratados sendas docenas de sabios economistas por el Gobierno para que nos cuenten lo que ya sabemos. Que estamos jodidos, que vamos a m\u00e1s, pero que no hay que perder la esperanza y que adem\u00e1s ha vuelto el futbol y eso distrae mucho.<\/p>\n<p>Ya me contar\u00e1n. Yo mantengo la distancia social y me he comprado un pa\u00f1uelo de blanco grande para saludar y evitar errores o no de protocolo. Caso Portugal en la apertura de la frontera. Un asunto para puristas.<\/p>\n<p>El mundo fluye y se olvida de sus tradiciones. Aqu\u00ed estoy yo, por ejemplo, para recordar lo de las rogativas que tampoco hace da\u00f1o a nadie y as\u00ed damos un paseo todos y volveremos a vernos las caras o lo que queda de ellas con la mascareta puesta.<\/p>\n<p>Bis margen o sea hasta ma\u00f1ana a lo mejor.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a1QUE PAGUE EUROPA! Que el calor est\u00e1 apretando no es una noticia o solo se convierte en noticia cuando pasa de los 40 grados, como ya ha ocurrido ayer en un pueblo de la Comunidad; la gente sopla y es motivo de comentario, aunque he de decirles que desde que yo era peque\u00f1o- o sea [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-4535","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts\/4535","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/comments?post=4535"}],"version-history":[{"count":1,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts\/4535\/revisions"}],"predecessor-version":[{"id":4536,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts\/4535\/revisions\/4536"}],"wp:attachment":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/media?parent=4535"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/categories?post=4535"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/tags?post=4535"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}