{"id":5103,"date":"2022-03-20T17:06:53","date_gmt":"2022-03-20T17:06:53","guid":{"rendered":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/?p=5103"},"modified":"2022-03-20T17:06:53","modified_gmt":"2022-03-20T17:06:53","slug":"ejercicios-para-viejos","status":"publish","type":"post","link":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/2022\/03\/20\/ejercicios-para-viejos\/","title":{"rendered":"EJERCICIOS PARA VIEJOS"},"content":{"rendered":"<table class=\"W_6D6F H_6D6F p_R bo_BA ku_f\" data-test-id=\"message-view\">\n<tbody>\n<tr class=\"W_6D6F\">\n<td class=\"V_GM H_6D6F\">\n<div class=\"d_3zJDR P_1Izyn\">\n<div class=\"msg-body w_AS mq_AS ix_AS H_Z1jxxvJ o_A\" data-test-id=\"message-body\">\n<div dir=\"ltr\"><strong>EJERCICIOS PARA VIEJOS<\/strong><\/div>\n<div dir=\"ltr\"><strong>Antes que nada deben saber, puede que a muchos les importe una higa pero a m\u00ed no como es natural y comprensible, que hace horas que he sobrepasado la barrera de los 81 y en consecuencia he adquirido el titulo de viejo em\u00e9rito por derecho propio.<\/strong><\/div>\n<div dir=\"ltr\"><strong>Como nunca me he distinguido en deporte alguno, creo que ha llegado el momento de hacerme el prop\u00f3sito firme de hacer algo.<\/strong><\/div>\n<div dir=\"ltr\"><strong>He repasado algunos deportes por si de su estudio deduzco alguno posible y beneficioso; para ello NO CUENTO con los consejos que me han dado algunos amigos m\u00e9dicos que me honran, pese a todo, con su amistad y comprensi\u00f3n.<\/strong><\/div>\n<div dir=\"ltr\"><strong>Antes una noticia de alcance que me parece de inter\u00e9s. Ustedes recordar\u00e1n que el Sr. Borrell, el super jefe de la diplomacia europea se lanz\u00f3 a recomendarnos cosas, acciones que sirvieran para aliviar la carga de los costes de la energ\u00eda que ya sentimos en nuestros bolsillos vac\u00edos y por ello recomend\u00f3 que baj\u00e1ramos un grado la temperatura ambiental dom\u00e9stica. Yo lo estoy pensando porque soy friolero y tengo miedo de caer en manos de una pulmon\u00eda que para todos es mala y para los viejos m\u00e1s; la noticia es que la Sra. Botin, la del inmenso banco ha bajado, y lo ha dicho, a 17 grados su temperatura dom\u00e9stica.<\/strong><\/div>\n<div dir=\"ltr\"><strong>Yo creo que si fuera ella no me importar\u00eda demasiado porque la imagino de aqu\u00ed para all\u00e1 visitando sucursales, ajustando reuniones, mandando a sus ejecutivos objetivos a cumplir para seguir acumulando beneficios para sus accionistas y de paso para ella. Loable acci\u00f3n solidaria.<\/strong><\/div>\n<div dir=\"ltr\"><strong>Se sabe que yo no visito sucursales propias salvo la zona del WC con demasiada frecuencia prost\u00e1tica.<\/strong><\/div>\n<div dir=\"ltr\"><strong>A lo que \u00edbamos. Repaso deportes. Futbol no puedo porque tengo miedo a caerme, con lo que he resuelto que desde mi sill\u00f3n har\u00e9 un simulacro de levantar los brazos ante una jugada de pena o de \u00e9xito, es lo de menos, acompa\u00f1ando el movimiento con alg\u00fan \u201ctaco\u201d sonoro y fuerte para mejorar la glotis.<\/strong><\/div>\n<div dir=\"ltr\"><strong>Me paso al tenis y miro a Nadal y veo que no puedo porque todav\u00eda recuerdo el morr\u00f3n que me pegu\u00e9, cuando intentando retomar el pasado discret\u00edsimo, me enganch\u00e9 conmigo mismo y di con mis huesos en tierra batida y mi rival, mi esposa, crey\u00f3 que era una broma de lo elegantemente que me hab\u00eda ca\u00eddo (eso si hay que hacerlo con pedigr\u00ed), as\u00ed que no he vuelto, pero me levanto y al pie de la cama hago unas torsiones de cintura para mantener las lorzas en su santo sitio.<\/strong><\/div>\n<div dir=\"ltr\"><strong>Luego est\u00e1 el golf que practica mi amigo Ricardo, pero he intentado, en el comedor de mi casa, pero la forma de coger el palo no me sale y me parece contra natura. Sugiero el mocho como elemento \u00fatil que me permite limpiar la zona donde se me cae la baba que en ocasiones emito, pese a que me han dicho que con un poco de Botox la cosa disminuye, no me f\u00edo no se me vaya a quedar la boca como los \u201cmorritos\u201d de la Esteban, por ejemplo,<\/strong><\/div>\n<div dir=\"ltr\"><strong>Del rugby ni hablar; no me veo en la mel\u00e9, como tampoco en manifestaciones o masclet\u00e1s por la cosa misma del aplastamiento o no me confundan con ese octogenario detenido estos d\u00edas por tocamiento a una menor (hace a\u00f1os que escrib\u00ed sobre el \u201cpalpaculs\u201d como un habitual en esas concentraciones incluidas la del traslado de la Virgen que con la excusa del amor mariano etc.).<\/strong><\/div>\n<div dir=\"ltr\"><strong>Del levantamiento de peso no me f\u00edo porque me puedo quedar enganchado como hace alg\u00fan tiempo trasladando un colch\u00f3n de plumas. Aqu\u00ed recomiendo una ligera sentadilla de 20 grados haciendo fuerza con el suelo p\u00e9lvico (aconsejo llevar paquete por un por si acaso).<\/strong><\/div>\n<div dir=\"ltr\"><strong>Del llamado hoy running, o sea correr, nada. Recomiendo paseo por el pasillo de puntillas apoyando la mano en la pared no sea que demos un mal paso.<\/strong><\/div>\n<div dir=\"ltr\"><strong>,<\/strong><\/div>\n<div dir=\"ltr\"><strong>Quiz\u00e1s deba usted cerrar los ojos unos minutos para descansar y s\u00ed en ese proceso se queda usted frito no pasa nada cuando le sorprendan \u201cin fraganti\u201d. \u201cEstaba reflexionando\u201d como dec\u00eda mi santo padre que luego presum\u00eda diciendo que casi no dorm\u00eda por las noches. Perdona pap\u00e1 que est\u00e1s en los cielos, seguro, pero ten\u00eda que decirlo.<\/strong><\/div>\n<div dir=\"ltr\"><strong>Como no ten\u00edamos calefacci\u00f3n no pod\u00edamos, en plan Sra.\u00a0 Bot\u00edn, bajar un grado, pero lo resolv\u00edamos mediate el viejo sistema de echar \u201cuna firma\u201d al brasero de lo que se encargaba mi abuela. Como todas las abuelas de la \u00e9poca, m\u00e1s o menos, viv\u00eda con nosotros. Ahora \u201cla modernor\u201d parece que lo impide.<\/strong><\/div>\n<div dir=\"ltr\"><strong>Con todos estos consejos mantendr\u00e1 usted con dignidad su titulo de viejo, resistiendo la tendencia moderna de considerarlo \u201cviejo asqueroso o tonto\u201d.\u00a0 Yo estoy en ello y ya llevo dos d\u00edas. A pasarlo bien<\/strong><\/div>\n<\/div>\n<\/div>\n<\/td>\n<\/tr>\n<tr class=\"W_6D6F\">\n<td class=\"V_GM\">\n<div class=\"D_B P_1Eu6qC z_2wc7QY\">\n<table class=\"W_6D6F H_6D6F p_R bo_BA\" data-test-id=\"message-toolbar\">\n<thead class=\"b_n\"><\/thead>\n<tbody>\n<tr class=\"W_6D6F\">\n<td class=\"V_M W_d3W t_l J_x\">\n<form class=\"D_I\" action=\"https:\/\/mail.yahoo.com\/b\/compose?.src=ym&amp;reason=unsupported_browser&amp;folderType=SENT&amp;accountIds=1\" method=\"POST\" name=\"msgListForm\" data-test-id=\"dummyTestId\"><strong><button class=\"b_n D_X A_6EqO u_e69 H_6LEV i_6LEV o_h P_Z2guAVt G_e V_M C4_Z2aVTcY q_Z1Q0oGn q4_ZlS9Rj E_eo6\" title=\"Responder\" name=\"action\" type=\"submit\" value=\"reply\" aria-label=\"Responder\"><\/button><button class=\"b_n D_X A_6EqO u_e69 H_6LEV i_6LEV o_h P_Z2guAVt G_e V_M C4_Z2aVTcY q_22a6rV q4_Z1xTMwV E_eo6\" title=\"Responder a todos\" name=\"action\" type=\"submit\" value=\"replyAll\" aria-label=\"Responder a todos\"><\/button><button class=\"b_n D_X A_6EqO u_e69 H_6LEV i_6LEV o_h P_Z2guAVt G_e V_M C4_Z2aVTcY q_P8sMj q4_Z47DJi E_eo6\" title=\"Reenviar\" name=\"action\" type=\"submit\" value=\"forward\" aria-label=\"Reenviar\"><\/button><\/strong><\/form>\n<\/td>\n<td class=\"V_M t_C J_x\">\n<form id=\"msgListForm\" class=\"D_I\" action=\"https:\/\/mail.yahoo.com\/b\/folders\/2?.src=ym&amp;reason=unsupported_browser&amp;folderType=SENT&amp;offset=0\" method=\"POST\" name=\"msgListForm\" data-test-id=\"dummyTestId\">\n<div><strong><span class=\"J_x D_X M_3Y3Gk P_3LQ7g\"><button class=\"b_n D_X A_6EqO u_e69 H_6LEV i_6LEV o_h P_Z2guAVt G_e V_M C4_Z2aVTcY q_Z25N1By q4_ZB0RNU Q_eo6\" title=\"Eliminar\" name=\"action\" type=\"submit\" value=\"moveToFolder\" aria-label=\"Eliminar\">Eliminar<\/button><\/span><\/strong><\/div>\n<\/form>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p>EJERCICIOS PARA VIEJOS Antes que nada deben saber, puede que a muchos les importe una higa pero a m\u00ed no como es natural y comprensible, que hace horas que he sobrepasado la barrera de los 81 y en consecuencia he adquirido el titulo de viejo em\u00e9rito por derecho propio. Como nunca me he distinguido en [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-5103","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts\/5103","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/comments?post=5103"}],"version-history":[{"count":1,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts\/5103\/revisions"}],"predecessor-version":[{"id":5104,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts\/5103\/revisions\/5104"}],"wp:attachment":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/media?parent=5103"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/categories?post=5103"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/tags?post=5103"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}