{"id":831,"date":"2011-04-24T20:33:42","date_gmt":"2011-04-24T18:33:42","guid":{"rendered":"http:\/\/firmas.lasprovincias.es\/carlospajuelodearcos\/?p=831"},"modified":"2011-04-24T20:33:42","modified_gmt":"2011-04-24T18:33:42","slug":"por-que-ha-cambiado-de-repenteel-catalanismo-y-abandona-a-eliseu","status":"publish","type":"post","link":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/2011\/04\/24\/por-que-ha-cambiado-de-repenteel-catalanismo-y-abandona-a-eliseu\/","title":{"rendered":"\u00bfPor qu\u00e9 ha cambiado, de repente,&#8221;el catalanismo&#8221; y abandona a Eliseu?"},"content":{"rendered":"<p>La visi\u00f3n de la cifra obtenida por diversos conceptos por Eliseu Climent es mareante. \u00bfPor qu\u00e9? Por defender una unidad , al parecer, de una lengua y unos territorios que no son iguales a los que se han empe\u00f1ado en llamar catalanes.<\/p>\n<p>La batalla nueva del Ebro se ha inclinado a favor de la econom\u00eda y los encuentros entre empresarios que est\u00e1n m\u00e1s por la exportaci\u00f3n y las infraestructuras ha desvelado los ojos de Mas y su actual Generalitat y quiz\u00e1s tambien los de Camps ocupado ahora en recuperares y en ganar,claro, las elecciones.<\/p>\n<p>Un nueve de Octubre o en una fecha \u00a0de esa \u00a0semana recuerdo haber dado una conferencia en la Universitat bajo el amparo de la organizaci\u00f3n de Eliseu y cobr\u00e9 por ello; no sab\u00eda a la sa\u00f3n que ese dinero proven\u00eda de las arcas de la Generalitat&#8230;pero ahora que lo pienso no me importa y por no importarme ni me acuerdo del titulo y conteniod de la conferencia. Debe ser la edad.<\/p>\n<p>En cualquier caso sigo estando de acuerdo con una amistosa uni\u00f3n con Catalu\u00f1a y Murcia para hacer un frente econ\u00f3mico y demogr\u00e1fico com\u00fan. Una especie de Suiza mediterranea. \u00bfY Madrid? Pues mire usted no s\u00e9 que decir. No me gustan las duplicidades. Tanto depender de Costas,por ejemplo, me da rabia- es una concepci\u00f3n modesta de la mala uva que me inunda cuando pienso en estas cosas. Buenas tardes.<\/p>\n<p>Bien por Nadal y por Ferrer, por cierto.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una buena uni\u00f3n nos hace m\u00e1s fuertes.<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-831","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts\/831","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/comments?post=831"}],"version-history":[{"count":0,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts\/831\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/media?parent=831"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/categories?post=831"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/tags?post=831"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}