{"id":843,"date":"2011-04-30T05:15:02","date_gmt":"2011-04-30T03:15:02","guid":{"rendered":"http:\/\/firmas.lasprovincias.es\/carlospajuelodearcos\/%c2%bfautoridad-o-poder-siempre-autoridad-para-mi-claro"},"modified":"2011-04-30T05:15:02","modified_gmt":"2011-04-30T03:15:02","slug":"autoridad-o-poder-siempre-autoridad-para-mi-claro","status":"publish","type":"post","link":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/2011\/04\/30\/autoridad-o-poder-siempre-autoridad-para-mi-claro\/","title":{"rendered":"\u00bfAutoridad o poder? Siempre autoridad&#8230;para mi, claro"},"content":{"rendered":"<p><strong><a href=\"http:\/\/www.lasprovincias.es\/v\/20110430\/salud\/autoridad-20110430.html\" target=\"_BLANK\" rel=\"external nofollow\">La autoridad<\/a> <\/strong><\/p>\n<p><strong>30.04.11 &#8211; 00:39 &#8211; <\/strong><\/p>\n<p><strong>CARLOS PAJUELO DE ARCOS PERIODISTA | <\/strong><\/p>\n<p><strong>La capacidad de ejercer o hacer que se ejerza el poder en su nombre tiene muchas aristas y una de ellas nace del propio ejerciente. Nace no s\u00f3lo del reconocimiento de los dem\u00e1s que entienden y aceptan como m\u00e1s sabio, sino al propio equilibrio de quien hace de la autoridad su &#8216;modus vivendi&#8217;. Se reconoce, no se impone, y para hablar de ello mi vecino tiene una expresi\u00f3n que camina paralela, pero no es coincidente; se trata del poder. <\/strong><\/p>\n<p><strong>Prefiero aquella a este. Imponer es siempre un prologo a la tensi\u00f3n. <\/strong><\/p>\n<p><strong>Todo esto viene a cuento del la selecci\u00f3n de una servicio, de un m\u00e9dico, de un letrado, de una compa\u00f1\u00eda de seguros, de un servicio telef\u00f3nico y, si quiere usted, me arriesgo m\u00e1s diciendo que hasta en la elecci\u00f3n mutua de pareja. <\/strong><\/p>\n<p><strong>El conocimiento adquirido y su aplicaci\u00f3n p\u00fablica que no s\u00f3lo te acredita para su ejercicio, sino como lo aplicas, te da el espaldarazo del respeto, de la consideraci\u00f3n del otro, que es uno de los valores m\u00e1s altos de la escala humana. No se trata de beber, comer, fornicar, no tener fr\u00edo etc., sino de obtener la consideraci\u00f3n explicita de tu entorno y del resto de la sociedad d\u00f3nde te ha tocado vivir. <\/strong><\/p>\n<p><strong>Ahora toca un tiempo en el que hay que elegir. Yo lo har\u00e9 por el respeto que el otro me ofrece. Su &#8216;auctoritas&#8217; y no el poder adquirido por circunstancias ajenas a su propia trayectoria. Ocurre que hay gente que se ve abocada, mejor empujada por las circunstancias a situarse al mando y ejercer un poder que extralimita su conocimiento cayendo en una suerte de totalitarismo ineficaz. <\/strong><\/p>\n<p><strong>Hay que saber profundizar en el escudo protector de quien ejerce para saber si tiene la acreditaci\u00f3n de la &#8216;auctoritas&#8217;. Buenos d\u00edas.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La autoridad 30.04.11 &#8211; 00:39 &#8211; CARLOS PAJUELO DE ARCOS PERIODISTA | La capacidad de ejercer o hacer que se ejerza el poder en su nombre tiene muchas aristas y una de ellas nace del propio ejerciente. Nace no s\u00f3lo del reconocimiento de los dem\u00e1s que entienden y aceptan como m\u00e1s sabio, sino al propio [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-843","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts\/843","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/comments?post=843"}],"version-history":[{"count":0,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts\/843\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/media?parent=843"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/categories?post=843"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/tags?post=843"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}