{"id":846,"date":"2011-05-02T06:13:09","date_gmt":"2011-05-02T04:13:09","guid":{"rendered":"http:\/\/firmas.lasprovincias.es\/carlospajuelodearcos\/?p=846"},"modified":"2011-05-02T06:13:09","modified_gmt":"2011-05-02T04:13:09","slug":"ya-ahora-que-tras-la-muerte-de-bin-laden","status":"publish","type":"post","link":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/2011\/05\/02\/ya-ahora-que-tras-la-muerte-de-bin-laden\/","title":{"rendered":"\u00bfYa ahora qu\u00e9? Tras la muerte de Bin Laden"},"content":{"rendered":"<p>&#8220;Am\u00e9rica puede hacer lo que se proponga&#8221;, esta es una de la frases pronunciadas ayer por el presidente Obama. Tras diez a\u00f1os el l\u00edder Bin Laden ha ca\u00eddo en una de las numerosas operaciones que se hab\u00edan llevado a cabo contra \u00e9l. No conozco el tema y lo dejo aqu\u00ed. Me centro en la frase.&#8221; America puede hacer lo que se proponga&#8221; y supongo que debe ser verdad&#8230;en algunos casos.<\/p>\n<p>\u00bfPodr\u00edamos decir nosotros lo mismo? S\u00e9, lo he le\u00eddo en los libros de Historia- es una forma de saber- que hubo un tiempo en que si lo pod\u00edamos hacer. \u00bfCuales son las condiciones para se pueda decir eso hoy?<\/p>\n<p>Se habla, con raz\u00f3n, del desastre econ\u00f3mico que vivimos y me pregunto de quien es realmente la culpa o si hay un solo culpable. Ya s\u00e9 que me dir\u00e1n que es un mix de decisiones. Por ejemplo se dice que el Gobierno no puede crear empleo y que solo debe, es obvio, estimular las condiciones que hagan posible a las empresas esa creaci\u00f3n.<\/p>\n<p>\u00bfHemos llamado a Am\u00e9rica?<\/p>\n<p>Ha muerto un hijo de Gadafi, un Bin Laden y el cardenal de Valencia a quien conoc\u00ed personalmente bastante en un \u00e9poca anterior y eso me sugiere el c\u00f3mo el poder desaparece en forma de nada en unos cuantos segundos. \u00bfEntonces?. Pasad el mejor d\u00eda posible. Buenos d\u00edas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Am\u00e9rica puede hacer lo que se proponga&#8221;, esta es una de la frases pronunciadas ayer por el presidente Obama. Tras diez a\u00f1os el l\u00edder Bin Laden ha ca\u00eddo en una de las numerosas operaciones que se hab\u00edan llevado a cabo contra \u00e9l. No conozco el tema y lo dejo aqu\u00ed. Me centro en la frase.&#8221; [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-846","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts\/846","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/comments?post=846"}],"version-history":[{"count":0,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/posts\/846\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/media?parent=846"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/categories?post=846"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.lasprovincias.es\/carlospajuelo\/wp-json\/wp\/v2\/tags?post=846"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}